{"id":20255,"date":"2025-05-27T16:44:05","date_gmt":"2025-05-27T21:44:05","guid":{"rendered":"https:\/\/carmelites.net\/?p=20255"},"modified":"2026-08-23T14:22:57","modified_gmt":"2026-08-23T19:22:57","slug":"laudato-si-action-plan-may-2025","status":"publish","type":"post","link":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/","title":{"rendered":"Plan de Acci\u00f3n Laudato Si' | Mayo 2025"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20255\" class=\"elementor elementor-20255\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-468fd29 e-flex e-con-boxed e-con e-parent\" data-id=\"468fd29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1b78f0 elementor-widget elementor-widget-image\" data-id=\"c1b78f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"300\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200.png\" class=\"attachment-large size-large wp-image-17725\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200.png 1200w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200-300x135.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200-1024x461.png 1024w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200-768x346.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/03\/Spanish1200-18x8.png 18w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-68c47a3 e-flex e-con-boxed e-con e-parent\" data-id=\"68c47a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b11400 elementor-widget elementor-widget-text-editor\" data-id=\"1b11400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Provincia Carmelita del Pur\u00edsimo Coraz\u00f3n de Mar\u00eda<br \/><\/strong><strong>2025<\/strong><\/h3><p style=\"text-align: center;\"><em>\"Os pido, en nombre de Dios, que defend\u00e1is a la Madre Tierra\".   - Papa Francisco<\/em><\/p><p>De Dennis Kalob, Coordinador del Plan de Acci\u00f3n Laudato Si'...<\/p><p>En 2023, la Provincia se comprometi\u00f3 a intensificar su compromiso de vivir los valores y la visi\u00f3n de la primera enc\u00edclica del Papa Francisco, <em>Laudato Si': Sobre el cuidado de la casa com\u00fan.\u00a0 <\/em>Este es el compromiso:<\/p><p><span style=\"text-decoration: underline;\"><strong>Declaraci\u00f3n de compromiso de la provincia de PCM<\/strong><\/span><\/p><p style=\"padding-left: 40px;\"><em>Uni\u00e9ndose a una comunidad mundial, la Provincia Carmelita del Pur\u00edsimo Coraz\u00f3n de Mar\u00eda se compromete a un proceso de seis a\u00f1os del Plan de Acci\u00f3n Laudato Si'. Este proceso incluir\u00e1 la inscripci\u00f3n en la Plataforma de Acci\u00f3n Laudato Si', la creaci\u00f3n de un Plan de Acci\u00f3n Laudato Si', y evaluaciones y actualizaciones anuales del Plan. A lo largo de estos seis a\u00f1os, se revisar\u00e1n las aportaciones del Consejo Provincial y de las Comisiones Provinciales. El Consejo Provincial y las Comisiones Provinciales supervisan todos los aspectos de las operaciones provinciales. Como escribi\u00f3 el Papa Francisco en Laudato Si': \"Se necesitan los talentos y la participaci\u00f3n de todos\" (LS14).<\/em><\/p><p style=\"padding-left: 40px;\"><em>\u00a0<\/em><em>Se ha creado un fondo Laudato Si' para apoyar este proyecto. Este fondo se utilizar\u00e1 para contratar a una persona que coordine el esfuerzo. Este coordinador gestionar\u00e1 las interacciones entre el Consejo Provincial, las Comisiones Provinciales, la Familia Carmelita en general, la ONG Carmelita y la comunidad de la Plataforma de Acci\u00f3n Laudato Si'. <\/em><\/p><p style=\"padding-left: 40px;\"><em>\u00a0<\/em><em>Como se afirma en Laudate Deum, \"algunos efectos de la crisis clim\u00e1tica son ya irreversibles\" (LD 15). Entendemos que ya vivimos en un mundo cambiado y que somos \"incapaces de detener algunos de los enormes da\u00f1os que hemos causado\" (LD 16). Por ello, con la contemplaci\u00f3n orante de la realidad actual, nos comprometemos al discernimiento provincial de acciones restauradoras fundamentadas en la ecolog\u00eda integral. Rezamos para que este compromiso provincial con el proceso del Plan de Acci\u00f3n de Laudato Si' conduzca a un alejamiento de los estilos de vida irresponsables y a una cultura provincial de aut\u00e9ntico cuidado de los dem\u00e1s y de toda la creaci\u00f3n.<\/em><\/p><p>Este compromiso nace de una profunda fe.  Hemos elegido dar Gloria a Dios a trav\u00e9s de nuestras continuas e intensificadas acciones para cuidar de los dem\u00e1s y de Su creaci\u00f3n.<\/p><p>Como nos dijo el Papa Francisco, \"Cuando 'Buscamos primero el reino de Dios' (Mateo 6:33), manteniendo una relaci\u00f3n correcta con Dios, la humanidad y la naturaleza, entonces la justicia y la paz pueden fluir como una corriente inagotable de agua pura, nutriendo a la humanidad y a todas las criaturas.\"  Los tiempos que corren exigen que actuemos con audacia ante tantas injusticias, conflictos y la amenaza existencial del cambio clim\u00e1tico.<\/p><p>As\u00ed pues, con este esp\u00edritu y con fe sincera, la Provincia inici\u00f3 su camino para crear un Plan de Acci\u00f3n Laudato Si' y llevarlo a cabo.<\/p><p>Fui contratado a principios de 2024 como Coordinador del Plan de Acci\u00f3n Laudato Si'.  Unas semanas m\u00e1s tarde, se complet\u00f3 un plan de acci\u00f3n inicial, se distribuy\u00f3 y se subi\u00f3 a la Plataforma de Acci\u00f3n Laudato Si' (un proyecto global del Dicasterio Vaticano para la Promoci\u00f3n del Desarrollo Humano Integral).  Este plan provincial inicial se identific\u00f3 como \"Un comienzo\".  Se trataba de un esbozo, que invitaba a desarrollar y promover acciones espec\u00edficas por parte de personas y ministerios de toda la provincia.<\/p><p>Desde entonces, he mantenido varias reuniones (en persona, por Zoom o por tel\u00e9fono) con varios miembros de la provincia.  He visitado varias comunidades y ministerios y he enviado muchos correos electr\u00f3nicos.  Tambi\u00e9n he creado un bolet\u00edn electr\u00f3nico del Plan de Acci\u00f3n Laudato Si', que durante el \u00faltimo a\u00f1o ha salido al menos cada dos meses, y a veces con m\u00e1s frecuencia.<\/p><p>Todo esto nos llev\u00f3 al objetivo de tener un plan m\u00e1s detallado terminado para la Semana Laudato Si' de 2025 (24-31 de mayo).  Este plan ser\u00eda, de hecho, una colecci\u00f3n de planes individuales de los ministerios y comunidades carmelitas de toda la provincia.  Muchos carmelitas y asociados han respondido a esta llamada.<\/p><p>As\u00ed pues, este documento es la recopilaci\u00f3n de los numerosos Planes de Acci\u00f3n Laudato Si' individuales que se han creado hasta la fecha.  Como podr\u00e1s leer, cada plan comienza generalmente con un resumen de lo que ese ministerio o comunidad ya ha hecho para promover los objetivos y la visi\u00f3n de Laudato Si'-escuchar el clamor de la tierra y el clamor de los pobres.  Adem\u00e1s, cada plan esboza sus pr\u00f3ximos pasos.<\/p><p>Como ver\u00e1, algunos planes son incre\u00edblemente detallados y elaborados, mientras que otros son m\u00e1s breves y sencillos.  No importa.  Se pidi\u00f3 a cada ministerio y comunidad que presentara lo que pudiera, entendiendo que cada circunstancia ser\u00e1 diferente.  Algunas entidades son peque\u00f1as y\/o tienen recursos limitados.  Otras son grandes y disponen de mayores recursos (entendiendo por recursos tanto el tiempo como el dinero).  Se trata simplemente de que cada uno haga lo que pueda con lo que tiene.<\/p><p>Este es un documento vivo.  Peri\u00f3dicamente se introducir\u00e1n cambios en \u00e9l.  Algunos de los planes que me fueron enviados e incluidos en este informe ven\u00edan con el entendimiento de que se har\u00edan ajustes unas semanas o meses m\u00e1s tarde.  Algunos ministerios y comunidades carmelitas no pudieron enviar sus planes a tiempo para ser incluidos en este informe inicial, pero pueden ser incluidos en una fecha posterior.<\/p><p>Deseo hacer un par de observaciones adicionales.  En primer lugar, me ha impresionado mucho todo lo que ya se ha hecho en toda la provincia para vivir Laudato Si'.  Todos y cada uno de los ministerios y comunidades carmelitas ya estaban \"escuchando el clamor de la tierra y el clamor de los pobres\" y estaban respondiendo.  Me contrataron no para ayudar a la provincia <em>comience<\/em> la labor de vivir los valores y la visi\u00f3n de Laudato Si', sino alentar <em>m\u00e1s<\/em> pasos.\u00a0<\/p><p>Mi otro punto es que los Carmelitas y asociados con los que me he comunicado durante el \u00faltimo a\u00f1o han sido todos acogedores conmigo personalmente y con la llamada a promover la acci\u00f3n de Laudato Si'.  Por ello estoy muy agradecido.<\/p><p>Ahora, \u00a1a construir un mundo mejor!<\/p><p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>Una oraci\u00f3n por nuestra Tierra<\/strong><\/span><\/p><p style=\"text-align: center;\">Dios todopoderoso, t\u00fa est\u00e1s presente en todo el universo<br \/>y en la m\u00e1s peque\u00f1a de tus criaturas.<br \/>Abrazas con tu ternura todo lo que existe.<br \/>Derrama sobre nosotros la fuerza de tu amor,<br \/>para proteger la vida y la belleza.<br \/>Ll\u00e9nanos de paz, para que podamos vivir<br \/>como hermanos y hermanas, sin hacer da\u00f1o a nadie.<br \/>Oh Dios de los pobres,<br \/>ay\u00fadanos a rescatar a los abandonados y olvidados de esta tierra,<br \/>tan precioso en tus ojos.<br \/>Trae sanaci\u00f3n a nuestras vidas,<br \/>para que protejamos al mundo y no lo depredemos,<br \/>para que sembremos belleza, no contaminaci\u00f3n y destrucci\u00f3n.<br \/>Tocar los corazones<br \/>de los que s\u00f3lo buscan la ganancia<br \/>a costa de los pobres y de la tierra.<br \/>Ens\u00e9\u00f1anos a descubrir el valor de cada cosa,<br \/>para llenarse de asombro y contemplaci\u00f3n,<br \/>reconocer que estamos profundamente unidos<br \/>con toda criatura<br \/>mientras viajamos hacia tu luz infinita.<br \/>Les damos las gracias por estar con nosotros cada d\u00eda.<br \/>An\u00edmanos, te lo pedimos, en nuestra lucha<br \/>por la justicia, el amor y la paz.<\/p><p style=\"text-align: center;\">-Papa Francisco (de su enc\u00edclica, <em>Laudato Si'<\/em>, 2015)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a1bc9c9 e-flex e-con-boxed e-con e-parent\" data-id=\"a1bc9c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4031800 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4031800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-096909d elementor-widget elementor-widget-menu-anchor\" data-id=\"096909d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"return\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01d9d14 elementor-widget elementor-widget-text-editor\" data-id=\"01d9d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>Contenidos seleccionables por ministerio\/comunidad<\/strong><\/span><\/h4><p><a href=\"#Darien\">Campus Carmelita en Darien, Illinois<\/a><\/p><p style=\"text-align: center;\"><a href=\"#JPIC\">Comisi\u00f3n JPIC de la Provincia<\/a><\/p><p style=\"text-align: center;\"><a href=\"#WFH\">Whitefriars Hall en Washington, D.C.<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Xiberta\">Casa de formaci\u00f3n en Ciudad Delgado, El Salvador<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Scipio\">Ministerio de Retiros en Scipio, Kansas<\/a><\/p><p style=\"text-align: center;\"><a href=\"#CCHS\">Carmel Catholic High School en Mundelein, Illinois<\/a><\/p><p style=\"text-align: center;\"><a href=\"#CRESPI\">Crespi Carmelite High School en Encino, California<\/a><\/p><p style=\"text-align: center;\"><a href=\"#JCA\">Joliet Catholic Academy en Joliet, Illinois<\/a><\/p><p><a href=\"#MCHS\">Instituto Mount Carmel de Chicago, Illinois<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Salpointe\">Salpointe Catholic High School en Tucson, Arizona<\/a><\/p><p><a href=\"#OLMCDarien\">Parroquia de Nuestra Se\u00f1ora del Carmen en Darien, Illinois<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Cecilia\">Parroquia de Santa Cecilia en Englewood, Nueva Jersey<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Cresskill\">Parroquia de Santa Teresa de Lisieux en Cresskill, Nueva Jersey<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Coahuila\">Parroquia de la Transfiguraci\u00f3n del Se\u00f1or, Torre\u00f3n, M\u00e9xico<\/a><\/p><p style=\"text-align: center;\"><a href=\"#ElSalvador\">Casa San Alberto de Jerusal\u00e9n, El Salvador<\/a><\/p><p style=\"text-align: center;\"><a href=\"#Tucson\">Priorato Carmelita en Tucson, Arizona<\/a><\/p><p style=\"text-align: center;\"><a href=\"#StCyril\">Priorato de San Cirilo en Chicago, Illinois<\/a><\/p><p style=\"text-align: center;\"><a href=\"#StSimon\">Priorato de San Sim\u00f3n Stock en Darien, Illinois<\/a><\/p><p><a href=\"#TheresePhoenix\">Priorato de Santa Teresa de Lisieux en Phoenix, Arizona<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4d5287e e-flex e-con-boxed e-con e-parent\" data-id=\"4d5287e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-674bf25 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"674bf25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c681c98 elementor-widget elementor-widget-menu-anchor\" data-id=\"c681c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Darien\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6da73fe e-grid e-con-full e-con e-child\" data-id=\"6da73fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96c2d1c elementor-widget elementor-widget-heading\" data-id=\"96c2d1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plan de Acci\u00f3n Laudato Si' para el\nCampus Carmelita en Darien, Illinois\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c3bc50 elementor-widget elementor-widget-text-editor\" data-id=\"0c3bc50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><u>Resumen del Campus<\/u><\/strong><strong>\u00a0<\/strong><\/p><p><strong>Esfuerzos de Laudato Si <\/strong><strong>en los \u00faltimos a\u00f1os<\/strong><strong>\u00a0<\/strong><\/p><p>Se ha sustituido la mayor parte de la iluminaci\u00f3n por bombillas de bajo consumo.\u00a0<\/p><p>Instalaci\u00f3n de paneles solares.<\/p><p>Preservaci\u00f3n del entorno natural en torno al estanque.<\/p><p>Reducci\u00f3n de los productos de pl\u00e1stico de un solo uso y de los residuos de papel.\u00a0<\/p><p>Se han plantado \u00e1rboles.<\/p><p><strong>Futuros esfuerzos de Laudato Si<\/strong><\/p><p>Identificar un Equipo de Cuidado de la Creaci\u00f3n para el campus. Se reunir\u00e1n mensualmente para supervisar los avances de Laudato Si' e identificar acciones adicionales.<\/p><p>Buscar asesoramiento profesional que lleve a reimaginar el paisajismo del campus. A considerar: plantar m\u00e1s \u00e1rboles, crear un jard\u00edn de polinizadores y\/o plantas aut\u00f3ctonas, y\/o crear un jard\u00edn comunitario. Posibles consultas: habitatrestoration.com y candenativelandscape.com<\/p><p>Garantizar que la futura construcci\u00f3n de edificios sea lo m\u00e1s respetuosa posible con el medio ambiente.<\/p><p>Estudiar una ampliaci\u00f3n de la energ\u00eda solar.<\/p><p>Establecer un programa general de reciclaje en el campus.<\/p><p><strong><u>Campus de la Sociedad del Carmen<\/u><\/strong><\/p><p><strong>Finalizaciones de Laudato Si':<\/strong><\/p><p><strong>\u00a0<\/strong>Jard\u00edn de meditaci\u00f3n<\/p><ul><li>En los \u00faltimos 10 a\u00f1os se han plantado m\u00e1s de 81 \u00e1rboles, mientras que en a\u00f1os anteriores s\u00f3lo se hab\u00edan plantado entre 15 y 20 \u00e1rboles.<\/li><li>Esos \u00e1rboles son aut\u00f3ctonos del Medio Oeste (peral, roble, arce, pino y rosa de Sharon).<\/li><li>Hemos encontrado formas de retener el agua con m\u00faltiples parterres de plantaci\u00f3n y la instalaci\u00f3n de riego con el apoyo de nuestro campus.<\/li><li>Toda la electricidad instalada es de bajo voltaje y 8419 Bailey (Centro Espiritual)<\/li><\/ul><p>Complet\u00f3 una renovaci\u00f3n en 2016 que incluy\u00f3 muchas actualizaciones el\u00e9ctricas para la eficiencia....<\/p><ul><li>Sensores de ocupaci\u00f3n en salas de reuniones (hace que las luces se enciendan y apaguen cuando alguien entra o sale)<\/li><li>Toda la iluminaci\u00f3n se actualiz\u00f3 a LED o balastos de bajo voltaje.<\/li><li>Las neveras de las cocinas se han mejorado con un aislamiento m\u00e1s grueso y una refrigeraci\u00f3n m\u00e1s eficaz.<\/li><li>La iluminaci\u00f3n exterior se ha cambiado a<\/li><li>Se instal\u00f3 energ\u00eda solar en<\/li><\/ul><p>8433 Bailey Rd (Santuario Nacional)<\/p><ul><li>El edificio se construy\u00f3 para estar a la vanguardia con todas las eficiencias energ\u00e9ticas (aunque no se puede instalar energ\u00eda solar en este edificio).<\/li><\/ul><ul><li>Se han plantado 20 \u00e1rboles en lugar de los 4 que se perdieron durante la construcci\u00f3n.<\/li><\/ul><p>8501 Bailey Rd (Museo, Tienda, Archivos, Finanzas)<\/p><ul><li>El edificio se ha modernizado por completo con iluminaci\u00f3n LED o de bajo voltaje.<\/li><li>(Solar no se puede instalar en este )<\/li><li>Todos los sistemas de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado son de alta eficiencia y uno de ellos se est\u00e1 sometiendo actualmente a un<\/li><li>Los aseos p\u00fablicos se renovaron e incluyeron agua<\/li><li>El contenedor de reciclaje se encuentra en<\/li><\/ul><p>Casa Blanca<\/p><ul><li>Se instal\u00f3 un sistema de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado energ\u00e9ticamente eficiente en<\/li><li>La mayor parte del alumbrado, si no todo, se ha cambiado a LED<\/li><li>Todos los electrodom\u00e9sticos son de bajo consumo<\/li><li>En el \u00faltimo a\u00f1o se han plantado m\u00e1s de 15 \u00e1rboles.<\/li><\/ul><p>Casa de la Misi\u00f3n<\/p><ul><li>Se instal\u00f3 un sistema de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado energ\u00e9ticamente eficiente en<\/li><li>La mayor parte del alumbrado, si no todo, se ha cambiado a LED<\/li><\/ul><p>1317 N. Frontage (Oficina Provincial:)<\/p><ul><li>Se instal\u00f3 un sistema de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado energ\u00e9ticamente eficiente en<\/li><li>En 2019 se instal\u00f3 iluminaci\u00f3n de bajo consumo.<\/li><\/ul><p>1313 N. Frontage (Sociedad de la Peque\u00f1a Flor)<\/p><ul><li>En 2019 se instal\u00f3 iluminaci\u00f3n de bajo consumo.<\/li><li>Los ba\u00f1os se renovaron e incluyen agua<\/li><li>Cuando los equipos de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado fallen, se cambiar\u00e1n para cumplir los requisitos energ\u00e9ticos actuales.<\/li><\/ul><p><strong>Otras notas\/opiniones<\/strong><\/p><p>En el campus de Dari\u00e9n hay ahora m\u00e1s \u00e1rboles que nunca. Nuestro humedal y estanque se mantienen con la m\u00e1xima calidad. Tenemos muchas especies de flores y plantas para que prosperen todo tipo de aves y animales. Los humedales se mitigan anualmente y est\u00e1n bajo el control del condado de DuPage y del estado de Illinois. Hemos aumentado el tama\u00f1o del humedal para crear un entorno m\u00e1s natural alrededor del estanque.<\/p><p>Estamos muy limitados en el uso de reciclaje ya que cada lugar tiene su propio contenedor de basura y necesidad. El espacio es muy limitado para un contenedor o recogida m\u00e1s grande.<\/p><p>Cuando completamos nuestra auditor\u00eda solar, se observ\u00f3 que en la mayor\u00eda de nuestros edificios no se puede instalar energ\u00eda solar debido al tipo de tejado o a las garant\u00edas, ni tampoco se pueden instalar paneles solares en los terrenos con nuestra actual disposici\u00f3n paisaj\u00edstica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53c26f1 elementor-widget elementor-widget-button\" data-id=\"53c26f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a35c2e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9a35c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb79aef elementor-widget elementor-widget-menu-anchor\" data-id=\"eb79aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"JPIC\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ac8d42 elementor-widget elementor-widget-text-editor\" data-id=\"8ac8d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Comisi\u00f3n JPIC<br \/><\/strong><strong>Presentado por: Dave Semmens<\/strong><\/h4><p><strong>Medidas ya adoptadas:<\/strong><\/p><ul><li>Una de las principales responsabilidades de la Comisi\u00f3n JPIC, derivada de la legislaci\u00f3n provincial, es gestionar las solicitudes de subvenci\u00f3n patrocinadas por los miembros de O.Carm. miembros. Estas subvenciones proporcionan $150.000 d\u00f3lares de financiaci\u00f3n cada a\u00f1o.  Si las subvenciones financiadas son inferiores a $150.000 la cantidad restante va a un \"Fondo de Emergencia\". El Fondo de Emergencia se utiliza para proporcionar financiaci\u00f3n a los Carmelitas en situaciones de emergencia, como cat\u00e1strofes naturales o guerras.\u00a0<\/li><li>Desde 2017 los planes estrat\u00e9gicos provinciales de JPIC se han centrado en temas relacionados con Laudato Si. JPIC invit\u00f3 a Eduardo Scarel O.Carm a hablar sobre el cambio clim\u00e1tico y la Doctrina Social Cat\u00f3lica en las reuniones regionales de 2019 y 2022. En 2023, la comisi\u00f3n de JPIC pregunt\u00f3 al cap\u00edtulo si deb\u00edamos comprometernos con un proceso de plan Laudato Si para los pr\u00f3ximos 6 a\u00f1os. La provincia lo apoy\u00f3 y contrat\u00f3 a un coordinador de Laudato Si.<\/li><li>Para m\u00e1s detalles, v\u00e9ase el Ap\u00e9ndice.<\/li><\/ul><p><strong><br \/>Plan de acci\u00f3n para 2025:<\/strong><\/p><ul><li>Noviembre de 2024: La comisi\u00f3n a\u00f1adi\u00f3 la siguiente pregunta al formulario de solicitud de subvenci\u00f3n de JPIC: Describa c\u00f3mo su proyecto se alinea con uno o m\u00e1s de los objetivos de Laudato Si.<\/li><li>Verano de 2025: La Comisi\u00f3n se reunir\u00e1 en mayo para discutir los informes de las becas 2024. El objetivo es seleccionar los informes de las becas para destacarlos en la revista digital Carmelite Review.  Esta ser\u00e1 una manera de dar a conocer el trabajo de JPIC apoyado por la provincia y contar historias de las personas afectadas por las subvenciones.\u00a0<\/li><\/ul><p><strong><br \/>Ap\u00e9ndice: <\/strong><strong>Acciones JPIC 2020-2024<\/strong><\/p><p><strong>Actualizaciones provinciales de 2020 para CCF y CHDF + Fondo de Emergencia<\/strong><\/p><ul><li>Se ha creado una cuenta bancaria CCF separada que financia el CCF $75000 para el ejercicio presupuestario.<ul><li>Los cheques de las subvenciones ben\u00e9ficas saldr\u00e1n de esta cuenta.<\/li><\/ul><\/li><li>Se ha creado una cuenta bancaria CHCF separada que financia el CHDF $75000 para el ejercicio presupuestario.<ul><li>Los cheques de las subvenciones de Desarrollo Humano saldr\u00e1n de esta cuenta.<\/li><\/ul><\/li><li>Una cuenta separada del Fondo de Emergencia JPIC<ul><li>La cantidad a\u00f1adida al Fondo de Emergencia es 150000 - (CCF + CHDF) Subvenciones aprobadas para el a\u00f1o.<\/li><li>El importe del Fondo de Emergencia no se pierde al final del ejercicio presupuestario. Los fondos permanecen en la cuenta hasta que se utilizan.<\/li><\/ul><\/li><\/ul><p><strong><u><br \/>Objetivo del Consejo Provincial JPIC 2020-2023 y Acciones de la Comisi\u00f3n JPIC:<\/u><\/strong><\/p><p><strong>Objetivo de la Diputaci\u00f3n para 2020 (2020-23):<\/strong><\/p><p><em>Somos muy conscientes de una serie de problemas medioambientales mundiales cr\u00edticos, entre los que destacan el impacto inmediato del cambio clim\u00e1tico y la disparidad en el consumo de recursos entre la familia de naciones. Por ello, nos comprometemos a...<\/em><\/p><ul><li><em>Educar a los hombres de nuestra provincia en cuestiones relacionadas con el cambio clim\u00e1tico y sus causas.<\/em><\/li><li><em>Iniciar un debate comunitario sobre estas cuestiones medioambientales urgentes en cada una de nuestras comunidades locales, desafiando primero a nuestros hombres a leer y debatir la carta pastoral del Papa Francisco, Laudato Si<\/em><\/li><li><em>Determinar la huella de carbono de las instituciones y propiedades propiedad de la provincia o administradas por ella, con el objetivo de reducir la huella de carbono provincial hacia emisiones netas cero, reduciendo as\u00ed el consumo de energ\u00eda basada en combustibles f\u00f3siles y avanzando hacia la energ\u00eda sostenible.<\/em><\/li><li><em>Colaborar con Catholic Energies, la ONG carmelita y otras entidades carmelitas en la consecuci\u00f3n de estos objetivos. <\/em><\/li><li><em>Animar a nuestros afiliados a dar peque\u00f1os pasos concretos para proteger el medio ambiente.<\/em><\/li><\/ul><p><strong><u>\u00a0<\/u><\/strong><\/p><p><strong>Objetivo 2020: Trabajar con Catholic Energies para reducir la huella de carbono hacia emisiones netas cero \/ energ\u00eda sostenible.<\/strong><\/p><p>3 de octubre de 2020: Reuni\u00f3n JPIC: Presentaci\u00f3n de <strong>P\u00e1gina Gravely <\/strong>- Catholic Energies (instalaciones solares en Whitefriars Hall, Darien.) Empresa: Programa Mission Energy: Catholic Energies<\/p><p><strong>Energ\u00edas cat\u00f3licas 2020 y hoja de ruta hacia Net Zero<\/strong><\/p><ul><li>Las emisiones son directas (luces, calefacci\u00f3n, aislamiento, ventanas, etc.) e indirectas (fuente de energ\u00eda).<\/li><li>A corto plazo<ul><li>Cambios de bajo coste o gratuitos para reducir el consumo de servicios p\u00fablicos mediante el uso de luces, electrodom\u00e9sticos, etc. m\u00e1s eficientes.<\/li><li>Conservaci\u00f3n<\/li><li>Cambiar de fuente de energ\u00eda (solar, uso de electricidad renovable comunitaria)<\/li><li>A largo plazo<\/li><li>Cree <a href=\"https:\/\/betterbuildingssolutioncenter.energy.gov\/toolkits\/green-revolving-funds\">Fondo Rotatorio Verde<\/a> y utilizar el ahorro derivado de un menor consumo de energ\u00eda para reponer el fondo.<\/li><li>Cuando los sistemas de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado, calderas, etc. lleguen al final de su vida \u00fatil, sustit\u00fayalos por sistemas energ\u00e9ticamente eficientes.<\/li><\/ul><\/li><li>Catholic Energies puede ayudar con soluciones tanto a corto como a largo plazo proporcionando datos de emisiones antes y despu\u00e9s para su an\u00e1lisis.<\/li><li>Crear una cartera de propiedades a nivel provincial<\/li><li>Las escuelas suelen ser un buen punto de partida para reducir las emisiones. Tienen un elevado consumo energ\u00e9tico, tejados planos para la energ\u00eda solar y propiedades relativamente grandes. Muchos Estados ofrecen incentivos y permiten la inversi\u00f3n de terceros en energ\u00eda solar.<\/li><\/ul><p><strong><br \/>1 de febrero de 2021: Page Gravely se reuni\u00f3 con los Presidentes de HS.  Discuti\u00f3 el proceso para que Catholic Energies analice y haga una propuesta para instalaciones solares en Salpointe, Crespi y Mundelein. <\/strong><\/p><ul><li>Catholic Energies recibi\u00f3 un a\u00f1o de facturas de energ\u00eda de los colegios, analiz\u00f3 las instalaciones, la normativa estatal, d\u00f3nde permitir\u00eda el colegio paneles solares, etc.\u00a0<\/li><\/ul><p>De febrero a octubre, Catholic Energies trabaj\u00f3 con Salpointe, Crespi y Carmel Catholic para presentar propuestas.  Ninguno decidi\u00f3 seguir solar con Catholic Energies.\u00a0<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Objetivo 2021: Trabajar con ONG... Iniciar un debate comunitario... Animar a los miembros a dar pasos peque\u00f1os pero individuales...<\/strong><\/p><p>Entre septiembre y octubre de 2021 se celebraron debates comunales.  Se utiliz\u00f3 el documento 14 Simple Changes de la ONG para centrar los debates.  La comisi\u00f3n de JPIC facilit\u00f3 un formulario en l\u00ednea para recoger los debates comunitarios.  La participaci\u00f3n y el compromiso sobre el tema de los pasos individuales para proteger el medio ambiente fueron elevados.\u00a0<\/p><p><strong>Objetivo 2022: Trabajar con una ONG... Educar a la provincia en temas relacionados con el cambio clim\u00e1tico y sus causas... Desafiar a los hombres a leer\/discutir Laudato Si.\u00a0 <\/strong><\/p><p><strong>2022 <\/strong>Eduardo Agosta Scarel, O.Carm. acept\u00f3 hacer presentaciones sobre Laudato Si y el cambio clim\u00e1tico y sus causas en las reuniones regionales.\u00a0<\/p><p><strong>Objetivo 2023:\u00a0 <\/strong><strong>Iniciar un debate comunitario sobre estos acuciantes problemas medioambientales.<\/strong><\/p><p>Presentaci\u00f3n de propuesta para votaci\u00f3n en Cap\u00edtulo: \"<strong><em>La provincia PCM se compromete a la creaci\u00f3n de un Plan de Acci\u00f3n Laudato Si que se evaluar\u00e1 anualmente y se actualizar\u00e1 seg\u00fan sea necesario durante los pr\u00f3ximos 6 a\u00f1os.\"<\/em><\/strong><\/p><p><strong><u>JPIC 2023 Cap\u00edtulo Propuesta e implementaci\u00f3n de LSAP:<\/u><\/strong><\/p><p><strong><em>La provincia PCM se compromete a la creaci\u00f3n de un Plan de Acci\u00f3n Laudato Si que se evaluar\u00e1 anualmente y se actualizar\u00e1 seg\u00fan sea necesario durante los pr\u00f3ximos 6 a\u00f1os.\"<\/em><\/strong><\/p><p><strong><em>\u00a0<\/em><\/strong><\/p><p>Resultado: La provincia se compromete con la propuesta<\/p><p><strong>2023 Cumplimiento del compromiso con el Plan de Acci\u00f3n Laudato Si <\/strong><\/p><p>Creaci\u00f3n de la Declaraci\u00f3n de Compromiso del Plan de Acci\u00f3n Laudato Si<\/p><p>La Provincia crea un Fondo Laudato Si<\/p><p>La Provincia crea un puesto de Coordinador Laudato Si con cargo al Fondo Laudato Si<\/p><p><strong>2024 Puesto de coordinador de Laudato Si cubierto<\/strong><\/p><p>Enero - Dennis Kalob comienza a trabajar como Coordinador de Laudato Si para la provincia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-709c6c5 elementor-widget elementor-widget-button\" data-id=\"709c6c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c88259a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c88259a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d108dc7 e-flex e-con-boxed e-con e-parent\" data-id=\"d108dc7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e276707 elementor-widget elementor-widget-menu-anchor\" data-id=\"e276707\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"WFH\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-696adb0 e-grid e-con-full e-con e-child\" data-id=\"696adb0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad90d28 elementor-widget elementor-widget-image\" data-id=\"ad90d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"206\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture4.png\" class=\"attachment-large size-large wp-image-20259\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture4.png 187w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture4-11x12.png 11w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c0dfa elementor-widget elementor-widget-text-editor\" data-id=\"c5c0dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><strong>Plan de Acci\u00f3n Laudato Si' 2025-2026<br \/><\/strong><em>Comunidad Carmelita en Whitefriars Hall<br \/><\/em><strong>Comprometidos con el cuidado de nuestra casa com\u00fan <\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b725ca9 elementor-widget elementor-widget-text-editor\" data-id=\"b725ca9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Oraci\u00f3n <\/strong><strong>\u00a0<\/strong><\/p><p><strong>Dios de toda la creaci\u00f3n, <\/strong>Nos has dado esta tierra como nuestra casa com\u00fan, confiada a nuestro cuidado. Que, como El\u00edas, reconozcamos Tu presencia en el susurro de la suave brisa. Danos corazones agradecidos, manos generosas y un esp\u00edritu que camine suavemente sobre la tierra. Que, por intercesi\u00f3n de Nuestra Se\u00f1ora del Carmen, crezcamos en amor por Ti y por todo lo que T\u00fa has hecho. <strong>Am\u00e9n. <\/strong><\/p><p><strong>Lo que ya hemos hecho <\/strong><\/p><p>En Whitefriars Hall, hemos tomado medidas significativas para cuidar de la creaci\u00f3n de manera que reflejen nuestros valores carmelitas:<\/p><ul><li><strong>Energ\u00eda solar: <\/strong>Desde 2019, nuestros paneles solares han ayudado a reducir nuestra dependencia de los combustibles f\u00f3siles.<\/li><li><strong>Jard\u00edn de lluvia: <\/strong>Instalado en 2022, ayuda a gestionar las aguas pluviales, evita la erosi\u00f3n y proporciona un h\u00e1bitat para la fauna local.<\/li><li><strong>Veh\u00edculos el\u00e9ctricos: <\/strong>Hemos instalado una estaci\u00f3n de carga para nuestros dos coches h\u00edbridos enchufables, lo que permite que la mayor\u00eda de nuestros desplazamientos locales sean el\u00e9ctricos.<\/li><li><strong>Plantaci\u00f3n de \u00e1rboles: <\/strong>En los dos \u00faltimos a\u00f1os se han plantado casi 100 \u00e1rboles en nuestra propiedad.<\/li><li><strong>Filtros de agua: <\/strong>Hemos instalado dos sistemas de filtraci\u00f3n para reducir la dependencia del agua embotellada.<\/li><li><strong>Reciclaje: <\/strong>Nuestra comunidad separa y recicla una gran variedad de materiales.<\/li><li><strong>Comit\u00e9 JPIC: <\/strong>Nuestro comit\u00e9 de Justicia, Paz e Integridad de la Creaci\u00f3n promueve activamente una vida sencilla y sostenible.<\/li><\/ul><p><strong><br \/>A qu\u00e9 nos comprometemos en 2025 y m\u00e1s all\u00e1 <\/strong><\/p><p>Estos esfuerzos est\u00e1n dirigidos por nuestro comit\u00e9 de JPIC, pero requieren la participaci\u00f3n de toda la comunidad. Cuidar de la creaci\u00f3n no es un proyecto puntual, es una forma de vida. Juntos, nos comprometemos a vivir de forma m\u00e1s sencilla, a compartir m\u00e1s generosamente y a caminar con suavidad sobre la tierra.<\/p><p><strong>Compartir lo que tenemos - Respuesta al clamor de los pobres <\/strong><\/p><ul><li>Continuar con las entregas mensuales de alimentos para inmigrantes y familias necesitadas.<\/li><li>Dona ropa y enseres dom\u00e9sticos en buen estado a quienes puedan utilizarlos.<\/li><\/ul><p><strong><br \/>Reducir el consumo de energ\u00eda: respuesta al clamor de la Tierra <\/strong><\/p><ul><li>Actualizaci\u00f3n a iluminaci\u00f3n LED en toda la casa.<\/li><li>Instale sensores de movimiento para reducir el consumo innecesario de energ\u00eda.<\/li><li>Mantenga los termostatos a 67 \u00b0F en invierno y 70 \u00b0F en verano para ahorrar energ\u00eda.<\/li><li>Considere la posibilidad de programar una auditor\u00eda energ\u00e9tica para identificar nuevas mejoras.<\/li><\/ul><p><strong><br \/>Reducci\u00f3n de residuos - Adopci\u00f3n de estilos de vida sostenibles <\/strong><\/p><ul><li>Ampliar el compostaje en colaboraci\u00f3n con <em>Residuos Cero DC <\/em>para convertir los restos de comida en tierra sana.<\/li><li>Reutilice materiales como cajas de transporte siempre que sea posible.<\/li><li>Evite los productos con exceso de envases, especialmente los pl\u00e1sticos de un solo uso, como el agua embotellada.<\/li><\/ul><p><strong><br \/>Vivir de forma sencilla y sostenible <\/strong><\/p><ul><li>Siempre que sea posible, camine, vaya en bicicleta o utilice el transporte p\u00fablico para trayectos cortos.<\/li><li>Combine los viajes en coche para reducir el consumo de combustible.<\/li><li>Reduzca el consumo de agua: instale cabezales de ducha de bajo caudal, sustituya los inodoros por modelos de bajo consumo cuando sea necesario y cierre el grifo durante las rutinas diarias (por ejemplo, mientras se cepilla los dientes o se ducha).<\/li><li>Explora la posibilidad de a\u00f1adir barriles de lluvia para recoger agua para uso exterior.<\/li><li>Seguir plantando plantas aut\u00f3ctonas para favorecer la biodiversidad.<\/li><li>\u00danase a los actos trimestrales de limpieza del barrio en cooperaci\u00f3n con la <em>Asociaci\u00f3n de Vecinos de Queens Chapel<\/em>.<\/li><li>Celebre los viernes sin carne como un sencillo acto de solidaridad ecol\u00f3gica.<\/li><\/ul><p><strong><br \/>Aprender y crecer juntos<\/strong><\/p><ul><li>El comit\u00e9 de JPIC organizar\u00e1 debates, retiros e iniciativas para mantener a nuestra comunidad comprometida y cada vez m\u00e1s concienciada.<\/li><li>Colaboraremos con Dennis Kalob, el director provincial de <em>Coordinadora de Laudato Si'<\/em>para alinearse con la respuesta carmelita m\u00e1s amplia.<\/li><li>Planificar actos comunitarios como celebraciones del D\u00eda de la Tierra (22 de abril) y homil\u00edas educativas.<\/li><li>Organizar una excursi\u00f3n comunitaria con la <em>Sociedad de la Cuenca Hidrogr\u00e1fica de Anacostia <\/em>para comprometernos con nuestro entorno local.<\/li><\/ul><p><strong><br \/>Resiliencia y capacitaci\u00f3n de la comunidad - Pr\u00f3ximos pasos<\/strong><\/p><ul><li>El comit\u00e9 JPIC ayudar\u00e1 a crear un plan pr\u00e1ctico para que estos compromisos formen parte de la vida cotidiana.<\/li><li>Empezaremos a hacer un seguimiento de nuestro consumo de energ\u00eda y agua para medir los progresos a lo largo del tiempo.<\/li><li>Estas acciones no son meros proyectos, sino que reflejan un cambio de estilo de vida, arraigado en nuestra fe y en nuestra llamada a cuidar la creaci\u00f3n de Dios.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5922379 elementor-widget elementor-widget-button\" data-id=\"5922379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71a8646 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71a8646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-58f63c7 e-flex e-con-boxed e-con e-parent\" data-id=\"58f63c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e30e0df elementor-widget elementor-widget-menu-anchor\" data-id=\"e30e0df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Xiberta\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5977ea elementor-widget elementor-widget-text-editor\" data-id=\"e5977ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><strong><span class=\"--l sentence_highlight\"><span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">Laudato<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">SI<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">Acci\u00f3n<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">Plan<br \/><\/span><\/span><\/strong><strong><span class=\"--l sentence_highlight\">Casa de Formaci\u00f3n Fray Bartolom\u00e9 Xiberta<br \/><\/span><\/strong><strong><span class=\"--l sentence_highlight\">Cant\u00f3n Caba\u00f1as, Ciudad Delgado, Carretera de Oro Km 14.5<br \/><\/span><\/strong><strong><span class=\"--l sentence_highlight\">21 de abril de 2025<br \/><\/span><\/strong><strong><span class=\"--l sentence_highlight\">P. Benjam\u00edn Constante, O.Carm.<\/span><\/strong><\/h5><p><span style=\"text-decoration: underline;\"><span class=\"--l sentence_highlight\"><strong>Acciones en el esp\u00edritu de \"Laudato SI\" que ya se han emprendido.<\/strong> <\/span><\/span><\/p><p><span class=\"--l --r sentence_highlight\">1.- Conservaci\u00f3n y protecci\u00f3n de la fauna y flora del lugar y sus propiedades, concienciando de la importancia de la conservaci\u00f3n del lugar. <\/span><span class=\"--l sentence_highlight\">En la casa de formaci\u00f3n Xiberta se cuidan y protegen las zonas verdes, respetando la fauna que all\u00ed habita y conservando mediante un mantenimiento continuo los jardines dentro de esta misma casa de formaci\u00f3n. <\/span><\/p><p><span class=\"--l sentence_highlight\">Huerto ecol\u00f3gico: uso de abonos, fungicidas, insecticidas 100% ecol\u00f3gicos, para evitar la contaminaci\u00f3n del aire y del suelo con productos qu\u00edmicos que acaban matando los nutrientes del suelo y los productos cosechados en los huertos. <\/span><\/p><p><span class=\"--l sentence_highlight\">3.- Proyecto activo de reciclaje a peque\u00f1a escala en la casa de formaci\u00f3n, tambi\u00e9n educando a nuevos miembros de la comunidad en el reciclaje para que sigan el proyecto e invitando a los miembros a educar a las familias en los proyectos. <\/span><\/p><p><span class=\"--l sentence_highlight\">Utilizar energ\u00edas renovables y sostenibles que reduzcan el consumo de electricidad (paneles solares). <\/span><\/p><p><span style=\"text-decoration: underline;\"><span class=\"--l sentence_highlight\"><strong>Plan de acci\u00f3n<\/strong> <\/span><\/span><\/p><p><span class=\"--l sentence_highlight\">1.- Planificar y realizar catequesis de educaci\u00f3n ambiental con los hermanos de la comunidad y vecinos. (Fecha: Julio a Noviembre 2025). <\/span><\/p><p><span class=\"--l sentence_highlight\">Realizar una jornada de reforestaci\u00f3n en las \u00e1reas de la casa de formaci\u00f3n y comunidad local (Fecha: Julio a Noviembre 2025). <\/span><\/p><p><span class=\"--l sentence_highlight\">Gestionar la posibilidad de un aumento de paneles solares para una mayor producci\u00f3n de energ\u00eda renovable (Fecha: julio de 2025 a febrero de 2026).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78e759a elementor-widget elementor-widget-button\" data-id=\"78e759a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14612e1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"14612e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d1573a5 e-flex e-con-boxed e-con e-parent\" data-id=\"d1573a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-410a7cd elementor-widget elementor-widget-menu-anchor\" data-id=\"410a7cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"CCHS\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf1e89 elementor-widget elementor-widget-text-editor\" data-id=\"1bf1e89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Carmel Catholic High School<br \/><\/strong><strong>Mundelein, Illinois<br \/><\/strong><strong>Presentado: 4 de mayo de 2025<br \/><br \/><\/strong><\/h4><h4><strong>Antecedentes e iniciativas de sostenibilidad anteriores y en curso<\/strong><\/h4><h4><strong>Reducci\u00f3n del impacto ambiental y de los costes<\/strong><\/h4><p>Energ\u00eda<\/p><ul><li>Carmel realiz\u00f3 un seguimiento de los datos de consumo de energ\u00eda durante los tres \u00faltimos a\u00f1os utilizando el software ARC. ARC es una plataforma de rendimiento sostenible del USGBC, el Consejo de Construcci\u00f3n Ecol\u00f3gica de Estados Unidos. El primer movimiento fundacional de Carmel fue nuestra capacidad para medir y hacer un seguimiento del uso de los residuos energ\u00e9ticos. Una vez que empezamos a rastrear y analizar los datos, pudimos poner en marcha programas para reducir el consumo, como un programa de reciclaje electr\u00f3nico y recordatorios semanales para desconectar la tecnolog\u00eda innecesaria durante los fines de semana y las pausas largas. En conjunto, en los dos \u00faltimos a\u00f1os hemos registrado un descenso de 5% en el consumo de energ\u00eda.<\/li><li>Carmel ha firmado recientemente un contrato para la instalaci\u00f3n de un gran campo solar que se espera que proporcione unos 925.000 kWh en su primer a\u00f1o, lo que supone alrededor de 41% de su consumo anual de energ\u00eda. El dise\u00f1o, cuidadosamente pensado, preserva el espacio natural existente en el campus al instalarse exclusivamente en los tejados de la escuela.  Este planteamiento tambi\u00e9n reducir\u00e1 el calor radiante producido por ese tejado y devuelto a la atm\u00f3sfera.<\/li><li>Adem\u00e1s, Carmel aplica una mir\u00edada de m\u00e9todos para mitigar el derroche de energ\u00eda. Todas las bombillas del campus -ya sea en las aulas, los pasillos, el gimnasio o las propias luces del estadio de f\u00fatbol- son LED. Como ya se ha dicho, Carmel tambi\u00e9n ha puesto en marcha recordatorios de \"desconexi\u00f3n\", en los que profesores y alumnos desconectan toda la tecnolog\u00eda antes de los descansos largos. Los alumnos tambi\u00e9n ayudan a auditar las aulas y a los profesores a desconectar durante los fines de semana. Adem\u00e1s, muchos profesores cubren sus ventanas con cortinas opacas durante los d\u00edas m\u00e1s calurosos para ayudar a la escuela a utilizar la energ\u00eda para enfriar el edificio. Estas son las principales formas en que Carmel se ha comprometido en un proceso de mitigaci\u00f3n energ\u00e9tica.<\/li><li>Recientemente, la escuela ha llevado a cabo un proyecto de saneamiento medioambiental totalmente voluntario, a su costa, para retirar un dep\u00f3sito de fuel obsoleto y ha realizado un estudio de impacto medioambiental del suelo de la zona. Este esfuerzo por garantizar que somos buenos administradores de la tierra en la que operamos es un valor fundamental de nuestra misi\u00f3n y funcionamiento.<\/li><li>En los \u00faltimos diez a\u00f1os se han llevado a cabo varios proyectos de renovaci\u00f3n que abarcan casi 50% de todo nuestro campus, por dentro y por fuera. Estos proyectos incluyen: En 2013, se renovaron el Centro de Bellas Artes y Artes Esc\u00e9nicas y el Information Commons. El ala de Bellas Artes pas\u00f3 de ser un monasterio a un espacio de 33.000 pies cuadrados con aulas y salas de pr\u00e1cticas. Adem\u00e1s, la biblioteca de la escuela se renov\u00f3 para convertirla en un Information Commons. El proyecto de Bellas Artes obtuvo la certificaci\u00f3n LEED de plata. En 2020, se renov\u00f3 la entrada principal de la escuela, incluyendo un moderno vest\u00edbulo y zona de recepci\u00f3n, un centro de conferencias de 2.268 pies cuadrados que anteriormente era una capilla desacralizada, un camino al Jard\u00edn de Mar\u00eda del Monte Carmelo y acceso al espacio de reuni\u00f3n al aire libre del Jard\u00edn del Esp\u00edritu Santo. En 2020, el gimnasio, que antes era la sala de pesas y la sala de lucha, se renov\u00f3 y se convirti\u00f3 en una instalaci\u00f3n de \u00faltima generaci\u00f3n de 12.000 pies cuadrados. El suelo se fabric\u00f3 con esteras de caucho reciclado respetuoso con el medio ambiente. En 2020, se renov\u00f3 el auditorio de la escuela para aprovechar al m\u00e1ximo el espacio. Las luces LED sustituyeron a la mayor parte de la antigua iluminaci\u00f3n del escenario y de las actuaciones. Tambi\u00e9n se actualiz\u00f3 el sistema de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado para que este espacio fuera m\u00e1s eficiente a la hora de calentar y enfriar. El escenario y el atrezzo de las representaciones se construyen principalmente con madera, tornillos y otros materiales reutilizados, lo que evita que acaben en los vertederos. En 2021, casi 100% de la iluminaci\u00f3n de nuestro edificio se sustituy\u00f3 por iluminaci\u00f3n LED, incluidos el Salvi Arena y el Baker Stadium. En 2021, se sustituy\u00f3 el aparcamiento utilizando 25% de asfalto recuperado. En este proyecto se incluy\u00f3 la adici\u00f3n de bordillos para solucionar el drenaje del agua estancada. Se instalaron islas de \u00e1rboles en la zona de aparcamiento, a\u00f1adiendo 22 nuevos \u00e1rboles a nuestro campus.  A partir de 2021, se renovaron patios y espacios verdes, como el Jard\u00edn de Mar\u00eda y el Jard\u00edn del C\u00edrculo de Amigos, para un uso m\u00e1s activo por parte de los alumnos y las aulas. En 2022, la capilla de la escuela y el Centro Espiritual Mary Frances Clarke contiguo se renovaron para modernizar el espacio de reuni\u00f3n espiritual y social. En esta renovaci\u00f3n se reutilizaron intencionadamente materiales significativos de espacios anteriores de la escuela. Por ejemplo, el m\u00e1rmol original se cort\u00f3 y reutiliz\u00f3 como elemento est\u00e9tico destacado del nuevo espacio. En 2022, la eliminaci\u00f3n del asfalto de la zona suroeste del campus se sustituy\u00f3 por una zona verde y un comedor al aire libre. A partir de 2023, comenzaron las remodelaciones integrales de los cuartos de ba\u00f1o con nuevos lavabos de bajo consumo. Se han completado dos renovaciones de cuartos de ba\u00f1o, y cuatro m\u00e1s est\u00e1n por venir. En 2023, se instal\u00f3 un sendero exterior de 1,5 km, el Paseo del Rosario, alrededor del per\u00edmetro del campus. En los \u00faltimos diez a\u00f1os, se han instalado nuevas cubiertas en 68.129 pies cuadrados de los 300.000 pies cuadrados del tejado de nuestro edificio. Se ha a\u00f1adido aislamiento adicional para aumentar la eficiencia energ\u00e9tica, y los nuevos tejados tienen una clasificaci\u00f3n R-36. En los \u00faltimos diez a\u00f1os, las actualizaciones del sistema de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado han hecho que nuestro edificio sea m\u00e1s eficiente desde el punto de vista energ\u00e9tico. Tambi\u00e9n se han sustituido 75% de ventanas y retirado 90% de amianto.<\/li><\/ul><p><br \/>Agua y suelo<\/p><ul><li>Todo el riego del campus se realiza con agua municipal. Los alumnos recogen el agua de lluvia para utilizarla en el Huerto de El\u00edas, que se destina al cultivo y la donaci\u00f3n de productos a una organizaci\u00f3n ben\u00e9fica local.<\/li><\/ul><p><br \/>Gesti\u00f3n de residuos y productos qu\u00edmicos<\/p><ul><li>El Programa de Reducci\u00f3n de Desperdicios de la Cafeter\u00eda es un m\u00e9todo nuevo e innovador que Carmel inici\u00f3 durante el a\u00f1o escolar 22-23 para combatir el desperdicio de alimentos de los estudiantes en el comedor. Los estudiantes de Carmel son educados sobre qu\u00e9 art\u00edculos van en qu\u00e9 contenedores. Todos los materiales compostables, reciclables y de desecho tienen sus cubos asignados. Hay estudiantes y profesores voluntarios en los comedores cada d\u00eda para asegurar que estas pol\u00edticas se siguen. Adem\u00e1s, realizamos una auditor\u00eda anual de recogida y reciclaje de residuos electr\u00f3nicos para recopilar datos sobre la eficacia de nuestros h\u00e1bitos actuales y obtener ideas sobre lo que se puede mejorar. Por \u00faltimo, en cada aula se recicla por separado el papel y el pl\u00e1stico, lo que coincide con la gesti\u00f3n tradicional de la basura.<\/li><li>Nuestra escuela utiliza enfoques de Qu\u00edmica Verde con un m\u00ednimo de residuos. Hacemos laboratorios a microescala, lo que tambi\u00e9n minimiza el uso de productos qu\u00edmicos y residuos. El consumo estimado de productos qu\u00edmicos de laboratorio es de unos 500 L. Tenemos aproximadamente 150 galones de productos qu\u00edmicos de limpieza almacenados en armarios cerrados con llave. Adem\u00e1s, tambi\u00e9n tenemos aproximadamente 100 galones de desinfectante l\u00edquido para manos que tambi\u00e9n se almacena en un \u00e1rea a la que s\u00f3lo puede acceder el personal de mantenimiento. Tambi\u00e9n hay 110 galones de cera l\u00edquida para nuestros suelos, a la que s\u00f3lo puede acceder el personal de mantenimiento. Anderson Pest Solutions se encarga del control de plagas. En un momento dado, tenemos m\u00e1s de 24-18 oz latas de aerosol y 16 oz de gel de hormigas, ambos de los cuales se almacenan en el \u00e1rea de suministro de mantenimiento.<\/li><\/ul><p><br \/>Transporte alternativo<\/p><ul><li>En este momento, alrededor de 50% de los estudiantes conducen solos a la escuela, 25% comparten coche, y 18% toman el autob\u00fas. Los datos adjuntos proceden de una encuesta realizada a la comunidad dos veces al a\u00f1o a trav\u00e9s de la plataforma ARC de Carmel. La encuesta se comparte digitalmente como un enlace con la comunidad de Carmel. Mientras que el transporte puede ser un reto en un contexto de la escuela no p\u00fablica, un conjunto de cuatro estaciones de carga EV es parte de la campa\u00f1a de capital actual y se instalar\u00e1 como parte de la instalaci\u00f3n solar. V\u00e9ase la figura 7 del anexo.<\/li><li>Carmel anima a compartir coche y autob\u00fas tanto como sea posible. Este a\u00f1o tenemos 167 usuarios de autob\u00fas, alrededor del 15% del alumnado. Tambi\u00e9n hay \"caminantes\", que van en bicicleta o veh\u00edculos similares, pero estos datos est\u00e1n infrarrepresentados. Se puede estimar que una cuarta parte de los alumnos del Carmel toman el autob\u00fas, comparten coche o van a pie todo el tiempo o al menos parte del tiempo.<\/li><li>Carmel colabora con una empresa local de autobuses para gestionar cinco rutas de autob\u00fas que transportan a los alumnos de ida y vuelta a la escuela. El programa de transporte en autob\u00fas funciona con p\u00e9rdidas para animar a los usuarios a utilizar el autob\u00fas. Este a\u00f1o tenemos 167 alumnos. Adem\u00e1s, tambi\u00e9n hay alumnos que utilizan el transporte p\u00fablico, a los que ayudamos anunciando y vendiendo pases de autob\u00fas con descuento.<\/li><\/ul><h3>\u00a0<\/h3><h3>Mejorar la salud y el bienestar de los estudiantes y el personal<\/h3><p>Salud medioambiental<\/p><ul><li>Carmel contrata a Anderson Pest Solutions para que le visite una vez al mes e inspeccione las trampas colocadas por toda la escuela.<\/li><li>Disponemos de una campana extractora en la cocina principal para evacuar el mon\u00f3xido de carbono generado por la cocina y los hornos. Hay campanas extractoras y sistemas de ventilaci\u00f3n en todos los laboratorios de ciencias.<\/li><li>Todas las puertas exteriores est\u00e1n cerradas con llave despu\u00e9s del comienzo de las clases, y cualquier persona que entre en el edificio despu\u00e9s de las 8:05 am debe registrarse en la recepci\u00f3n para obtener una tarjeta de visitante. Durante las ma\u00f1anas, tenemos dos puertas programadas para desbloquearse de 6:30 a 8:05 am para cuando llegan los estudiantes, y esas son monitoreadas por el personal de 7:30 a 8:05 am. La mayor\u00eda de las puertas exteriores tienen acceso mediante llavero. Tambi\u00e9n contamos con un guardia de seguridad a tiempo completo. Carmel tiene 52 c\u00e1maras instaladas en todo el interior y el exterior del campus, y tenemos dos simulacros de incendio y un simulacro de cierre por a\u00f1o.<\/li><li>Las aulas se limpian a diario, y las unidades de techo tienen instalados filtros Merv 8 para ayudar a filtrar el aire.<\/li><li>Para ayudar a combatir la condensaci\u00f3n y la humedad, Carmel ha hecho ajustes de temperatura y compuertas de aire en el aire acondicionado para ayudar a eliminar la humedad de las aulas y las habitaciones con exceso de humedad. Hemos a\u00f1adido deshumidificadores a esas zonas.<\/li><li>Se ha realizado el mantenimiento de las unidades uni-vent y rooftop, y las actualizaciones de la unidad de tratamiento de aire se realizan dos veces al a\u00f1o, cuando cambiamos de aire acondicionado a calefacci\u00f3n y, a continuaci\u00f3n, cuando volvemos a utilizar aire acondicionado. El mantenimiento incluye el cambio de filtros, la lubricaci\u00f3n de la articulaci\u00f3n, y la calibraci\u00f3n de ellos para abrir y cerrar correctamente. En esas ocasiones, tambi\u00e9n se limpian las bobinas de las unidades de techo, o RTU, para garantizar la correcta disipaci\u00f3n del calor de la bobina del condensador.<\/li><li>Todas las rejillas de ventilaci\u00f3n de las aulas y las unidades de techo tienen compuertas de aire exterior que aspiran aire del exterior cuando est\u00e1n en funcionamiento.<\/li><li>Si tenemos que reparar una unidad de ventilaci\u00f3n, una unidad de tratamiento de aire o una unidad de tratamiento de aire, inspeccionamos el filtro para asegurarnos de que est\u00e1 limpio y lo sustituimos si es necesario.<\/li><li>La mayor parte de la limpieza de la escuela se realiza con el sistema \"Pathosans\", sin productos qu\u00edmicos y que utiliza agua, sal y un \"generador\" para hacer las soluciones.<\/li><\/ul><p><br \/>Nutrici\u00f3n y forma f\u00edsica<\/p><ul><li>Carmel cuenta con un huerto ecol\u00f3gico, Elijah's Garden, organizado y mantenido por el Garden Club y otros estudiantes. Los estudiantes de ingenier\u00eda construyeron las camas del jard\u00edn, el compost se hace in situ cada a\u00f1o a partir de los residuos recogidos en los comedores, y el equipo de f\u00fatbol rellena las camas con ese compost anualmente. En 2022, se donaron 300 libras de productos del huerto de Elijah a una despensa de alimentos local. Y en 2023, se donaron 500 libras. Las hierbas y verduras del jard\u00edn tambi\u00e9n se utilizan en las clases de salud para la creaci\u00f3n de recetas, donde la nutrici\u00f3n es una parte importante del plan de estudios. Los efectos de las dietas en la salud tambi\u00e9n se estudian en las clases de anatom\u00eda y biolog\u00eda. Adem\u00e1s, Elijah's Garden es un aula al aire libre para varias clases de medio ambiente, arte y fotograf\u00eda. El jard\u00edn es realmente un laboratorio al aire libre, un lugar de respiro y una fuente de inspiraci\u00f3n para distintas clases.\u00a0<\/li><li>Los cursos de Educaci\u00f3n para la Salud utilizan el plan de estudios de nutrici\u00f3n y la programaci\u00f3n de PLT4M, una plataforma de bienestar K-12 construida para la pr\u00f3xima generaci\u00f3n de alfabetizaci\u00f3n f\u00edsica, y MyPlate.gov. Estos servicios se especializan en aumentar el conocimiento de los estudiantes sobre c\u00f3mo las opciones diet\u00e9ticas crecen, remodelan, reparan y reponen el cuerpo. Los alumnos utilizan MyPlate durante una evaluaci\u00f3n formativa interactiva para descubrir la funci\u00f3n del tama\u00f1o de las porciones, los beneficios directos para la salud y destacar alimentos importantes en nuestra dieta actual. A continuaci\u00f3n, nuestro proyecto final permite a los alumnos realizar un seguimiento, etiquetar y analizar su propio consumo durante varios d\u00edas. Al completar este proyecto, los alumnos disponen de una v\u00eda tangible para etiquetar los alimentos y los grupos de nutrientes, a la vez que se toman un momento para reconocer lo mucho que han aprendido sobre el papel que desempe\u00f1a la nutrici\u00f3n en nuestra sociedad actual. Adem\u00e1s, TeamBuildr es un software en l\u00ednea de fuerza y acondicionamiento utilizado por el Departamento de Atletismo de Carmel y los cursos de educaci\u00f3n f\u00edsica. Este software permite dise\u00f1ar entrenamientos espec\u00edficos para el deporte y las habilidades de nuestro alumnado.<\/li><li>Fuel Up to Play60 se utiliza en Carmel durante la unidad de flag football. El programa proporciona equipos gratuitos y un plan de estudios para los cursos de Educaci\u00f3n F\u00edsica. El equipo tambi\u00e9n se utiliza en espacios al aire libre y permite la participaci\u00f3n en actividades de f\u00fatbol bandera extracurriculares e intramuros para los estudiantes.<\/li><li>Los espacios al aire libre y los jardines son importantes para los estudiantes del Carmel y para la comunidad del Carmel en general. Los estudiantes tienen acceso a los espacios al aire libre durante todo el d\u00eda a trav\u00e9s de vistas de la naturaleza (todas las aulas y pasillos tienen ventanas) y a trav\u00e9s del acceso a los patios durante el tiempo de clase e incluso los per\u00edodos de paso. Los cursos de teolog\u00eda utilizan espacios exteriores del campus rodeados de vegetaci\u00f3n y serenidad para la oraci\u00f3n, la reflexi\u00f3n y la meditaci\u00f3n. Este es un momento para que los estudiantes aprecien el hermoso paisaje que rodea la escuela mientras se centran intencionadamente en estar presentes con sus pensamientos en la naturaleza.  Como parte de nuestras actividades del d\u00eda del bienestar cada semestre, el alumnado participa en actividades al aire libre. Las actividades incluyen paseos por la naturaleza y para aliviar el estr\u00e9s, pickleball, f\u00fatbol, kickball, spikeball y jardiner\u00eda para obtener semillas aut\u00f3ctonas. Adem\u00e1s, todo el plan de estudios de la escuela de verano de educaci\u00f3n f\u00edsica se basa en la educaci\u00f3n al aire libre, incluyendo ciclismo, senderismo, kayak en Independence Grove Forest Preserve en Libertyville, y otros eventos deportivos. Carmel Catholic High School tambi\u00e9n organiza al menos un d\u00eda de servicio escolar cada a\u00f1o que combina ejercicio, naturaleza y nutrici\u00f3n. Una pieza fundamental de esta experiencia es completar una caminata de 5k dentro de una reserva natural al otro lado de la calle del campus. A continuaci\u00f3n, cada curso dedica tiempo a preparar y empaquetar comidas para familias necesitadas a trav\u00e9s de la organizaci\u00f3n sin \u00e1nimo de lucro Feed My Starving Children. Este evento culminante ofrece a los estudiantes la oportunidad de comprender el papel del servicio, la nutrici\u00f3n y los eventos de creaci\u00f3n de comunidad que se celebran en nuestros espacios verdes.<\/li><li>La sala de pesas y las instalaciones de cardio, recientemente renovadas, est\u00e1n a disposici\u00f3n de todos los profesores, empleados y estudiantes. Carmel se ha asociado con Illinois Bone and Joint Institute (IBJI) para facilitar la supervisi\u00f3n y promover el uso adecuado de la sala de pesas y las instalaciones de cardio. La asociaci\u00f3n ha permitido que el atletismo y las actividades extracurriculares se centren en el acondicionamiento dentro y fuera de temporada. Esta asociaci\u00f3n no s\u00f3lo aumenta la fuerza f\u00edsica de los estudiantes, sino que les da confianza y conocimiento para utilizar las instalaciones correctamente. Adem\u00e1s de promover la salud f\u00edsica y el bienestar a trav\u00e9s de las instalaciones de pesas de nuestra sala, un profesor y entrenador in situ est\u00e1 implementando un aspecto nutricional clave para construir y remodelar el tejido muscular. El entrenador Billy Moore ofrece combustible para despu\u00e9s del entrenamiento en forma de leche con chocolate y otras opciones de batidos de prote\u00ednas.  Por \u00faltimo, durante el a\u00f1o escolar 2022-2023, la facultad y el personal participaron en reuniones mensuales de formaci\u00f3n para aprender sobre ecolog\u00eda integral. Esto incluy\u00f3 oportunidades para cultivar un huerto, participar en un paseo por la naturaleza, escribir un diario sobre la naturaleza o crear obras de arte medioambientales.<\/li><\/ul><p><br \/>Salud escolar coordinada, salud mental, clima escolar y seguridad<\/p><ul><li>En Carmel Catholic High School, adem\u00e1s de las asignaturas optativas de Educaci\u00f3n F\u00edsica, Salud, Danza, Yoga y Educaci\u00f3n F\u00edsica disponibles, todos los alumnos participan en un programa de asesoramiento diario. Este programa facilita las iniciativas de bienestar y proporciona un espacio para que los estudiantes desarrollen la salud mental y habilidades de afrontamiento. Como ya se ha mencionado, tambi\u00e9n organizamos un D\u00eda del Bienestar cada semestre. Este d\u00eda permite a los estudiantes explorar diferentes facetas de su bienestar, incluyendo pero no limitado a lo social, emocional, espiritual, intelectual, f\u00edsico, ambiental, financiero y ocupacional.<\/li><li>Erika's Lighthouse es un programa de salud mental y un club de empoderamiento para adolescentes. Los grupos de debate dirigidos por compa\u00f1eros ayudan a normalizar las conversaciones en torno a la salud mental. Adem\u00e1s, las lecciones del Instituto Social se utilizan en 50% de las lecciones de asesoramiento. El Instituto Social capacita a los estudiantes y profesores para navegar positivamente por las redes sociales y la tecnolog\u00eda.<\/li><li>Los estudiantes tienen numerosas oportunidades para la salud y la forma f\u00edsica. Esto es evidente a trav\u00e9s de la amplia variedad de clases de educaci\u00f3n f\u00edsica y acondicionamiento f\u00edsico disponibles para las clases de cr\u00e9dito. Esto incluye yoga, fuerza y acondicionamiento, educaci\u00f3n f\u00edsica, desarrollo de velocidad y danza. Los cursos de Educaci\u00f3n para la Salud utilizan una secuencia de 9 unidades que incorporan el bienestar mental\/f\u00edsico, nutrici\u00f3n, abuso de sustancias, ciudadan\u00eda digital, relaciones\/consentimiento, reproducci\u00f3n humana, enfermedades cr\u00f3nicas e infecciosas y primeros auxilios.<\/li><\/ul><h3>\u00a0<\/h3><h3>Alfabetizaci\u00f3n medioambiental eficaz<\/h3><p>Cultura escolar de sostenibilidad<\/p><ul><li>En el Carmelo hablamos de la sostenibilidad como parte de la doctrina social cat\u00f3lica y del cuidado de la creaci\u00f3n. Todos los alumnos aprenden sobre la doctrina social y las responsabilidades para con la comunidad, la creaci\u00f3n y los marginados de la sociedad.<\/li><li>Todos los niveles de la administraci\u00f3n han desempe\u00f1ado un papel crucial y de apoyo en la escuela. El presidente de nuestro centro, el Dr. Bonham, es un partidario total y ha creado apoyo entre el consejo escolar. El director, el Sr. Ahlgrim, forma parte del Equipo Verde y ha demostrado su apoyo ayudando a los alumnos a realizar auditor\u00edas de residuos y a esparcir mantillo en los jardines.<\/li><li>La escuela cuenta con un profesor que ejerce de gestor de sostenibilidad y tambi\u00e9n dirige el Equipo Verde de la escuela.<\/li><li>Hay un Equipo Verde de diez personas dirigido por nuestro responsable de sostenibilidad y formado por estudiantes, profesores y personal, as\u00ed como antiguos alumnos. El a\u00f1o pasado, el club medioambiental dirigido por estudiantes desarroll\u00f3 la idea de proporcionar kits de utensilios para ayudar a eliminar los utensilios de pl\u00e1stico de un solo uso en la cafeter\u00eda. Los estudiantes tambi\u00e9n organizan actividades de la Semana de la Tierra, como la limpieza del campus y la recogida de semillas. El club de jardiner\u00eda, dirigido por estudiantes, gestiona los huertos de verduras y plantas aut\u00f3ctonas. Este a\u00f1o se donaron m\u00e1s de 500 libras de productos a una despensa local. A los alumnos tambi\u00e9n les gusta crear peque\u00f1os ramos de flores para los profesores. Existe una Sociedad de Honor Santa Kateri, que lleva el nombre de una santa ind\u00edgena. A trav\u00e9s de esta sociedad de honor, los alumnos participan activamente en 10 horas de servicio medioambiental ecol\u00f3gico cada a\u00f1o. Al graduarse, reciben un cord\u00f3n verde como s\u00edmbolo de su servicio y compromiso.<\/li><li>El a\u00f1o pasado, la escuela duplic\u00f3 el n\u00famero de estaciones de recarga de agua para que cada aula no est\u00e9 a m\u00e1s de 200 pies de una estaci\u00f3n de recarga. Tambi\u00e9n se a\u00f1adieron estaciones de recarga en la cafeter\u00eda para un acceso equitativo al agua potable. Todos los viernes, antes de las pausas largas y antes del verano, los alumnos ayudan a los profesores a \"desenchufar\" todos los objetos del aula para minimizar el uso de electricidad fantasma. Las comidas de los profesores utilizan materiales compostables y los profesores tambi\u00e9n incorporan estrategias de compostaje y minimizaci\u00f3n de residuos en sus fiestas y eventos. Los estudiantes ayudan como voluntarios en la cafeter\u00eda para educar a los alumnos en los procedimientos de compostaje, reciclaje y residuos. Todos los a\u00f1os se realiza una recogida de residuos electr\u00f3nicos. Al final del curso escolar, hay un importante programa de reutilizaci\u00f3n y reciclaje. Se recogen material escolar usado, uniformes, libros y otros materiales. El a\u00f1o pasado se reutilizaron o vendieron casi 2.000 libras de materiales. Los libros, uniformes y material se donan a los estudiantes que reciben ayuda financiera. Algunos libros se venden o donan a otras escuelas.<\/li><li>La justicia social y la espiritualidad ecol\u00f3gica son partes importantes de todos los programas y la educaci\u00f3n en torno a la sostenibilidad en el Carmelo. El cuidado de la creaci\u00f3n se ense\u00f1a como una responsabilidad fundamental de los alumnos. El colegio tambi\u00e9n est\u00e1 registrado en la plataforma de Acci\u00f3n Global Laudato Si del Vaticano, que hace un seguimiento de sus avances hacia sus objetivos clim\u00e1ticos.<\/li><\/ul><p><br \/>Plan de estudios y pedagog\u00eda<\/p><ul><li>Carmel Catholic defiende la alfabetizaci\u00f3n medioambiental. Las lecciones de asesoramiento incluyen elementos espec\u00edficos del t\u00e9rmino (comprensi\u00f3n, concienciaci\u00f3n, comportamientos, actitudes), que se ampl\u00edan a lo largo del plan de estudios de todo el a\u00f1o, haciendo hincapi\u00e9 en \u00e9l como punto central para los alumnos y el personal. Cada agosto, vemos demostraciones sobre c\u00f3mo separar los residuos de alimentos en las estaciones de reciclaje de la cafeter\u00eda, mientras que al final del semestre, aprendemos d\u00f3nde reciclar los cuadernos. La nueva formaci\u00f3n del profesorado cada oto\u00f1o pone de relieve nuestro compromiso con los valores fundamentales de educaci\u00f3n y justicia de nuestras \u00d3rdenes Fundadoras, inspir\u00e1ndonos a ser buenos administradores de la tierra. No evaluamos nuestra comprensi\u00f3n de la alfabetizaci\u00f3n medioambiental; m\u00e1s bien, la prueba de nuestra comprensi\u00f3n se encuentra en la adopci\u00f3n por parte de la comunidad de pr\u00e1cticas sostenibles, medidas por las libras de compost recogidas, los materiales reciclables separados y las verduras cultivadas.<\/li><li>Nuestro plan de estudios es rico en oportunidades de aprendizaje centradas en el medio ambiente. El plan de estudios \"Project Lead the Way\" para estudiantes de ingenier\u00eda incorpora conceptos de sostenibilidad. Por ejemplo, los estudiantes de ingenier\u00eda civil construyen una casa de \"H\u00e1bitat para la Humanidad\" que utiliza las directrices de sostenibilidad de HTH; estudian la certificaci\u00f3n LEED y debaten sobre el uso adecuado del aislamiento y el paisajismo para ahorrar energ\u00eda. Los estudiantes de Principios de Ingenier\u00eda construyen un coche que funciona con una pila de combustible y un panel solar. Los estudiantes de primer a\u00f1o de Ciencias de la Tierra ayudan a crear inter\u00e9s en nuestras otras clases optativas ecol\u00f3gicas, como Huella Ecol\u00f3gica Humana de Doble Cr\u00e9dito y Ciencias Medioambientales AP. Adem\u00e1s, el Club de Jardiner\u00eda se ofrece dos veces por semana para dar cabida a sus miembros activos, que cuidan y cosechan alimentos del Jard\u00edn de El\u00edas. La ecolog\u00eda se discute mucho en las clases de biolog\u00eda y qu\u00edmica, ya que los estudiantes consideran la composici\u00f3n atmosf\u00e9rica y la alteraci\u00f3n negativa de los contaminantes; esta interconexi\u00f3n entre las ciencias indica su importancia. Los profesores de qu\u00edmica compran materiales menos t\u00f3xicos para demostrar los conceptos de la qu\u00edmica verde minimizando la exposici\u00f3n. Nuestro responsable de higiene qu\u00edmica supervisa la compra, el almacenamiento y el uso de productos qu\u00edmicos. Para minimizar los residuos, compramos kits de productos qu\u00edmicos en lugar de hacer pedidos al por mayor. Los profesores siguen un plan publicado para eliminar los residuos qu\u00edmicos de forma responsable. En las clases de todas las disciplinas se opta por los recursos digitales en lugar del papel, y los esfuerzos de reciclaje en las aulas se incorporan a las hojas de procedimientos de los cursos y a los expositores de las aulas. En las clases de escenograf\u00eda, el atrezzo y las piezas del decorado se fabrican con materiales usados y reciclables y se dise\u00f1an para que puedan desmontarse para su recuperaci\u00f3n y reutilizaci\u00f3n. Se estudia la iluminaci\u00f3n esc\u00e9nica con LED y sus ventajas para el ahorro de energ\u00eda.<\/li><li>Nuestro plan estrat\u00e9gico nos pide que ampliemos las oportunidades de exploraci\u00f3n de carreras, incluidas las de sostenibilidad y ciencias ecol\u00f3gicas. Un equipo de profesores ha visitado el exitoso programa de exploraci\u00f3n de un distrito vecino con la esperanza de replicarlo para nuestros alumnos. En 2023, nuestro Club de Exploraci\u00f3n Profesional ret\u00f3 a sus miembros a seguir carreras creativas, muchas de ellas inmersas en tecnolog\u00edas ecol\u00f3gicas.<\/li><li>El aprendizaje al aire libre de los alumnos incluye la cocci\u00f3n de cer\u00e1mica, la exploraci\u00f3n de zool\u00f3gicos y jardines bot\u00e1nicos, la recogida de semillas en reservas forestales y los paseos por la naturaleza en el seminario, entre otras muchas actividades. Nuestro propio Jard\u00edn de Mar\u00eda se convierte en una luminosa aula al aire libre que involucra a toda la persona, ya que imparte la paz y la tranquilidad de la naturaleza, as\u00ed como recuerda al estudiante que nos encontramos con Dios en la creaci\u00f3n, cuya luz se refleja en la belleza que nos rodea. En la unidad \"Cuidado de la Creaci\u00f3n\/Laudato Si\" del \u00faltimo curso de Teolog\u00eda, los alumnos reflexionan sobre la belleza de la naturaleza con un paseo contemplativo por el Jard\u00edn de Mar\u00eda. Los estudiantes de primer a\u00f1o de la Fundaci\u00f3n tambi\u00e9n consideran la bondad de Dios en la creaci\u00f3n a trav\u00e9s de una reflexi\u00f3n b\u00edblica de Lectio Divina con im\u00e1genes del Jard\u00edn de Mar\u00eda.<\/li><li>Carmel Catholic High School se encuentra en un terreno aislado y exuberante barrio en Mundelein. Cada aula tiene una pared de ventanas, lo que permite la luz natural y vistas de la naturaleza para todos los estudiantes. El edificio de una sola planta tambi\u00e9n tiene numerosos patios que los estudiantes pasan a trav\u00e9s de todos los d\u00edas para ir de clase en clase. Los alumnos tambi\u00e9n pueden comer fuera durante el almuerzo. Hay 890 pies cuadrados de espacio verde por ocupante a tiempo completo en la escuela. Esto permite una interacci\u00f3n constante y diaria con la naturaleza. El campus tiene 333 \u00e1rboles, 714 arbustos y cientos de plantas perennes. Los \u00e1rboles se sustituyen cuando es necesario, y en los \u00faltimos cinco a\u00f1os se han plantado 49 \u00e1rboles. Un estudiante ha abierto una cuenta de Instagram con el lema \"\u00c1rboles del Carmelo\". Los departamentos de Religi\u00f3n y Lenguas del Mundo utilizan estos hermosos terrenos para sus descansos cerebrales al aire libre. Adem\u00e1s, se han creado etiquetas para los huertos en varios idiomas. Las clases de biolog\u00eda y ciencias medioambientales utilizan los espacios exteriores para laboratorios de biodiversidad. Los estudiantes de arte tambi\u00e9n utilizan el jard\u00edn para clases de inspiraci\u00f3n y fotograf\u00eda.<\/li><\/ul><p><br \/>Participaci\u00f3n comunitaria<\/p><ul><li>El servicio y la justicia social ecol\u00f3gica son valores fundamentales y, como tales, el compromiso c\u00edvico es un componente esencial de la experiencia del Carmelo. A trav\u00e9s de la Sociedad de Honor Santa Katerie, los estudiantes participan en el servicio comunitario ecol\u00f3gico tanto dentro como fuera del campus. Los estudiantes ayudan con proyectos locales de conservaci\u00f3n, tales como la eliminaci\u00f3n de espino cerval, jardiner\u00eda comunitaria, y el ahorro de semillas de plantas nativas. Alumnos y profesores ayudan en el huerto ecol\u00f3gico del campus y entregan productos a una despensa de alimentos local. Los estudiantes asistieron a las jornadas de presi\u00f3n del CEJA en Springfield antes de que se aprobara la ley. Esto incluy\u00f3 tanto en persona y el cabildeo virtual durante COVID-19. Se han reunido con legisladores para hablar de energ\u00eda limpia y de la importancia del medio ambiente. El a\u00f1o pasado, se reunieron con legisladores locales para presionar a favor del corredor verde de la Ruta 53. Carmel promueve activamente el compromiso con la comunidad entre los estudiantes y el personal a trav\u00e9s de nuestros programas de asesoramiento, actividades de formaci\u00f3n y reuniones de profesores. Estas iniciativas pretenden guiar a los estudiantes en su crecimiento personal y acad\u00e9mico, fomentando un sentido de responsabilidad social. En t\u00e9rminos de servicio comunitario, los estudiantes tienen la oportunidad de participar en varios proyectos, incluyendo One Hope United, Feed My Starving Children, Our Lady of the Angels Food Pantry, Beacon Place, Bernie's Books, Animal House Shelter, Catholic Charities, y muchos m\u00e1s. Los estudiantes pueden formar parte de la Sociedad de Honor de Santa Teresa de Lisieux, donde los estudiantes reciben oportunidades semanales a trav\u00e9s de nuestro bolet\u00edn digital para servir a la comunidad y aumentar la participaci\u00f3n c\u00edvica fuera de la escuela. El colegio hace especial hincapi\u00e9 en los \"temas verdes\" en los programas de asesoramiento, promoviendo la concienciaci\u00f3n y fomentando pr\u00e1cticas responsables con el medio ambiente. Esto incluye la gesti\u00f3n activa de los residuos en el comedor escolar, la realizaci\u00f3n de programas anuales de reciclaje y el trabajo para reducir nuestra huella de carbono. Adem\u00e1s, la escuela colabora con una despensa local de alimentos mediante el servicio voluntario y el suministro de verduras frescas cultivadas en nuestros huertos escolares. Los alumnos contribuyen a embellecer el colegio participando en actividades como la recogida de basura en el campus y la creaci\u00f3n de un jard\u00edn dise\u00f1ado espec\u00edficamente para atraer abejas y mariposas. Las actividades mensuales de formaci\u00f3n del profesorado, alineadas con principios como el de Laudato Si', se centran en los problemas de la comunidad y la implicaci\u00f3n c\u00edvica. Los talleres y eventos ofrecen una visi\u00f3n de la acci\u00f3n global, reforzando la importancia de la responsabilidad social. Las reuniones de personal integran el compromiso comunitario y c\u00edvico en la mentalidad escolar. Se insta a los profesores a incorporar proyectos relacionados con la comunidad en su plan de estudios y en el aula, haciendo hincapi\u00e9 en las pr\u00e1cticas de sostenibilidad como la reducci\u00f3n de residuos de papel en el aula mediante el uso de contenedores espec\u00edficos para el reciclaje de residuos, el uso de plataformas en l\u00ednea para presentar el trabajo, la donaci\u00f3n de libros de texto viejos, la donaci\u00f3n de uniformes, la limpieza de nuestra escuela, y la conservaci\u00f3n de la energ\u00eda. Carmel Catholic fomenta la participaci\u00f3n activa en actividades c\u00edvicas m\u00e1s all\u00e1 de la escuela, entretejiendo estos valores en la experiencia educativa. El programa, las actividades y las discusiones continuas dentro de la comunidad escolar promueven un sentido de responsabilidad hacia las preocupaciones sociales y medioambientales.<\/li><li>Como centro de ense\u00f1anza secundaria, el Carmel colabora con escuelas y universidades locales. Los estudiantes del Carmel participan regularmente en laboratorios y actividades de sostenibilidad con estudiantes m\u00e1s j\u00f3venes. Cada primavera, hay un d\u00eda de visita de 8\u00ba grado en nuestro campus. Los estudiantes de medio ambiente planifican, organizan y llevan a cabo actividades de sostenibilidad con los estudiantes m\u00e1s j\u00f3venes. Los estudiantes de Carmel tambi\u00e9n visitan las escuelas locales para hablar de sostenibilidad y realizar talleres de superh\u00e9roes medioambientales. Carmel tambi\u00e9n se asocia con la Universidad Loyola de Chicago para ofrecer clases de educaci\u00f3n ambiental de doble cr\u00e9dito. Entre ellas se incluyen las clases de Huella Ecol\u00f3gica Humana y Ciencias Medioambientales. El colegio comunitario local, College of Lake County (CLC), es tambi\u00e9n un valioso recurso. Durante la clase de verano de Introducci\u00f3n a la Empresa Sostenible se ofrece una excursi\u00f3n para visitar los programas de energ\u00eda limpia del CLC. Los estudiantes de Carmel tambi\u00e9n participan en la Feria de Vida Verde de Lake County promoviendo la alfabetizaci\u00f3n medioambiental y el voluntariado. Un grupo selecto de alumnos del Carmel participa en la Cumbre Juvenil sobre el Clima de la Archidi\u00f3cesis de Chicago. Estos estudiantes planean una cumbre clim\u00e1tica de un d\u00eda para los estudiantes de secundaria locales, incluyendo talleres y presentaciones.<\/li><li>Carmel utiliza diversos canales de medios sociales, boletines digitales y su sitio web para promover la sostenibilidad entre la comunidad en general.<\/li><li>El departamento de marketing del Carmel gestiona las cuentas del centro en Facebook, Twitter, Instagram y LinkedIn. En estas plataformas se comparten regularmente actualizaciones, anuncios y logros, lo que ayuda al colegio a conectar con un p\u00fablico m\u00e1s amplio, incluidos otros colegios y organizaciones interesados en promover la concienciaci\u00f3n medioambiental.<\/li><li>Carmel tambi\u00e9n entiende lo importante que es para los estudiantes formar parte de la promoci\u00f3n de la sostenibilidad. Nos centramos en los medios sociales gestionados por estudiantes, como la cuenta de Instagram @green.corsairs. Esta cuenta es una forma de compartir informaci\u00f3n sobre actividades y programas relacionados con la educaci\u00f3n medioambiental. Este esfuerzo dirigido por los estudiantes anima a los m\u00e1s j\u00f3venes a participar activamente en los esfuerzos de sostenibilidad de la escuela y act\u00faa como una fuente de informaci\u00f3n amena y cercana para la comunidad en general.<\/li><li>Carmel tambi\u00e9n utiliza un bolet\u00edn digital semanal. El bolet\u00edn se env\u00eda a todas las familias del colegio y ayuda a involucrar a padres, alumnos, profesores y personal. Anima a todos a participar en los esfuerzos de la escuela para ser m\u00e1s sostenible e incluye informaci\u00f3n sobre estas asociaciones y eventos.<\/li><\/ul><p><br \/>Desarrollo profesional<\/p><ul><li>Sesiones mensuales de formaci\u00f3n del profesorado\/personal programadas para 2022-2023 centradas exclusivamente en la educaci\u00f3n medioambiental, basadas en Laudato Si: Sobre el cuidado de nuestra casa com\u00fan, la enc\u00edclica del Papa Francisco de 2015. Estas reuniones de todo el personal contaron con ponentes como el P. Richard Fragomeni de la Uni\u00f3n Teol\u00f3gica Cat\u00f3lica, que habl\u00f3 sobre la Conversi\u00f3n Ecol\u00f3gica. Otros temas fueron la ecoespiritualidad y la educaci\u00f3n, el bien com\u00fan y las experiencias naturales.<\/li><li>Adem\u00e1s de las sesiones de formaci\u00f3n para todo el personal, las personas han participado en las siguientes actividades de desarrollo profesional relacionadas con el medio ambiente: M\u00e1ster en Gesti\u00f3n de la Sostenibilidad, curso de posgrado en Gesti\u00f3n de Residuos S\u00f3lidos, curso de posgrado en Dise\u00f1o Centrado en el Comportamiento para el Medio Ambiente, Conferencia Anual de la Asociaci\u00f3n de Educaci\u00f3n Medioambiental de Illinois.<\/li><li>Todos los profesores de ciencias reciben formaci\u00f3n y certificaci\u00f3n sobre residuos qu\u00edmicos cada tres a\u00f1os. Uno de los profesores de ciencias act\u00faa como responsable de higiene qu\u00edmica y tiene responsabilidades adicionales de formaci\u00f3n, certificaci\u00f3n y capacitaci\u00f3n. Cuatro de nuestros profesores han obtenido la certificaci\u00f3n Green Teacher a trav\u00e9s del USGBC. Uno de nuestros profesores es LEED Green Associate.<\/li><\/ul><h1>\u00a0<\/h1><h1>Esfuerzos de sostenibilidad propuestos para el ejercicio 2026<\/h1><p>Con un enfoque \"estrecho pero profundo\" de la sostenibilidad en el pr\u00f3ximo ejercicio, los esfuerzos se centrar\u00e1n en los tres \u00e1mbitos siguientes:<\/p><h2>1. Aprovechar los intereses de los estudiantes<\/h2><ul><li>A\u00f1adir preguntas relacionadas con la sostenibilidad a la encuesta de fin de curso de los estudiantes.<\/li><li>Impulsar la atenci\u00f3n y el apoyo a los dos clubes existentes relacionados con la sostenibilidad: Jardiner\u00eda y Medio Ambiente.<ul><li>Aclarar los estatutos y el alcance de las responsabilidades.<\/li><li>Recabar la opini\u00f3n de los estudiantes para iniciativas adicionales.<\/li><li>Apoye estas iniciativas econ\u00f3micamente y de otras formas.<\/li><\/ul><\/li><\/ul><h2>2. Participar en iniciativas ecol\u00f3gicas en el campus<\/h2><ul><li>Plantar y mantener un huerto frutal adem\u00e1s del Jard\u00edn de El\u00edas.<\/li><li>Garantizar que las cosechas de verduras y frutas se midan y se entreguen a las despensas de alimentos locales.<\/li><li>Implementar <em>Laudato Si<\/em>-a lo largo del Camino del Rosario.<\/li><\/ul><h2>3. Integrar la sostenibilidad en todos los planes de estudios de los departamentos<\/h2><ul><li>Aseg\u00farese de que cada departamento conoce los tres puntos de integraci\u00f3n propuestos.<\/li><li>Compruebe los progresos a mitad de a\u00f1o.<\/li><li>Aprovechar los datos de uso de recursos en las clases (electricidad, agua, distribuci\u00f3n de productos, etc.).<\/li><\/ul><p>Otras acciones, como las relacionadas con la cafeter\u00eda, se aplazar\u00e1n hasta un momento m\u00e1s apropiado.<\/p><h1>\u00a0<\/h1><h1>Ap\u00e9ndice: Lista de puntos de integraci\u00f3n curricular<\/h1><h2>Empresa y tecnolog\u00eda<\/h2><h3>Plan de estudios actual relacionado con la sostenibilidad:<\/h3><ul><li>Finanzas e inversiones: pros y contras de la inversi\u00f3n sostenible.<\/li><li>Intro to Business UCP: debate sobre el lavado verde en la \u00e9tica.<\/li><\/ul><h3>Plan de estudios adicional sobre sostenibilidad:<\/h3><ul><li><strong>Unidad 1: Sostenibilidad en Intro to Business UCP<\/strong><ul><li>Definici\u00f3n de sostenibilidad (econ\u00f3mica, medioambiental, social).<\/li><li>Responsabilidad social de las empresas (RSE), triple balance.<\/li><li>Casos pr\u00e1cticos de empresas sostenibles.<\/li><\/ul><\/li><li><strong>Unidad 2: Modelos empresariales sostenibles e iniciativa empresarial<\/strong><ul><li>Oportunidades de negocio ecol\u00f3gico, econom\u00eda circular, certificaci\u00f3n B Corp.<\/li><li>Desarrollar planes de negocio sostenibles.<\/li><\/ul><\/li><li><strong>Unidad 3: Cadena de suministro y abastecimiento \u00e9tico<\/strong><ul><li>Abastecimiento sostenible, comercio justo, huella de carbono.<\/li><li>Trabajo \u00e9tico y estudios de casos de l\u00edderes sostenibles.<\/li><\/ul><\/li><li><strong>Unidad 4: Marketing y comportamiento del consumidor<\/strong><ul><li>Lavado verde frente a marketing aut\u00e9ntico, etiquetado ecol\u00f3gico.<\/li><li>Comprensi\u00f3n de los consumidores ecol\u00f3gicos, creaci\u00f3n de marcas, estrategias digitales.<\/li><li>Estudio de caso: Seventh Generation.<\/li><li>Actividad: Dise\u00f1a una campa\u00f1a de marketing para un producto ecol\u00f3gico.<\/li><\/ul><\/li><li><strong>Unidad 5: Finanzas e inversi\u00f3n sostenibles<\/strong><ul><li>ESG, bonos verdes, inversi\u00f3n de impacto, incentivos gubernamentales.<\/li><li>Analizar los informes de sostenibilidad de las empresas.<\/li><li>Estudio de caso: \"Compra un par, regala un par\" de Warby Parker.<\/li><\/ul><\/li><li><strong>Unidad 6: Derecho y \u00e9tica empresarial<\/strong><ul><li>EPA, revelaciones clim\u00e1ticas de la SEC, pol\u00edticas comerciales mundiales.<\/li><\/ul><\/li><li><strong>Unidad 7: Sostenibilidad en Operaciones y Gesti\u00f3n<\/strong><ul><li>Eficiencia energ\u00e9tica, tecnolog\u00eda ecol\u00f3gica, indicadores clave de sostenibilidad.<\/li><li>El papel de las empresas en los ODS de la ONU.<\/li><li>Tendencias futuras: IA, neutralidad del carbono, estudio de caso IKEA.<\/li><\/ul><\/li><li><strong>Unidad 8: Gesti\u00f3n sanitaria<\/strong><ul><li>Estudios de casos, oradores invitados, simulaciones, debates.<\/li><li>Dise\u00f1ar cadenas de suministro sostenibles para la atenci\u00f3n sanitaria.<\/li><\/ul><\/li><\/ul><h2>Ingenier\u00eda<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>PLTW incluye temas de sostenibilidad.<\/li><li>Introducci\u00f3n a la ingenier\u00eda: ciclos de vida de los productos, ingenier\u00eda \u00e9tica.<\/li><li>Principios de ingenier\u00eda: reciclabilidad de los materiales.<\/li><li>Ingenier\u00eda civil: Proyecto Tiny House siguiendo el modelo de Habitat for Humanity.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>Fuentes de energ\u00eda alternativas.<\/li><li>Materiales del filamento: vegetales frente a derivados del petr\u00f3leo.<\/li><li>Cultura de reparaci\u00f3n frente a cultura de sustituci\u00f3n.<\/li><\/ul><h2>Ingl\u00e9s<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>Poes\u00eda de la naturaleza (10UCP, 12AP Lit), haikus (9UCP).<\/li><li>Investigaci\u00f3n sobre The Bean Trees, Into the Wild Light, Station Eleven.<\/li><li>Estudio tem\u00e1tico: La Biblia de Poisonwood, Frankenstein.<\/li><li>Pr\u00e1cticas sostenibles en el aula: desenchufar, compostables, limitaciones de IA.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>No se prev\u00e9n grandes incorporaciones este a\u00f1o.<\/li><\/ul><h2>Bellas Artes<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>Arte 2: culminaci\u00f3n utilizando materiales reciclados.<\/li><li>Cer\u00e1mica: reciclaje de arcilla.<\/li><li>Banda\/Coro: reutilizaci\u00f3n de m\u00fasica, reparaci\u00f3n de instrumentos.<\/li><li>Teatro: disfraces de segunda mano.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>Volver a solicitar iPads para partituras digitales.<\/li><li>Siga reciclando y reutilizando.<\/li><\/ul><h2>Matem\u00e1ticas<\/h2><h3>Plan de estudios previsto:<\/h3><ul><li>\u00c1lgebra 2\/3: proyectos de optimizaci\u00f3n.<\/li><li>\u00c1lgebra 1\/2: an\u00e1lisis de regresi\u00f3n del cambio clim\u00e1tico.<\/li><li>Precalc: modelizaci\u00f3n exponencial\/logar\u00edtmica de la energ\u00eda.<\/li><li>Geometr\u00eda: volumen y superficie en la conservaci\u00f3n del agua.<\/li><\/ul><h2>Educaci\u00f3n F\u00edsica y Salud<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>Aprendizaje al aire libre, paseos por la naturaleza, paseos en bicicleta, D\u00eda del Bienestar.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>Salud: temas de salud medioambiental (calidad del aire\/agua, toxinas).<\/li><li>Colaboraci\u00f3n con el Club de Jardiner\u00eda.<\/li><li>Organizar una jornada de embellecimiento del campus.<\/li><\/ul><h2>Estudios Sociales<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>Mundo antiguo: acueductos.<\/li><li>Historia Mundial e Historia de EE.UU.: industrializaci\u00f3n, conservaci\u00f3n, New Deal.<\/li><li>Gobierno de EE.UU. y gobiernos comparados: Clean Air\/Water Acts, pol\u00edticas internacionales.<\/li><li>Estudios afroamericanos: racismo medioambiental.<\/li><li>Geograf\u00eda y cuestiones globales: activismo, sostenibilidad.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>Casos pr\u00e1cticos de racismo medioambiental (Flint, Cancer Alley).<\/li><li>An\u00e1lisis comparativo de la pol\u00edtica gubernamental (autoritaria frente a democr\u00e1tica).<\/li><li>Historia de EE.UU.: comparaciones de la cultura de consumo.<\/li><\/ul><h2>Teolog\u00eda<\/h2><h3>Plan de estudios actual:<\/h3><ul><li>Doctrina Social Cat\u00f3lica: Cuidado de la Creaci\u00f3n.<\/li><li>Revelaci\u00f3n natural, unidad Laudato Si.<\/li><li>Fe y ciencia, estilos de vida cristianos.<\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>Religiones del mundo: a\u00f1ada el cuidado de la creaci\u00f3n en el islam, el hinduismo y el budismo.<\/li><li>La ecolog\u00eda en el Antiguo y el Nuevo Testamento.<\/li><\/ul><h2>Lenguas del mundo<\/h2><h3>Plan de estudios actual:<\/h3><ul><li><strong>Franc\u00e9s:<\/strong> fast fashion, eco h\u00e1bitos, Les Yeux de Carmen, encuestas residuo cero.<\/li><li><strong>Espa\u00f1ol:<\/strong><ul><li><em>Vertedero Harmonic<\/em>, <em>La isla m\u00e1s peligrosa<\/em>, <em>Los ojos de Carmen<\/em>.<\/li><li>Poes\u00eda y cuentos: Ulibarr\u00ed, Quiroga, Neruda, Garc\u00eda M\u00e1rquez.<\/li><li>Actividades de escritura creativa y artes visuales.<\/li><\/ul><\/li><\/ul><h3>Plan de estudios previsto:<\/h3><ul><li>V\u00eddeos de Dreaming Spanish.<\/li><li>Jardiner\u00eda urbana con MovieTalk.<\/li><li>Explora El Hotel Basura.<\/li><li>Estudie las iniciativas urbanas ecol\u00f3gicas de Par\u00eds.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1039a63 elementor-widget elementor-widget-button\" data-id=\"1039a63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8905cc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f8905cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e183969 e-flex e-con-boxed e-con e-parent\" data-id=\"e183969\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b87b5bc elementor-widget elementor-widget-menu-anchor\" data-id=\"b87b5bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Scipio\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705251f elementor-widget elementor-widget-text-editor\" data-id=\"705251f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Ministerio de Retiros - Scipio, Kansas<br \/><\/strong><strong>Presentado por:  David Simpson<br \/><\/strong><strong>21 de abril de 2025<\/strong><\/p><p><strong>Acciones en el esp\u00edritu de Laudato Si' que ya se han emprendido<\/strong><\/p><ol><li>Invitaci\u00f3n a los participantes en el retiro a vivir con sencillez durante su estancia en la ermita (verano de 2023)<ul><li>Est\u00e9 atento al termostato de la calefacci\u00f3n o del aire acondicionado: utilice ventiladores de techo.<\/li><li>Comidas sencillas<\/li><li>Observar el silencio y la soledad<\/li><li>Intenta observar el esp\u00edritu carmelita contemplativo<\/li><\/ul><\/li><li>Ser conscientes del uso del agua y de la acumulaci\u00f3n de basura (verano de 2023)<\/li><li>Fomentar la oraci\u00f3n diaria (breve) de gratitud por la naturaleza y los dones que Dios nos hace (verano 2023)<\/li><\/ol><ol start=\"4\"><li>Invitar al ejercitante a mantener la ermita y sus alrededores limpios y respetuosos (verano 2023)<\/li><li>Intentar simplificar los materiales utilizados: detergente, jab\u00f3n de lavander\u00eda, papel higi\u00e9nico y toallas de papel, materiales de limpieza (verano de 2023)<\/li><\/ol><p><strong><br \/>Plan de acci\u00f3n<\/strong><\/p><ol><li>Buscar activamente lo que est\u00e1 disponible en la zona para el reciclaje (oto\u00f1o de 2025). En este momento, el reciclaje no est\u00e1 disponible, pero podr\u00eda estarlo con algunos viajes a una localidad diferente que recicle.<\/li><li>Investigar la posibilidad de invitar a los pobres de la zona a utilizar las ermitas con fines de retiro (oto\u00f1o de 2025). Algunas personas no pueden permitirse el estipendio previsto para el uso de la ermita. Ofrecer el don de tal uso peri\u00f3dicamente.<\/li><li>Empezar a utilizar m\u00e1s materiales reciclables, por ejemplo, la toalla de papel (verano de 2025). Una cesta de pa\u00f1os que puedan lavarse y reutilizarse en lugar de la toalla de papel.<\/li><li>Proporcionar bolsas de tela en las ermitas para hacer la compra (verano de 2025). Ayudar a eliminar la pl\u00e9tora de pl\u00e1sticos.<\/li><li>Eliminar los cubiertos desechables (verano de 2025)<\/li><li>Investigar el coste de los paneles solares para las ermitas (Oto\u00f1o 2025 - Invierno 2026)<\/li><\/ol><p><br \/>(La gente de nuestra zona se resiste a los paneles solares comerciales; no deber\u00eda ser un problema, ya que no somos comerciales).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0bbc2b elementor-widget elementor-widget-button\" data-id=\"b0bbc2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d761c6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9d761c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5f90202 e-flex e-con-boxed e-con e-parent\" data-id=\"5f90202\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78b6387 elementor-widget elementor-widget-menu-anchor\" data-id=\"78b6387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"CRESPI\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0444ae0 elementor-widget elementor-widget-text-editor\" data-id=\"0444ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Crespi Carmelite High School<br \/><\/strong><strong>Encino, California<br \/><\/strong><strong>Enviado: 12 de mayo de 2025<\/strong><\/h4><p><strong>Esfuerzos pasados y en curso<\/strong><\/p><p>Crespi ha tenido semanas de impacto para los niveles de grado 9-11 durante a\u00f1os.  El primer a\u00f1o se centr\u00f3 en el medio ambiente y la participaci\u00f3n en actividades: Encino Clean up, Heal the Bay, Planting Tress with Tree People, restauraci\u00f3n de rutas de senderismo, mantenimiento de jardines y campos en varios lugares.<\/p><p>Crespi lleva a\u00f1os reciclando botellas y latas y hace dos a\u00f1os empez\u00f3 a recoger restos de comida en contenedores verdes.  A\u00fan estamos trabajando en ello.  Tenemos Reencles (<a href=\"https:\/\/reencle.co\/?srsltid=AfmBOoreqnkT57olTLyNRYPEMePoGbvYwTt3d8KQ16AF0Tq6wWm7hMhh\">https:\/\/reencle.co\/?srsltid=AfmBOoreqnkT57olTLyNRYPEMePoGbvYwTt3d8KQ16AF0Tq6wWm7hMhh<\/a>) en lugares centrales para el personal.  El proveedor del servicio de comidas utiliza un Reencle muy grande para compostar los residuos de su cafeter\u00eda.  Crespi tiene el mayor Reencle en un campus escolar en Am\u00e9rica del Norte.<\/p><p>Organizar recogidas anuales de residuos tecnol\u00f3gicos en el campus.<\/p><p>2024 La acreditaci\u00f3n WCEA\/WASC incluy\u00f3 un Comit\u00e9 de Iniciativa Verde<\/p><p><strong>El futuro<\/strong><\/p><p>2025 El Comit\u00e9 de la Iniciativa Verde de la WCEA\/WASC seguir\u00e1 elaborando nuestro plan de acci\u00f3n como un documento vivo.<\/p><ul><li>Participaci\u00f3n de toda la comunidad escolar<\/li><li>Utilizar la tierra abonada para proyectos del campus, incluida la entrega de plantas de primer a\u00f1o a la comunidad vecina de Encino.<\/li><li>Realizar auditor\u00edas de final de a\u00f1o para identificar \u00e1reas de mejora.<\/li><li>Elaborar opciones de mejora basadas en los datos recogidos.<\/li><li>Incluir a nuestra empresa de gesti\u00f3n de residuos para proporcionar experiencias de aprendizaje a nuestros estudiantes y miembros de la cohorte STEM.<\/li><li>Formalizar una campa\u00f1a educativa para todos los grupos\/miembros de la Comunidad de Crespi.<\/li><li>Integrar las lecciones de sostenibilidad en todo el plan de estudios<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce46d2d elementor-widget elementor-widget-button\" data-id=\"ce46d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cd3fbd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9cd3fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f0b95f3 e-flex e-con-boxed e-con e-parent\" data-id=\"f0b95f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-577ac6e elementor-widget elementor-widget-menu-anchor\" data-id=\"577ac6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"JCA\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5328f7b elementor-widget elementor-widget-text-editor\" data-id=\"5328f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de Acci\u00f3n Laudato Si' - Presentado el 22 de abril de 2025<br \/><\/strong><strong>Joliet Catholic Academy<br \/><\/strong><strong>Joliet, Illinois<\/strong><\/h4><p><strong><u>Laudato S<\/u><\/strong><strong>i - <\/strong><strong>\"Qui\u00e9nes somos <\/strong><\/p><p><strong>Medio ambiente<\/strong><\/p><ul><li>Programa de reciclaje (estudiantes \/ Mantenimiento)<\/li><li>Club de jardiner\u00eda<\/li><li>Sustituci\u00f3n de luces LED<\/li><li>Santos carmelitas y franciscanos<\/li><li>Ense\u00f1anzas sociales cat\u00f3licas en el plan de estudios \/ tercer y \u00faltimo curso<\/li><li>D\u00eda del Servicio<\/li><li>Reciclaje Re-Store - Club H\u00e1bitat para la Humanidad<\/li><li>Reflexiones semanales de pensamientos carmelitas y franciscanos de Servicio \/ Medio Ambiente<\/li><li>Planificaci\u00f3n estrat\u00e9gica de m\u00e1s espacios verdes utilizables (campa\u00f1a de capital)<\/li><li>Explorar los \"tejados verdes<\/li><li>Exploraci\u00f3n de los h\u00e1bitats de las abejas aut\u00f3ctonas en el campus<\/li><li>Gesti\u00f3n positiva de los terrenos adquiridos<\/li><li>Menos papel y m\u00e1s tecnolog\u00eda<\/li><li>Conscientes de plantar y mantener \u00e1rboles en el campus<\/li><li>Conciencia de utilizar recursos renovables al modernizar las instalaciones del campus<\/li><li>Nuevas estaciones de agua para reducir las botellas de pl\u00e1stico de un solo uso<\/li><li>Director de mantenimiento concienciado con el medio ambiente<\/li><\/ul><p><strong>Servicio a los pobres <\/strong><\/p><ul><li>Programas de servicios escolares<ul><li>D\u00eda del Servicio<\/li><li>Programa de horas de servicio para todos los estudiantes<\/li><li>Alimentar a mis ni\u00f1os hambrientos<\/li><li>Key Club reconocido a nivel nacional<\/li><li>Clubes y organizaciones Proyectos de servicio<\/li><\/ul><\/li><li>Recogida de alimentos<\/li><li>Undy Sunday<\/li><li>Recogida de calzado<\/li><li>Adoptar el modelo de liderazgo de servicio al liderazgo<\/li><\/ul><p><strong>General <\/strong><\/p><ul><li>Conciencia de inversi\u00f3n global<\/li><\/ul><h4>\u00a0<\/h4><h4 style=\"text-align: left;\"><strong>Laudato Si' <br \/><\/strong><strong>Joliet Catholic Academy<br \/><\/strong><strong>Por departamento<\/strong><\/h4><p><strong>Ciencia<\/strong><\/p><ul><li>Las clases de Biolog\u00eda y Biolog\u00eda AP cubren a fondo la Ecolog\u00eda, la diversidad de especies y la importancia de todas las especies para el \u00e9xito del planeta. Se habla de las especies clave y de la biodiversidad a lo largo de los cap\u00edtulos ecol\u00f3gicos.<\/li><li>Debatimos sobre el impacto humano en el planeta y sus recursos, el impacto medioambiental y la sostenibilidad. Compartimos un hogar com\u00fan con todos los seres vivos, y no debemos abusar de \u00e9l ni destruirlo.<\/li><li>Hablamos de la actualidad, de fen\u00f3menos meteorol\u00f3gicos como tornados, inundaciones, huracanes, etc. Las clases cubren el tiempo junto con el espacio y la atm\u00f3sfera.<\/li><li>Hablamos del cambio clim\u00e1tico, el calentamiento global, los efectos invernadero y soluciones \u00fatiles como reciclar, limitar los residuos, conservar los recursos naturales y reducir la contaminaci\u00f3n.<\/li><li>Contamos con clubes de ciencias, de jardiner\u00eda y de medio ambiente para ofrecer debates adicionales. Incluida la construcci\u00f3n de un jard\u00edn de polinizadores y la plantaci\u00f3n de varios \u00e1rboles en el campus.<\/li><li>Intentamos limitar el uso y el desperdicio de papel utilizando OneNote y Teams para distribuir las tareas y no utilizar papel. Tambi\u00e9n tenemos varios laboratorios virtuales que limitan el desperdicio de suministros, productos qu\u00edmicos y papel.<\/li><li>Se anima a los estudiantes a utilizar botellas de agua potable reutilizables, nuevas fuentes de agua potable y a contribuir a limitar el despilfarro de pl\u00e1sticos y otros recursos.<\/li><li>Varios proyectos de clase y presentaciones sobre Ecolog\u00eda y la importancia de salvar el medio ambiente.<\/li><li>22 de abril<sup>nd<\/sup> es el D\u00eda de la Tierra y se reconoce en las clases con concursos de carteles y otros actos. Se habla de la Hora del Planeta para que todo el mundo apague las luces y los aparatos el\u00e9ctricos no esenciales para concienciar sobre los retos medioambientales.<\/li><\/ul><p><strong><br \/>Teolog\u00eda<\/strong><\/p><ul><li>Asignaci\u00f3n de paseo por la naturaleza de teolog\u00eda de primer a\u00f1o.\u00a0<\/li><li>Teolog\u00eda senior- Proyecto sobre presupuesto m\u00ednimo para vivir.\u00a0<\/li><li>Ense\u00f1anza Social Cat\u00f3lica todo el semestre- Seniors- Stewardship\u00a0<\/li><li>Jr sacramentos - sacramentalidad, ver a Dios en la creaci\u00f3n y en los dem\u00e1s\u00a0<\/li><li>Resiliencia y empoderamiento de la comunidad- Moralidad- No estamos limitados a aquello en lo que nacemos.\u00a0<\/li><li>Gracias, cartas,<\/li><li>Obras de misericordia corporales\u00a0<\/li><li>Fomentar el crecimiento espiritual personal dentro de la comunidad espiritual\u00a0<\/li><li>Regar las plantas en el aula\u00a0<\/li><li>Dignidad de todas las personas, independientemente de su condici\u00f3n social, salud o situaci\u00f3n.\u00a0<\/li><li>Estructuras sociales pecaminosas\u00a0<\/li><li>El Gran Parche de Basura del Pac\u00edfico dentro del concepto de estructuras sociales pecaminosas\u00a0<\/li><li>No se permiten m\u00e1s botellas de agua desechables en Kairos\u00a0<\/li><\/ul><p><strong><br \/>Estudios Sociales<\/strong><\/p><ul><li>Curr\u00edculo empresarial: importancia de cada parte del ciclo empresarial y c\u00f3mo est\u00e1n interconectadas a lo largo del proceso -objetivos comunes para todas las partes implicadas<\/li><li>Historia - protestas por los derechos humanos, incluidos Vietnam y los derechos civiles<\/li><li>Intercambio colombino y cambio medioambiental - Las tribus nativas americanas utilizan el medio ambiente para determinar su modo de vida<\/li><li>Avance tecnol\u00f3gico - Revoluci\u00f3n industrial, Guerra Fr\u00eda, d\u00e9cada de 1980<\/li><li>Movimiento Verde durante los a\u00f1os 60\/70 como cambio medioambiental<\/li><li>Historia del mundo - c\u00f3mo hemos llegado hasta aqu\u00ed desde el principio de la historia hasta hoy- cambiante - c\u00f3mo las sociedades utilizaron sus recursos y su entorno para dar forma a su cultura<\/li><li>Gobierno: derechos civiles, enmiendas<\/li><li>Econ- costes impl\u00edcitos de todo lo que haces - Comprar en Shein\/Temu (sitios web de moda r\u00e1pida) y el impacto global.\u00a0<\/li><\/ul><p><strong><br \/>Ingl\u00e9s<\/strong><\/p><p><strong><u>Primer a\u00f1o<\/u><\/strong><\/p><ul><li><strong>Mitolog\u00eda<\/strong>: Conexi\u00f3n de dioses y diosas con las ra\u00edces naturales<\/li><li><strong><em>Matar a un ruise\u00f1or<\/em><\/strong>: Debate sobre el trato y las opiniones de los dem\u00e1s y el entorno que nos rodea<\/li><\/ul><p><strong><u>Segundo a\u00f1o<\/u><\/strong><\/p><ul><li><strong>Relatos breves<\/strong>: Debates sobre el respeto a la naturaleza y el trato a los dem\u00e1s, como en \"El juego m\u00e1s peligroso\", \"Blues Ain't No Mockingbird\", \"El ibis escarlata\", \"La cosecha\", entre otros.<\/li><li><strong>No ficci\u00f3n<\/strong>: Discusi\u00f3n sobre el respeto a la naturaleza y el trato a los dem\u00e1s como se encuentra en (pero no limitado a) - \"Residencia de AD2029\", \"La lavandera\", \"Celebraci\u00f3n de los abuelos\".<\/li><\/ul><p><strong><u>A\u00f1o Junior<\/u><\/strong><\/p><ul><li>An\u00e1lisis de cada obra literaria le\u00edda y conexi\u00f3n con temas de actualidad de la sociedad actual y de nuestras vidas individuales.<\/li><li><strong>Trascendentalismo<\/strong>: Debate sobre el respeto de la naturaleza<\/li><li><strong>Otra bibliograf\u00eda<\/strong>: Discusi\u00f3n sobre el tratamiento de los dem\u00e1s tal y como se encuentra en (pero no limitado a)-Poes\u00eda de Cummings y Auden, <em>Las uvas de la ira<\/em>, <em>De izquierda a derecha<\/em>, <em>El Gran Gatsby<\/em><\/li><li>Libro de texto en l\u00ednea<\/li><\/ul><p><strong><u>\u00daltimo a\u00f1o <\/u><\/strong><\/p><ul><li><strong>17<sup>th<\/sup> &amp; 18<sup>th<\/sup> Siglo<\/strong>: Debate sobre la revoluci\u00f3n cient\u00edfica y c\u00f3mo destruye el medio ambiente<\/li><li><strong>Unidad Romanticismo<\/strong>: Debate sobre la reconexi\u00f3n con la naturaleza y la importancia de Dios en la naturaleza<\/li><li><strong><em>Frankenstein<\/em><\/strong>: Discusi\u00f3n sobre el trato a los dem\u00e1s (el hombre intenta jugar a ser Dios)<\/li><\/ul><p><strong><br \/>Matem\u00e1ticas<\/strong><\/p><ul><li>Decoraci\u00f3n para el aula a largo plazo que no hay que cambiar con frecuencia<\/li><li>Plantas en nuestras habitaciones para promover un aire m\u00e1s limpio<\/li><li>Fomento de los bienes reciclados para la creaci\u00f3n de proyectos con factor de escala<\/li><li>Encender menos luces para ahorrar energ\u00eda<\/li><li>Utilizando nuestras unidades Mitsubishi de forma conservadora<\/li><li>Apagar nuestros proyectos cuando no se utilizan<\/li><li>Permita que los alumnos rellenen las botellas de agua para reducir los residuos pl\u00e1sticos<\/li><li>Crear clases sin libros de texto para que los alumnos no tengan que comprar libros nuevos.<\/li><li>Utilizar libros antiguos para que los alumnos compren nuevos<\/li><li>Tareas sin papel<\/li><li>Recoger l\u00e1pices del suelo para que los utilicen los alumnos que no tengan uno<\/li><li>Reventa de uniformes y armario del decanato<\/li><li>Estaciones para rellenar botellas de agua<\/li><li>Club de jardiner\u00eda<\/li><\/ul><p><strong><br \/>Bellas Artes<\/strong><\/p><p><strong>Artes esc\u00e9nicas<\/strong><\/p><ul><li>Materiales digitalizados para ahorrar papel.<ul><li>Todas las tareas est\u00e1n digitalizadas.<\/li><li>Tambi\u00e9n se digitalizan todos los programas de los conciertos.<\/li><\/ul><\/li><li>Promover la sensibilizaci\u00f3n de las comunidades ind\u00edgenas a trav\u00e9s de la m\u00fasica y los guiones teatrales.<\/li><li>Proyectos pr\u00e1cticos para fomentar la movilidad activa, mental y emocional.<ul><li>Ejemplo: Banda de m\u00fasica y habilidades motrices<\/li><\/ul><\/li><\/ul><p><strong><br \/>Artes visuales<\/strong><\/p><ul><li>Materiales digitalizados para ahorrar papel.<ul><li>Todas las tareas est\u00e1n digitalizadas.<\/li><\/ul><\/li><li>Reciclar y reutilizar todos los materiales para garantizar que no haya residuos al desarrollar los proyectos.<ul><li>Ejemplo: Toda la arcilla se rehidrata para volver a utilizarla.<\/li><\/ul><\/li><li>Proyectos pr\u00e1cticos para fomentar la movilidad activa, mental y emocional.<\/li><li>Los estudiantes de Bellas Artes aprenden que la creatividad no necesita herramientas especiales: la creaci\u00f3n art\u00edstica est\u00e1 al alcance de todos.<\/li><li>Los objetos encontrados se convierten en peque\u00f1as esculturas y texturas para la arcilla, los papeles y tableros reciclados se convierten en elementos de dise\u00f1o para esculturas en relieve, los restos de metal e hilo se combinan en ensamblajes<\/li><\/ul><p><strong><br \/>Educaci\u00f3n F\u00edsica\/Salud<\/strong><\/p><ul><li>Unidad sobre salud social, c\u00f3mo respetarse mutuamente y crear interconectividad a trav\u00e9s de diversos or\u00edgenes.<\/li><li>Unidad sobre dieta, nutrici\u00f3n y proporciones para promover un estilo de vida saludable.<\/li><li>Unidades de c\u00f3mo planificar y ejecutar la movilidad activa para garantizar un estilo de vida largo y saludable.<\/li><li>Las tareas de salud est\u00e1n digitalizadas. El libro de salud est\u00e1 en l\u00ednea y las tareas tambi\u00e9n se completan en l\u00ednea.<\/li><\/ul><p><strong><br \/>Lenguas del mundo<\/strong><\/p><ul><li>Interconexi\u00f3n: Todo en el mundo est\u00e1 conectado, y el grito de la Tierra est\u00e1 entrelazado con el grito de los pobres.<\/li><\/ul><ul><li>Se anima a los estudiantes a reflexionar y aprender sobre la construcci\u00f3n de una comunidad m\u00e1s cercana.<\/li><\/ul><ul><li style=\"list-style-type: none;\"><ul><li>Temas de la unidad que aportan vocabulario, comparaciones culturales y conversaci\u00f3n abierta al voluntariado en su propio entorno y en el mundo hispano y franc\u00f3fono.<\/li><li>Proyectos en los que los estudiantes se sumergen en lo que su comunidad puede ofrecer a la poblaci\u00f3n desfavorecida.<\/li><li>Crear carteles y folletos que puedan utilizarse para promocionar esas ayudas.<\/li><li>Comprender otras culturas a trav\u00e9s de lecturas y literatura.<\/li><\/ul><\/li><\/ul><ul><li>Comuni\u00f3n universal: Toda la creaci\u00f3n forma parte de una familia universal, creada por un solo Padre.<\/li><\/ul><ul><li>Para fomentar el sentido de comunidad, los estudiantes participan en actividades de revisi\u00f3n entre iguales y de trabajo en parejas\/peque\u00f1os grupos para negociar el significado del lenguaje\/contenido,<\/li><li>Se anima a los estudiantes a buscar orientaci\u00f3n acad\u00e9mica de otros estudiantes, especialmente de aquellos con los que no est\u00e9n familiarizados.\u00a0<\/li><li>Trabajar juntos en clase y fuera de ella mediante proyectos y otras actividades.<\/li><\/ul><ul><li>Destino com\u00fan de los bienes: La Tierra es una herencia compartida, y sus frutos est\u00e1n destinados a beneficiar a todos.<\/li><\/ul><ul><li>Se anima a los alumnos a proteger el mundo y a aprender sobre concienciaci\u00f3n social.<ul><li>Unidad basada en la protecci\u00f3n del futuro de nuestro planeta y las preocupaciones medioambientales actuales.\u00a0<\/li><li>Dar a los alumnos el vocabulario necesario para preguntar sobre el medio ambiente y pronunciarse a favor de la protecci\u00f3n de la Tierra para las generaciones futuras.<\/li><li>Proyectos que ayudan a llevar energ\u00eda respetuosa con el medio ambiente a otros pa\u00edses.<\/li><\/ul><\/li><\/ul><ul><li>Cr\u00edtica al paradigma tecnocr\u00e1tico: El enfoque dominante en la tecnolog\u00eda y el beneficio ha conducido a la degradaci\u00f3n medioambiental y a la desigualdad social.<\/li><\/ul><ul><li>Se anima a los alumnos a utilizar la tecnolog\u00eda s\u00f3lo cuando sea necesario y con integridad:<ul><li>Sitios como los motores de b\u00fasqueda Google\/Bing y OpenAI no son accesibles durante las horas de clase.<\/li><li>Las tareas de los estudiantes alternan entre l\u00e1piz\/papel y formato electr\u00f3nico,<\/li><li>Se recomienda a los estudiantes que utilicen diccionarios impresos.<\/li><li>El instructor demuestra c\u00f3mo utilizar la tecnolog\u00eda de forma consciente y honesta (por ejemplo, utilizando palabras clave para buscar informaci\u00f3n).<\/li><\/ul><\/li><\/ul><ul><li>Llamamiento a una revoluci\u00f3n cultural: Es necesario un cambio de mentalidad, pol\u00edticas y estilos de vida para abordar la crisis ecol\u00f3gica.<\/li><\/ul><ul><li>Se espera que los alumnos se abstengan de utilizar tel\u00e9fonos m\u00f3viles\/dispositivos de escucha para practicar la atenci\u00f3n plena (estar en el momento\/interactuar con los que est\u00e1n en su presencia),<\/li><li>El instructor comparte herramientas para maximizar el rendimiento de los dispositivos escolares reduciendo el consumo de energ\u00eda (por ejemplo, reducir el n\u00famero de aplicaciones que se ejecutan en segundo plano, ser consciente del n\u00famero de pesta\u00f1as abiertas en el navegador web).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79169f7 elementor-widget elementor-widget-button\" data-id=\"79169f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e6c0d9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9e6c0d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f35344 elementor-widget elementor-widget-menu-anchor\" data-id=\"6f35344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"MCHS\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1448884 elementor-widget elementor-widget-heading\" data-id=\"1448884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informe Laudato Si\nColegio Mount Carmel\nChicago, IL\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdf39a3 elementor-widget elementor-widget-text-editor\" data-id=\"fdf39a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>25 de julio de 2025<\/strong><\/p><p><strong>De: Brendan Conroy, Presidente<\/strong><\/p><p><strong><u>El Monte Carmelo y \"El cuidado de nuestra casa com\u00fan\"<\/u><\/strong><\/p><p><strong>Actividades actuales:<\/strong> Podr\u00edamos hacerlo mucho mejor de maneras peque\u00f1as y sencillas, tanto individualmente como en conjunto.  A continuaci\u00f3n se presentan \u00e1reas que reflejan lo que se est\u00e1 haciendo y lo que podr\u00eda hacerse mejor.<\/p><p><em>Energ\u00edas renovables<\/em>:  Este es el mayor logro singular del Monte Carmelo en el esp\u00edritu de <em>Laudato Si.\u00a0 <\/em>Gracias a la estrecha colaboraci\u00f3n con nuestro asesor energ\u00e9tico, hemos conseguido lo siguiente:<\/p><ul><li>Sustituir gratuitamente tres tejados envejecidos y con goteras, lo que supone un ahorro a valores actuales de unos $350.000.<\/li><li>Llegar a un acuerdo para instalar paneles solares mediante el arrendamiento, durante los pr\u00f3ximos 25 a\u00f1os, de los tejados de nuestros dos espacios m\u00e1s grandes: el Convocation Center (gimnasio y Commons) y el Edificio Principal, para suministrar la electricidad que alimenta nuestro campus.<\/li><li>Reducir nuestra dependencia de la red el\u00e9ctrica.<\/li><li>Permitirnos pagar la electricidad a una tarifa m\u00e1s baja y constante que, seg\u00fan las previsiones, ahorrar\u00e1 a Mount Carmel alrededor de $750.000 en ese mismo periodo.<\/li><li>Gestiona el riesgo al no ser propietario de los paneles solares. Por lo tanto, el coste de las reparaciones por desgaste normal y cualquier sustituci\u00f3n habitual de los paneles no recae en Mount Carmel.<\/li><li>Obtener garant\u00edas de que los cambios en el apoyo federal a la energ\u00eda solar y otras energ\u00edas renovables no nos afectar\u00e1n. Se trata de una preocupaci\u00f3n a largo plazo en caso de que disminuya el apoyo de los inversores y del Estado de Illinois.<\/li><\/ul><p><em>Reducci\u00f3n y reciclaje de recursos<\/em>:  Nuestro historial es desigual y podr\u00eda ser mucho m\u00e1s s\u00f3lido.  He aqu\u00ed algunos puntos fuertes y \u00e1reas de crecimiento:<\/p><ul><li>Impresoras y fotocopiadoras: Muy pocas oficinas individuales tienen impresoras, y hay tres fotocopiadoras conocidas en la escuela, ya que hemos cambiado significativamente de ser una instituci\u00f3n tradicional basada en papel a formatos electr\u00f3nicos.<\/li><li>Ense\u00f1anza y aprendizaje: Los profesores pueden utilizar papel, pero un porcentaje significativo de tareas, folletos y ex\u00e1menes son electr\u00f3nicos. Aunque esto es alentador desde el punto de vista medioambiental, el aprendizaje sigue siendo m\u00e1s eficaz en el formato tradicional de papel.<\/li><li>Reuniones de gobierno: Actualmente ofrecemos paquetes impresos para nuestros miembros de la Junta Directiva de la Escuela, la Junta de la Fundaci\u00f3n Educativa Mount Carmel y el Comit\u00e9 de Finanzas, adem\u00e1s de enviar los paquetes electr\u00f3nicamente antes de las reuniones. Voy a solicitar a nuestro actual Presidente de la Junta, Presidente de la Fundaci\u00f3n y Presidente del Comit\u00e9 de Finanzas que ofrezcamos paquetes impresos s\u00f3lo bajo petici\u00f3n.<\/li><\/ul><p>Adem\u00e1s, seguimos dependiendo en gran medida de platos, utensilios y envases de bebidas de un solo uso para estas reuniones, as\u00ed como para las reuniones del profesorado.<\/p><ul><li>Cafeter\u00eda: Nuestro proveedor de servicios de cafeter\u00eda es un proveedor contratado.  Aunque estamos satisfechos con la calidad del servicio y la comida que proporcionan, hay \u00e1reas de preocupaci\u00f3n, incluyendo:<ul><li>Coste<\/li><li>Residuos alimentarios<\/li><li>Papel, pl\u00e1sticos y espuma de poliestireno de un solo uso<\/li><li>Eliminaci\u00f3n de botellas y latas de bebidas en lugar de reciclarlas<\/li><\/ul><\/li><\/ul><p><em>NOTA: Incluyo aqu\u00ed el coste para indicar que nuestros alumnos y familias ya pagan un alto precio por el desayuno y el almuerzo, y sospecho que esos costes seguir\u00e1n aumentando.  Es una elecci\u00f3n, pero tambi\u00e9n una carga econ\u00f3mica, para nuestras familias tal y como est\u00e1n las cosas.  El coste ser\u00e1 un factor a la hora de determinar si imponemos requisitos de sostenibilidad a nuestro proveedor de servicios alimentarios.<\/em><\/p><ul><li>Correo y marketing: Durante muchos a\u00f1os hemos realizado la mayor parte de nuestro marketing y comunicaciones electr\u00f3nicamente, pero seguimos imprimiendo y enviando o distribuyendo copias en papel limitadas de piezas seleccionadas. La mentalidad del Departamento de Desarrollo es examinar c\u00f3mo podemos comunicarnos de forma eficiente al tiempo que reducimos costes.  Se lo agradezco y me gustar\u00eda que a\u00f1adi\u00e9ramos consideraciones ecol\u00f3gicas a la reflexi\u00f3n.<\/li><li>D\u00edas de partido y otros eventos: Estos eventos pueden recibir hasta 4.000 visitantes en nuestro campus durante una tarde, y no debemos subestimar el impacto de los residuos que se producen y se tiran en lugar de reciclarse.<\/li><li>Paisajismo: Nuestro campus es un lugar extraordinariamente bello, y nuestros antiguos alumnos, donantes y visitantes lo aprecian.  Sobre todo, nuestros estudiantes se lo merecen. Cualquier debate sobre el cuidado de nuestra casa com\u00fan debe incluir un examen de nuestro impacto en el medio ambiente, incluidos el riego, la vegetaci\u00f3n, los fertilizantes, los herbicidas y otras pr\u00e1cticas.  Esto incluye lo que una vez fue un jard\u00edn en el tejado.<\/li><\/ul><p><strong>\u00a0<\/strong><\/p><p><strong>Mirando hacia el futuro:\u00a0 <\/strong>A continuaci\u00f3n se exponen algunas ideas que constituyen un primer borrador de lo que podr\u00edamos plasmar en un plan que nos gu\u00ede para vivir m\u00e1s de cerca el esp\u00edritu de <em>Laudato Si.<\/em><\/p><ul><li>Empezar con algo peque\u00f1o y definitivo <em>sostenible<\/em> pasos, y no dejes que el deseo de la acci\u00f3n perfecta obstaculice la realizaci\u00f3n de una acci\u00f3n meramente buena. Vincular el prop\u00f3sito a nuestra misi\u00f3n: \"Celo por Dios, por la vida, por aprender\". Estar abiertos a la acci\u00f3n del Esp\u00edritu Santo en nuestros debates y esfuerzos.<\/li><li>Comprometer los corazones, las mentes y las manos de los estudiantes, el profesorado, el personal y los padres. Formar un grupo b\u00e1sico que no s\u00f3lo est\u00e9 interesado, sino dispuesto a ayudar.<\/li><li>Crear un fondo de dotaci\u00f3n para <em>Laudato Si<\/em> iniciativas, y facultar al grupo central para que recomiende o determine el mejor destino para los fondos anuales que se generen. Nuestra dotaci\u00f3n da 5% al a\u00f1o, por lo que un Fondo Laudato Si de $100.000 ofrecer\u00eda $5.000 anuales para proyectos de sostenibilidad.<\/li><li>Quiz\u00e1 ofrecer un curso de filosof\u00eda o religi\u00f3n de alto nivel sobre <em>Laudato Si, <\/em>o un curso con otros componentes que incluya un examen en profundidad de<em> Laudato Si.<\/em><\/li><li>Explorar lo que se est\u00e1 haciendo con \u00e9xito en otros institutos.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be89e99 elementor-widget elementor-widget-button\" data-id=\"be89e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02ebb92 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"02ebb92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-42aa7c7 e-flex e-con-boxed e-con e-parent\" data-id=\"42aa7c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-767cb7e elementor-widget elementor-widget-menu-anchor\" data-id=\"767cb7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Salpointe\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca4627 elementor-widget elementor-widget-image\" data-id=\"3ca4627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"514\" height=\"385\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture5.jpg\" class=\"attachment-large size-large wp-image-20260\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture5.jpg 514w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture5-300x225.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture5-16x12.jpg 16w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0c8d5 elementor-widget elementor-widget-text-editor\" data-id=\"1b0c8d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><strong>Salpointe Catholic High School<\/strong><\/h2><h3 style=\"text-align: center;\">Plan de Acci\u00f3n para la Sostenibilidad 2025-2030<\/h3><p style=\"text-align: center;\">Resumen ejecutivo<br \/>Preparado para la Provincia Carmelita<br \/>Creado por el Comit\u00e9 Salpointe para el Cuidado de la Creaci\u00f3n<\/p><h2>Visi\u00f3n general<\/h2><p>Salpointe Catholic High School se fund\u00f3 en 1950 con una matr\u00edcula inicial de 100 alumnos. Hoy, setenta y cinco a\u00f1os m\u00e1s tarde, la poblaci\u00f3n estudiantil se ha multiplicado por m\u00e1s de doce y el campus ha pasado de ser un solo edificio a una instalaci\u00f3n compleja que consta de diez edificios, una pista y m\u00faltiples campos de atletismo. Con la publicaci\u00f3n del Papa Francisco\u02bc <em>Laudato S\u00ed<\/em> enc\u00edclica en 2015, el desarrollo del campus adquiri\u00f3 un nuevo enfoque, creando un campus que modelara el cuidado de la creaci\u00f3n en todos los aspectos. Salpointe estableci\u00f3 r\u00e1pidamente su <em>Comit\u00e9 para el Cuidado de la Creaci\u00f3n, <\/em>con el objetivo de fomentar la gesti\u00f3n medioambiental en el desarrollo curricular, incorporar la sostenibilidad en las infraestructuras y mejoras del campus y promover la justicia social y medioambiental en el servicio, el desarrollo espiritual y la programaci\u00f3n del campus. <em>. <\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6b02f37 e-grid e-con-boxed e-con e-parent\" data-id=\"6b02f37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-242db97 elementor-widget elementor-widget-image\" data-id=\"242db97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"314\" height=\"313\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture1.jpg\" class=\"attachment-large size-large wp-image-20256\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture1.jpg 314w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture1-300x300.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture1-150x150.jpg 150w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture1-12x12.jpg 12w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260c226 elementor-widget elementor-widget-image\" data-id=\"260c226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"296\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture2-300x296.png\" class=\"attachment-medium size-medium wp-image-20257\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture2-300x296.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture2-768x757.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture2-12x12.png 12w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture2.png 993w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-36689af e-grid e-con-boxed e-con e-parent\" data-id=\"36689af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0a50e0 elementor-widget elementor-widget-text-editor\" data-id=\"e0a50e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Salpointe, hacia 1956<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8495d5 elementor-widget elementor-widget-text-editor\" data-id=\"e8495d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Salpointe, 2023, tras el incendio de julio<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e4248d1 e-flex e-con-boxed e-con e-parent\" data-id=\"e4248d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-349a93e elementor-widget elementor-widget-text-editor\" data-id=\"349a93e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><em>Logros hasta la fecha <\/em><\/strong><\/p><table width=\"668\"><tbody><tr><td width=\"77\"><p><strong>A\u00f1o <\/strong><\/p><\/td><td width=\"591\"><p><strong>Hechos relevantes en relaci\u00f3n con Laudato Si y la sostenibilidad <\/strong><\/p><\/td><\/tr><tr><td width=\"77\"><p>2015<\/p><\/td><td width=\"591\"><p>Creaci\u00f3n del Comit\u00e9 Laudato S\u00ed<\/p><p>Creaci\u00f3n del plan de estudios Laudato Si financiado por la ONG Carmelita y la Hna. Jane Remson,<\/p><p>O.Carm. y la Fundaci\u00f3n Cantando por el Cambio de Jimmy Buffet<\/p><p>Creaci\u00f3n del Jard\u00edn STEM<\/p><p>Salpointe instala paneles solares fotovoltaicos en el Patio STEM<\/p><p>Los carmelitas instalan paneles solares fotovoltaicos en el Priorato de Nuestra Se\u00f1ora del Carmen<\/p><p>Salpointe crea una cuenca de captaci\u00f3n en el lado norte del campus para devolver el agua al acu\u00edfero local.<\/p><p>Las nuevas construcciones actuales y futuras utilizan secadores de manos en lugar de toallas de papel, grifos de agua autom\u00e1ticos, iluminaci\u00f3n autom\u00e1tica, persianas y ventanas con alto factor R.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2016<\/p><\/td><td width=\"591\"><p>Continuaci\u00f3n del trabajo sobre el plan de estudios de Laudato Si; documento impreso en ingl\u00e9s y espa\u00f1ol.<\/p><p>Salpointe adopta el uso de platos compostables para el servicio de comidas.<\/p><p>Salpointe inicia el reciclaje en las aulas. Los estudiantes de teolog\u00eda de segundo a\u00f1o son responsables de la recogida de los contenedores de reciclaje. No estoy seguro de cu\u00e1ndo empez\u00f3 esto.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2017<\/p><\/td><td width=\"591\"><p>Plan de estudios Laudato Si Presentado por Kay Sullivan y Kate McGarey Vasey en el <em>Segundo Congreso de Escuelas Carmelitas<\/em>Roma, 5-10 de noviembre de 2017. Documento compartido con m\u00e1s de 40 escuelas carmelitas de secundaria de todo el mundo.<\/p><p>Salpointe instal\u00f3 paneles solares en el tejado del gimnasio de la familia Kalil.<\/p><p>Salpointe renueva el Patio de la Bondad de los estudiantes de segundo a\u00f1o\/Fr. John Malley, O.Carm., con cuencas de captaci\u00f3n y formato xeriscape, dando prioridad a la conservaci\u00f3n del agua mediante el uso de plantas tolerantes a la sequ\u00eda y t\u00e9cnicas de riego eficientes.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2018<\/p><\/td><td width=\"591\"><p>Kate McGarey Vasey asisti\u00f3 a la conferencia \"Laudato Si\u02bc: Respondiendo a la visi\u00f3n con una renovada<\/p><p>Curriculum in Catholic High Schools,\" Archdiocese of New Orleans Leadership<\/p><p>Conferencia, 10 de octubre de 2018, en nombre de Salpointe y de la Orden Carmelita.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2019<\/p><\/td><td width=\"591\"><p>Los distintos departamentos crean objetivos de sostenibilidad<\/p><p>Kate McGarey Vasey present\u00f3 la obra \"Laudato Si\u02bc High School\", creada por Salpointe.<\/p><p>Curriculum\", en \"Laudato Si\u02bc and the U.S. Catholic Church\", Catholic Climate Covenant y Creighton University en junio de 2019.<\/p><\/td><\/tr><\/tbody><\/table><table width=\"668\"><tbody><tr><td width=\"77\"><p>2020<\/p><\/td><td width=\"591\"><p>Salpointe inicia la marca Green Lancer para comunicarse con el alumnado y desarrollar una cultura de concienciaci\u00f3n sobre Laudato Si en el campus.<\/p><p>Salpointe acoge una miniconferencia de Laudato Si Showcase con participantes procedentes de 5 colegios carmelitas, y administradores de otros siete institutos cat\u00f3licos. Escuelas jesuitas y otras escuelas cat\u00f3licas.<\/p><p>Salpointe cambia la modalidad de horas de servicio de Impact Day a XVol.<\/p><p>La pandemia de COVID lleva a instalar sistemas de ventilaci\u00f3n y filtraci\u00f3n de alto rendimiento.\u00a0<\/p><p>Salpointe invierte en el desarrollo profesional de sus miembros de Cuidado de la Creaci\u00f3n enviando a un representante a la conferencia de Escuelas Verdes para conectar con la comunidad m\u00e1s amplia de innovadores de campus verdes del pa\u00eds. Esta pr\u00e1ctica contin\u00faa.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2021<\/p><\/td><td width=\"591\"><p>Salpointe pone en marcha un comit\u00e9 para formular una declaraci\u00f3n de reconocimiento de la tierra que reconozca a los administradores ind\u00edgenas hist\u00f3ricos de la tierra que ahora habita Salpointe.<\/p><p>Salpointe se desprende de su cartera no filtrada e invierte en el FEG Catholic Values Composite, que consiste en carteras institucionales totalmente discrecionales (OCIO) que incluyen el cribado seg\u00fan las directrices establecidas por la USCCB.<\/p><p>Salpointe inicia los retos de la clase m\u00e1s ecol\u00f3gica para invitar a los alumnos a participar en pr\u00e1cticas respetuosas con el medio ambiente basadas en las tres erres: reducir, reutilizar y reciclar.<\/p><p>Salpointe convoca anualmente el Premio al Cuidado de la Creaci\u00f3n, que se otorgar\u00e1 a un alumno cada a\u00f1o en reconocimiento a sus destacados esfuerzos por promover la justicia medioambiental, abogar por un cambio de estilo de vida sostenible e integrar la espiritualidad consciente en su relaci\u00f3n con la naturaleza.\u00a0<\/p><p>Salpointe inicia la Semana de la Tierra, una celebraci\u00f3n de una semana de duraci\u00f3n con actividades estudiantiles, temas medioambientales en masa, centrada en el D\u00eda de la Tierra.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2022<\/p><\/td><td width=\"591\"><p>Salpointe utiliza productos de limpieza respetuosos con el medio ambiente.<\/p><p>Salpointe alinea la Semana de la Tierra con la Temporada de la Creaci\u00f3n y la celebraci\u00f3n de San Francisco de As\u00eds.<\/p><p>Salpointe adopta una campa\u00f1a para aumentar los esfuerzos de compostaje en Foundation Hall (durante el almuerzo). Los estudiantes de teolog\u00eda de segundo a\u00f1o son responsables de mover los cubos de compost al contenedor de compost en el jard\u00edn STEM.\u00a0<\/p><p>Tres miembros del comit\u00e9 Cuidado de la Creaci\u00f3n participan en la conferencia Escuelas Verdes.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2023<\/p><\/td><td width=\"591\"><p>El Club de la Tierra desarrolla un sistema de compostaje para la cercana Escuela Primaria Lineweaver<\/p><p>Salpointe instala luces LED en todas las aulas, el gimnasio y el Alumni Hall.<\/p><p>Salpointe celebra la primera campa\u00f1a anual de reciclaje de residuos electr\u00f3nicos, pintura y pilas.<\/p><p>Salpointe invita al anciano Jerry Carlyle del Distrito de San Xavier de los Tohono<\/p><p>O\u02bcodham Nation para dirigir un c\u00edrculo de oraci\u00f3n en todo el campus en conmemoraci\u00f3n del D\u00eda de la Tierra.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2024<\/p><\/td><td width=\"591\"><p>Los alumnos del Club de la Tierra empiezan a colaborar como voluntarios con ONG medioambientales locales en la eliminaci\u00f3n de especies invasoras, realizando estudios de las poblaciones de castores, y hacen excursiones bimensuales en reservas naturales.\u00a0<\/p><p>Salpointe pone en marcha una iniciativa de compostaje.<\/p><p>Salpointe ampl\u00eda la campa\u00f1a de reciclaje para incluir la recogida de alimentos, mantas, toallas y s\u00e1banas para refugios de animales.<\/p><\/td><\/tr><tr><td width=\"77\"><p>2025<\/p><\/td><td width=\"591\"><p>Kino Teens visita el refugio de Nogales, M\u00e9xico, con la Iniciativa Fronteriza de Kino.<\/p><p>Salpointe empieza a eliminar las pajitas de pl\u00e1stico de la cafeter\u00eda.<\/p><p>Estudiantes de ingenier\u00eda dise\u00f1an un cargador solar para bicicletas el\u00e9ctricas y tel\u00e9fonos m\u00f3viles.<\/p><p>En los objetivos de la WCEA, Salpointe se compromete a ampliar la participaci\u00f3n de los alumnos en programas medioambientales que los expongan a diferentes necesidades y oportunidades para comprometerse con el medio ambiente.<\/p><p>Salpointe inicia un proyecto de Viaje de Cuaresma Laudato Si con estudiantes de Biolog\u00eda Ambiental de Honores, para forjar relaciones m\u00e1s fuertes y significativas entre el medio ambiente y la comunidad estudiantil.<\/p><p>Los estudiantes de Biolog\u00eda Ambiental participan en el D\u00eda del Medio Ambiente en el Capitolio del estado de Arizona para reunirse con representantes y defender iniciativas medioambientales.<\/p><\/td><\/tr><\/tbody><\/table><p><em>Nuestra visi\u00f3n de futuro <\/em><\/p><p><strong>Desarrollaremos y aplicaremos un plan completo de sostenibilidad para Salpointe, que incluir\u00e1 objetivos y metas mensurables para muchos proyectos. Este documento m\u00e1s detallado se crear\u00e1 en una sesi\u00f3n del 16 de junio convocada expl\u00edcitamente para tal fin. La siguiente tabla muestra uno o dos puntos destacados de cada uno de los siete objetivos compartidos por la Provincia Carmelita. Los puntos en verde tienen actualmente un calendario y objetivos mensurables.<\/strong><\/p><table width=\"653\"><tbody><tr><td width=\"653\"><p><strong><em>Respuesta al clamor de la Tierra<\/em><\/strong>. <em>Hacer frente a la contaminaci\u00f3n, la p\u00e9rdida de biodiversidad y el cambio clim\u00e1tico y promover la sostenibilidad ecol\u00f3gica. <\/em><\/p><p>Salpointe est\u00e1 explorando activamente la adici\u00f3n de paneles solares sobre el lote QB Club y el lote de la facultad \/ personal.<\/p><p>Llevaremos a cabo auditor\u00edas peri\u00f3dicas para evaluar el impacto medioambiental de la escuela e identificar \u00e1reas de mejora.<\/p><p>Crearemos un jard\u00edn de polinizadores cerca de nuestro gimnasio y plantaremos especies resistentes a la sequ\u00eda cerca de nuestra entrada de Cherry Street a partir de finales de abril y durante los primeros meses del pr\u00f3ximo semestre.<\/p><\/td><\/tr><tr><td width=\"653\"><p><strong><em>Respuesta al clamor de los pobres<\/em><\/strong>. <em>Promover la justicia econ\u00f3mica, el desarrollo sostenible y una transici\u00f3n justa. <\/em><\/p><p>Salpointe continuar\u00e1 su estrecha asociaci\u00f3n con la Iniciativa Fronteriza Kino, Casas Alitas, Covenant House y otras organizaciones similares para abordar el bienestar de los inmigrantes.<\/p><p>El 24 de abril, la Sociedad de Honor Hispana organizar\u00e1 un acto abierto a toda la escuela para <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">tejer<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">para dormir<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">alfombrillas<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">de<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">pl\u00e1stico<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=5JNe-hce0sY\">bolsas<\/a> para donar a los necesitados.<\/p><p>Victoria Dunk seguir\u00e1 exigiendo a sus alumnos de empresariales que creen proyectos empresariales sostenibles como componente principal de su nota.\u00a0<\/p><\/td><\/tr><tr><td width=\"653\"><p><strong><em>Econom\u00eda ecol\u00f3gica.<\/em><\/strong> <em>Promover un desarrollo econ\u00f3mico sostenible desde el punto de vista medioambiental. <\/em><\/p><p>Investigaremos la posibilidad de disponer de un fondo ESG para nuestros planes de jubilaci\u00f3n antes de que finalice el curso escolar.<\/p><\/td><\/tr><tr><td width=\"653\"><p><strong><em>Adopci\u00f3n de estilos de vida sostenibles.<\/em><\/strong><em> Vivir de forma consciente del impacto de nuestras acciones en los dem\u00e1s y en la Tierra. <\/em><\/p><p>Salpointe continuar\u00e1 coordinando y apoyando el proyecto Tierra, orientado a la sostenibilidad y dirigido por los estudiantes.<\/p><p>Club, fomentar eventos en todo el campus a trav\u00e9s de la coordinaci\u00f3n con STUCO (Consejo de Estudiantes), y trabajar con el Coordinador de Bienestar de Salpointe para implementar experiencias ambientales como parte del bienestar de los estudiantes.\u00a0<\/p><p>Salpointe llevar\u00e1 a cabo una campa\u00f1a contra el sedentarismo el D\u00eda de la Tierra y realizar\u00e1 un estudio de investigaci\u00f3n para evaluar el efecto de la campa\u00f1a comparando los resultados con la informaci\u00f3n de referencia obtenida previamente.<\/p><\/td><\/tr><tr><td width=\"653\">\u00a0<\/td><\/tr><tr><td width=\"653\"><p><strong><em>Educaci\u00f3n ecol\u00f3gica<\/em><\/strong>. <em>Replantear y redise\u00f1ar los planes de estudio y promover una educaci\u00f3n para un futuro sostenible para todos. <\/em><\/p><p>Desarrollaremos una clase de Liderazgo en Justicia Ecol\u00f3gica que establecer\u00e1 la agenda y las direcciones de todas las iniciativas de Cuidado de la Creaci\u00f3n en el campus.<\/p><p>Steven Weed ha propuesto una asignatura optativa titulada \"Econom\u00eda, justicia medioambiental y futuros sostenibles\", que est\u00e1 siendo revisada por Dennis Kalob.<\/p><p>Desarrollaremos y dirigiremos excursiones centradas en la educaci\u00f3n medioambiental en cooperaci\u00f3n con diversos miembros del profesorado.<\/p><p>El D\u00eda de la Tierra habr\u00e1 un concurso para identificar las llamadas y fotos de aves locales.<\/p><\/td><\/tr><tr><td width=\"653\"><p><strong><em>Espiritualidad ecol\u00f3gica<\/em><\/strong>. <em>Abrazar una conversi\u00f3n ecol\u00f3gica que reconozca a Dios en todas las cosas. <\/em><\/p><p>El Comit\u00e9 para el Cuidado de la Creaci\u00f3n trabajar\u00e1 con los hermanos carmelitas y los profesores de teolog\u00eda para desarrollar actividades.<\/p><\/td><\/tr><tr><td width=\"653\"><p><strong><em>Resiliencia y capacitaci\u00f3n de la comunidad<\/em><\/strong>. <em>Prever un camino sinodal de compromiso comunitario y acci\u00f3n participativa y construir una cultura del encuentro. <\/em><\/p><p>Fomentaremos las asociaciones con organizaciones medioambientales, empresas y organismos p\u00fablicos locales para potenciar los esfuerzos de sostenibilidad.<\/p><p>Una tienda local de bicicletas acoger\u00e1 un taller de mec\u00e1nica de bicicletas en oto\u00f1o de 2025.\u00a0<\/p><\/td><\/tr><\/tbody><\/table><p>Para llevar a cabo los objetivos anteriores, colaboraremos con la administraci\u00f3n, el profesorado y las organizaciones estudiantiles para integrar los principios de sostenibilidad en las operaciones, pol\u00edticas y pr\u00e1cticas de la escuela. Adem\u00e1s, investigaremos y recomendaremos nuevas pr\u00e1cticas y tecnolog\u00edas sostenibles a medida que se desarrollen.<\/p><p>Adem\u00e1s, trabajaremos con los profesores para incorporar los conceptos y pr\u00e1cticas de Laudato Si en el plan de estudios de las distintas asignaturas.<\/p><p><strong>NOTA: Este plan es s\u00f3lo el comienzo de un proceso m\u00e1s intensivo que culminar\u00e1 con la elaboraci\u00f3n de un plan completo en junio de 2025.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a61a84 elementor-widget elementor-widget-button\" data-id=\"5a61a84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a0d563 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6a0d563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9423aef elementor-widget elementor-widget-menu-anchor\" data-id=\"9423aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"OLMCDarien\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2faf6d elementor-widget elementor-widget-heading\" data-id=\"a2faf6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra Se\u00f1ora del Monte Carmelo, Darien, IL\t<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1c16ff elementor-widget elementor-widget-text-editor\" data-id=\"e1c16ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>23 de septiembre de 2025<\/strong><\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Acontecimientos pasados <\/strong><\/p><p>Campa\u00f1a Cuaresmal de Ayuno de Carbono (centrada en las ER para ayudar a difundir el mensaje entre los j\u00f3venes feligreses e influir en las familias).<\/p><p>Sustituir el pl\u00e1stico por opciones ecol\u00f3gicas en las propias necesidades cotidianas.<\/p><p>Campa\u00f1a Reducir, Reutilizar, Reciclar (con temas semanales durante todo el verano). Centrada en el agua, la reducci\u00f3n de pl\u00e1sticos y el consumo personal.<\/p><p>Sustituci\u00f3n de cubiertos y vasos en los actos de la Iglesia por opciones compostables (en curso).<\/p><p>Voluntariado en limpiezas de primavera y oto\u00f1o en eventos locales.<\/p><p>Apoyo al huerto parroquial mediante la labranza, el acolchado y el riego (el huerto complementa los productos para el banco de alimentos de la parroquia OLMC).<\/p><p>Utilizar productos de limpieza saludables en lugar de productos qu\u00edmicos agresivos.<\/p><p>Recetas de limpiadores caseros con ingredientes naturales compartidos con los feligreses - recetas, productos de limpieza, productos de papel (limpiadores dom\u00e9sticos).<\/p><p>Proporcionar cubos con productos de limpieza caseros a los beneficiarios del banco de alimentos OLMC junto con ideas sobre c\u00f3mo hacer sus propios productos de limpieza seguros en casa.<\/p><p>Celebraciones anuales del D\u00eda de la Tierra.<\/p><p>Charla sobre jardiner\u00eda aut\u00f3ctona y sus beneficios.<\/p><p>Proyecci\u00f3n de la pel\u00edcula \"Ahora todos somos de pl\u00e1stico\", que cont\u00f3 con una nutrida asistencia. A continuaci\u00f3n hubo un debate con los asistentes.<\/p><p>Muchos de nuestros eventos tienen un alcance para el programa OLMC Darien Religious Ed para aumentar la conciencia con las familias. La raz\u00f3n es que los ni\u00f1os pueden ser grandes influyentes en la familia.<\/p><p>\u00a0<\/p><p><strong>Acontecimientos actuales y futuros<\/strong><\/p><p>Desaf\u00edo NEXTREX para el reciclado de envases y pel\u00edculas de pl\u00e1stico (en curso). Si alcanzamos las 1000 libras en un a\u00f1o, la parroquia recibir\u00e1 su propio banco de jard\u00edn.<\/p><p>Ampliar la presencia en el sitio web de la parroquia OLMC Darien, con un rinc\u00f3n separado de Cuidado de la Creaci\u00f3n (CforC) y actualizaciones. Proporcionar un c\u00f3digo QR en el bolet\u00edn para que aparezca el rinc\u00f3n de CforC y as\u00ed reducir el coste de impresi\u00f3n y la necesidad de reciclar los boletines.<\/p><p>Profundizar la implicaci\u00f3n en la parroquia (aumentar la participaci\u00f3n en los actos de CforC).<\/p><p>Serie de libros sobre Laudato Si (Cuaresma 2026).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dae8747 elementor-widget elementor-widget-button\" data-id=\"dae8747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80c4738 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"80c4738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3935d8f e-flex e-con-boxed e-con e-parent\" data-id=\"3935d8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac4232 elementor-widget elementor-widget-menu-anchor\" data-id=\"3ac4232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Cecilia\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f047b0e elementor-widget elementor-widget-text-editor\" data-id=\"f047b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Parroquia de Santa Cecilia<br \/><\/strong><strong>presentada por Fr. Dan O'Neill, 21 de abril de 2025<\/strong><strong>\u00a0<\/strong><\/h3><p>Santa Cecilia en Englewood, Nueva Jersey, ha tomado varias medidas importantes en los \u00faltimos a\u00f1os para hacer frente a las necesidades de las instalaciones.  Al hacerlo, tambi\u00e9n hemos mejorado nuestra postura en respuesta al cambio clim\u00e1tico.<\/p><p>En los dos \u00faltimos a\u00f1os, Santa Cecilia ha instalado todas las ventanas nuevas con doble aislamiento en nuestros dos edificios escolares.<\/p><p>Este a\u00f1o se ha instalado en nuestra iglesia un nuevo sistema de calefacci\u00f3n hidr\u00f3nica energ\u00e9ticamente eficiente.<\/p><p>Nuestro pastor conduce ahora un coche h\u00edbrido Toyota Prius Prime.<\/p><p>Colaboramos con las parroquias carmelitas de Tenafly y Cresskill en un esfuerzo por celebrar una serie de estudios sobre Laudato Si.<\/p><p>A t\u00edtulo individual, algunos de nuestros jubilados deciden ahora caminar por las escaleras en lugar de utilizar el ascensor.<\/p><p>Otros caminan para hacer recados cortos y comuniones.<\/p><p>Esperamos seguir con el esp\u00edritu del Papa Francisco.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1531847 elementor-widget elementor-widget-button\" data-id=\"1531847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64b6122 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"64b6122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-839c030 elementor-widget elementor-widget-menu-anchor\" data-id=\"839c030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Cresskill\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47de0d7 elementor-widget elementor-widget-image\" data-id=\"47de0d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"468\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3-768x468.jpg\" class=\"attachment-medium_large size-medium_large wp-image-20258\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3-768x468.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3-300x183.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3-1024x624.jpg 1024w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/05\/Picture3.jpg 1379w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ebc4945 e-flex e-con-boxed e-con e-parent\" data-id=\"ebc4945\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-089d06f elementor-widget elementor-widget-text-editor\" data-id=\"089d06f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong><em>Plan de Acci\u00f3n Laudato Si' para Santa Teresa de Lisieux Par\u00eds<br \/><\/em><em>Cresskill, New Jersey<br \/><\/em><em>Presentado por el P. Sam Citero, 28 de marzo de 2025<\/em><\/strong><\/h4><p><em>Identificar y responder a los 7 Objetivos de la enc\u00edclica del Papa Francisco, <\/em>Laudato Si'<strong>\u00a0<\/strong><\/p><ol><li><strong>Respuesta al clamor de la Tierra <\/strong><em>(completo y en curso)<\/em><ul><li>termostatos programables en todos los edificios<\/li><li>Luces LED (en el interior y el exterior de todos los edificios)<\/li><li>interruptores de luz con sensor de movimiento en ba\u00f1os y habitaciones que no se utilicen a pleno rendimiento<\/li><\/ul><\/li><\/ol><p><strong><em>Futuro:<\/em><\/strong><\/p><p>Estudiar el cambio de aceite a gas en la Oficina Parroquial<\/p><p>Estudiar la posibilidad de instalar jardines de lluvia y\/o recoger agua de lluvia para reducir el consumo de agua.<\/p><p>Sustituya las ventanas viejas por otras eficientes energ\u00e9ticamenteInvente en paneles solares<\/p><ol start=\"2\"><li><strong>Respuesta al clamor de los pobres<\/strong> (<em>completa y en curso)<\/em><ul><li>Colectas mensuales para los necesitados de nuestra zona y de nuestra parroquia hermana adoptada en Jersey City (calcetines, gorros, guantes, mantequilla de cacahuete y mermelada, material escolar, etc.) - Participaci\u00f3n en la alimentaci\u00f3n de las personas sin hogar (Family Promise, Hackensack).<\/li><\/ul><\/li><\/ol><p><strong><em>Futuro:<\/em><\/strong><\/p><p>Estudiar c\u00f3mo podemos llegar a nuestros feligreses de edad avanzada (conducci\u00f3n, compras, etc.)<\/p><ol start=\"3\"><li><strong>Econom\u00eda ecol\u00f3gica - Promover un desarrollo econ\u00f3mico sostenible desde el punto de vista medioambiental<\/strong> <em>(completo y en curso)<\/em><ul><li>Colocaci\u00f3n de contenedores de reciclaje en todos los edificios y espacios comunes (vidrio, pl\u00e1stico y papel).<\/li><li>Comprar productos biodegradables y compostables, como platos de papel, vasos de papel y cubiertos de bamb\u00fa o madera, y eliminar la compra de pl\u00e1stico.<\/li><li>Utilice manteles de tela reutilizables<\/li><\/ul><\/li><\/ol><p><strong><em>Futuro:<\/em><\/strong><\/p><p>Instalar lavavajillas en el Centro Parroquial para poder comprar cubiertos que se puedan lavar y reutilizar.<\/p><p>A\u00f1adir refrigeradores de agua al Armand Hall para eliminar el uso de botellas de agua.<\/p><ol start=\"4\"><li><strong>Adopci\u00f3n de estilos de vida sostenibles <\/strong><em>(completo y en curso)<\/em><\/li><\/ol><p style=\"padding-left: 80px;\">- Examinar a los proveedores e identificar si suministran bienes sostenibles<\/p><p><strong><em>Futuro:<\/em><\/strong><\/p><p>A\u00f1ada contratos de mantenimiento a las unidades de calefacci\u00f3n y aire acondicionado para garantizar su eficiencia<\/p><ol start=\"5\"><li><strong>Educaci\u00f3n ecol\u00f3gica<\/strong> <em>(en curso)<\/em><ul><li>Utilizar las redes sociales de forma m\u00e1s agresiva (tanto Facebook como Instagram).<\/li><\/ul><\/li><\/ol><p><strong><em>Futuro:<\/em><\/strong><\/p><p>A\u00f1ade un acto del D\u00eda de la Tierra (quiz\u00e1s una mesa con informaci\u00f3n sobre alternativas a los pl\u00e1sticos y reciclaje) e investiga un posible patrocinador.<\/p><p>Hablar con los responsables de Educaci\u00f3n Religiosa y pedirles que incluyan la administraci\u00f3n de la tierra en momentos espec\u00edficos del a\u00f1o.<\/p><p>Hablar con las Damas B\u00edblicas y los Caballeros pidi\u00e9ndoles que sigan nuestro ejemplo en cualquier compra que puedan hacer para sus grupos, as\u00ed como las directrices sobre reciclaje.<\/p><ol start=\"6\"><li><strong>Espiritualidad ecol\u00f3gica<\/strong> <em>(en curso)<\/em><\/li><\/ol><p style=\"padding-left: 80px;\">Celebrar momentos del a\u00f1o que incluyan la administraci\u00f3n de nuestra tierra, como la Bendici\u00f3n de los Animales (octubre), el D\u00eda de la Tierra (abril), la Semana Laudato Si (mayo)...<\/p><p><strong><em>Futuro:<\/em><\/strong><\/p><p>Crear un huerto parroquial con algunas hortalizas<\/p><p>Crear Tarjetas de Oraci\u00f3n durante las \u00e9pocas del a\u00f1o indicadas anteriormente<\/p><ol start=\"7\"><li><strong>Resiliencia y capacitaci\u00f3n de la comunidad<\/strong> <em>(en curso)<\/em><ul><li>Capacitar a los grupos ministeriales para que sigan nuestro ejemplo en materia de reciclaje y compras.<\/li><\/ul><\/li><\/ol><p><strong><em>Futuro:<\/em><\/strong><\/p><p>Reintroducir el D\u00eda de Servicio Comunitario Parroquial (quiz\u00e1s haciendo algo fuera de la parroquia)<\/p><p>Animar a los feligreses a compartir lo que hacen en casa para llevar una vida m\u00e1s sostenible y publicarlo mensualmente en el bolet\u00edn.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83163f6 elementor-widget elementor-widget-button\" data-id=\"83163f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c21f167 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c21f167\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2d89fd4 e-flex e-con-boxed e-con e-parent\" data-id=\"2d89fd4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3396b3 elementor-widget elementor-widget-menu-anchor\" data-id=\"b3396b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Coahuila\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf5aa7 elementor-widget elementor-widget-text-editor\" data-id=\"ddf5aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span class=\"--l sentence_highlight\">Plan de acci\u00f3n Laudato Si<br \/><\/span><span class=\"--l sentence_highlight\">Parroquia de la Transfiguraci\u00f3n del Se\u00f1or en Torre\u00f3n<br \/><\/span><span class=\"--l sentence_highlight\">Avenida \u00d1ado #412<br \/><\/span><span class=\"--l sentence_highlight\">Colonia Valle Oriente<br \/><\/span><span class=\"--l --r sentence_highlight\">Torre\u00f3n, Coahuila. <\/span><span class=\"--l sentence_highlight\">C.P. 27299<br \/><\/span><span class=\"--l --r sentence_highlight\">Presentado por: <\/span><span class=\"--l sentence_highlight\">Rev. Fray Rogelio Marcelino Garc\u00eda Asencio<br \/><\/span><span class=\"--l sentence_highlight\">Fecha: 20 de abril de 2025<\/span><\/h4><p><strong><span class=\"--l sentence_highlight\">Acciones en el esp\u00edritu de Laudato Si que ya se han emprendido:<\/span><\/strong><\/p><p><span class=\"--l sentence_highlight\">1. Responder al clamor de la tierra:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l --r sentence_highlight\">- En las \u00e1reas verdes de las capillas se sembraron plantas end\u00e9micas de la regi\u00f3n des\u00e9rtica de Torre\u00f3n como huizaches, nopales, cact\u00e1ceas, etc. <\/span><span class=\"--l sentence_highlight\">Tanto en la iglesia parroquial como en las capillas, comenzando con este proyecto en 2023.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Se instalaron paneles solares en la casa parroquial y en la iglesia parroquial, que se actualizaron en 2025 para obtener la capacidad energ\u00e9tica necesaria.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l --r sentence_highlight\"><span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">\u2013<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">A<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">verde<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">zona<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">fue<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">configure<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">arriba<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">para<\/span> <span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">compostaje<\/span><span class=\"--l --r hover:bg-blue-100 hover:dark:bg-blue-600\">.<\/span> <\/span><span class=\"--l sentence_highlight\">En 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- En 2023 se instalar\u00e1 un pozo de captaci\u00f3n y absorci\u00f3n de aguas pluviales para la iglesia parroquial.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Sustituci\u00f3n de todas las bombillas incandescentes por bombillas de bajo consumo antes de 2023.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Instalaci\u00f3n de urinarios secos en los ba\u00f1os parroquiales para ahorrar agua, a partir de 2024.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">2. Responder al clamor de los pobres:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l --r sentence_highlight\">- Hay un comedor parroquial donde se preparan y distribuyen alimentos a los ancianos, que actualmente atienden a m\u00e1s de 50 ancianos. <\/span><span class=\"--l sentence_highlight\">Desde 2020.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Los alimentos se preparan y distribuyen provisionalmente a los inmigrantes en las zonas ferroviarias, desde 2024.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Entregan alimentos espor\u00e1dicamente a familiares de enfermos del hospital general de Torre\u00f3n desde 2024.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l --r sentence_highlight\">3. <\/span><span class=\"--l sentence_highlight\">Promover la educaci\u00f3n ecol\u00f3gica:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- En la casa parroquial se hace separaci\u00f3n de basura, por ejemplo, la basura organizada va al jard\u00edn de compostaje, desde 2023.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Hay conciencia de apagar las luces, apagar los aparatos que no se usan para ahorrar electricidad en las capillas, como en la iglesia parroquial, a partir de 2023.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Los aparatos de aire acondicionado de las aulas y los despachos s\u00f3lo se encender\u00e1n en los momentos en que los utilicen los distintos grupos parroquiales y los trabajadores, a partir de 2023.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Se realizan pagos justos a todos los trabajadores por encima del salario m\u00ednimo, desde 2022 y se revisan a\u00f1o a a\u00f1o, para realizar los ajustes oportunos.<\/span><\/p><p><strong><span class=\"--l sentence_highlight\">Plan de acci\u00f3n:<\/span><\/strong><\/p><p><span class=\"--l sentence_highlight\">1. Responder al clamor de la Tierra:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Est\u00e1 previsto en una de las capillas de la parroquia instalar paneles solares, para ahorro de energ\u00eda, proyecto que se realizar\u00e1 en julio de 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Continuar con el apoyo al proyecto Laudato Si, con la instalaci\u00f3n de paneles solares en las dem\u00e1s capillas de la parroquia, hasta 2026.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Hacer m\u00e1s jardines de lluvia y plantaci\u00f3n de plantas end\u00e9micas, para el cuidado del agua, hasta 2026.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Renovaci\u00f3n de los cuartos de ba\u00f1o, con instalaci\u00f3n de inodoros que ahorren agua, para 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Cambio e instalaci\u00f3n de urinarios secos en los ba\u00f1os de las capillas para 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Creaci\u00f3n de basureros ecol\u00f3gicos en la parroquia y en las capillas, con el reciclaje de la basura, 2026.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Creaci\u00f3n de m\u00e1s huertos de compost, 2026.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Creaci\u00f3n de m\u00e1s pozos de recogida y absorci\u00f3n de aguas pluviales en parroquias y capillas para 2026.<\/span><\/p><p><span class=\"--l sentence_highlight\">2. Responder al clamor de los pobres:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Continuar con el comedor social parroquial, para llevar comida a ancianos, inmigrantes y familiares de enfermos del hospital general, a partir de 2025.<\/span><\/p><p><span class=\"--l --r sentence_highlight\">3. <\/span><span class=\"--l sentence_highlight\">Promover la educaci\u00f3n ecol\u00f3gica:<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Creaci\u00f3n de un equipo parroquial de ecolog\u00eda para sensibilizar a la comunidad parroquial, de aqu\u00ed a 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Celebrar el A\u00f1o de la Tierra en junio-julio con charlas y plantaci\u00f3n de huertos con la ayuda de Laudato Si y el equipo ecologista de la parroquia para 2025.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34187b5 elementor-widget elementor-widget-button\" data-id=\"34187b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d06806b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d06806b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-fe948a7 e-flex e-con-boxed e-con e-parent\" data-id=\"fe948a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5bc3a0 elementor-widget elementor-widget-menu-anchor\" data-id=\"e5bc3a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ElSalvador\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f82e5ca elementor-widget elementor-widget-text-editor\" data-id=\"f82e5ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span class=\"--l sentence_highlight\">Plan de acci\u00f3n Laudato Si<br \/><\/span><span class=\"--l sentence_highlight\">Nombre del Ministerio o Comunidad: Hogar San Alberto de Jerusal\u00e9n <br \/><\/span><span class=\"--l sentence_highlight\">Ubicaci\u00f3n: Huiz\u00facar, Departamento de La Libertad, El Salvador<br \/><\/span><span class=\"--l --r sentence_highlight\">Presentado por: <\/span><span class=\"--l --r sentence_highlight\">Rodolfo Aznaran Ocarm. <\/span><span class=\"--l sentence_highlight\">- Anterior<br \/><\/span><span class=\"--l sentence_highlight\">Fecha: 20 de abril<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/h4><p><strong><span class=\"--l sentence_highlight\">Acciones en el esp\u00edritu de Laudato Si' que ya se han emprendido:<\/span><\/strong><\/p><p><span class=\"--l sentence_highlight\">-Vivimos en parte de lo que se cultiva y de los animales que se cr\u00edan en la Finca San El\u00edas.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Reducimos el uso y la reutilizaci\u00f3n de bolsas de pl\u00e1stico. <\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Reutilizamos el papel<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Recogemos el agua de lluvia<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Apagamos las luces cuando no se utilizan.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Los residuos org\u00e1nicos se utilizan para enriquecer el suelo.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Estamos haciendo la transici\u00f3n a herbicidas org\u00e1nicos.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Plantamos \u00e1rboles y cultivamos plantas ornamentales. <\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Cuidamos de nuestros hermanos y hermanas, especialmente de los ancianos y los enfermos.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Tenemos 2 d\u00edas sin carne en nuestro men\u00fa<\/span><\/p><p><strong><span class=\"--l sentence_highlight\">Durante este a\u00f1o - 2025:<\/span><\/strong><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Queremos mejorar nuestro sistema de reciclado, <\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- celebrar la Eucarist\u00eda del D\u00eda de la Tierra.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p><p><span class=\"--l sentence_highlight\">- Promover la educaci\u00f3n de ni\u00f1os y j\u00f3venes mediante la ense\u00f1anza de la lengua inglesa. <\/span><\/p><p><span class=\"--l sentence_highlight\">El a\u00f1o que viene presentaremos un proyecto para financiar la instalaci\u00f3n de paneles solares para reducir el coste de la electricidad y utilizar energ\u00eda sostenible.<\/span><span class=\"--r sentence_highlight\"><br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380b601 elementor-widget elementor-widget-button\" data-id=\"380b601\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f37c1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"24f37c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5a730d7 e-flex e-con-boxed e-con e-parent\" data-id=\"5a730d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7eb2d1 elementor-widget elementor-widget-menu-anchor\" data-id=\"c7eb2d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Tucson\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03eaea4 elementor-widget elementor-widget-text-editor\" data-id=\"03eaea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Priorato Carmelita en Tucson, AZ<br \/><\/strong><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Presentado por el P. Roberto Carlos Reyes Castillo<br \/><\/strong><strong>19 de abril de 2025<\/strong><\/h4><p><strong>Lo que ya ha hecho la comunidad<\/strong><\/p><ul><li>Hemos instalado paneles solares en la casa<\/li><li>Todas las bombillas de la casa, incluidas las del exterior, son de bajo consumo.<\/li><li>Las habitaciones disponen de inodoros de bajo consumo de agua<\/li><li>La casa separa la basura y los art\u00edculos reciclables se depositan en los contenedores municipales para esos art\u00edculos: cart\u00f3n, vidrio, botellas de pl\u00e1stico y latas de aluminio.<\/li><li>La comunidad ya no compra botellas de agua, pues se han instalado fuentes.<\/li><li>El tejado se ha tratado para aislarlo y evitar que entre el calor, con el fin de reducir el uso del aire acondicionado en verano.<\/li><\/ul><p><strong><br \/>Planes para el futuro<\/strong><\/p><ul><li>Hay un proyecto para convertir en paisajismo sostenible nuestro jard\u00edn interior en el pr\u00f3ximo a\u00f1o. As\u00ed se reducir\u00e1 el consumo de agua.<\/li><li>Tenemos previsto cambiar a coches el\u00e9ctricos o h\u00edbridos enchufables.<\/li><li>Tenemos previsto eliminar las palmeras de nuestra propiedad, ya que no son plantas aut\u00f3ctonas y requieren grandes cantidades de agua.<\/li><li>A\u00fan tenemos que encontrar la manera de llegar a las personas necesitadas.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-457fe1a elementor-widget elementor-widget-button\" data-id=\"457fe1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b5a493 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4b5a493\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-747bdac e-flex e-con-boxed e-con e-parent\" data-id=\"747bdac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3074c68 elementor-widget elementor-widget-menu-anchor\" data-id=\"3074c68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"StCyril\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d4386 elementor-widget elementor-widget-text-editor\" data-id=\"d9d4386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong><u>Laudato Si'<br \/><\/u><\/strong><strong><u>PLAN DE ACCI\u00d3N 2025<br \/><\/u><\/strong><strong>Priorato de San Cirilo, Chicago<br \/><\/strong><strong>18 de abril de 2025<\/strong><\/h4><p>Nuestra mayor necesidad es que la comunidad desarrolle una conciencia cada vez mayor de nuestra capacidad para cambiar lo que es \"normal\" en nuestras vidas.  Necesitamos identificar y reducir las fuentes de distracci\u00f3n trivial y desarrollar una habilidad para elegir lo que realmente importa.<\/p><p>Como individuos, esperamos implicaci\u00f3n y sacrificio personales.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Reciclar y evitar residuos<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 - sobre todo pl\u00e1stico, pero tambi\u00e9n papel y restos de comida<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 - limitar lo que va a parar a un vertedero<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 - apague las luces que no utilice<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 - comprar en mayor cantidad\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Reducir el uso del coche - coger el autob\u00fas<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Donar art\u00edculos no utilizados<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Repasa y utiliza las ideas de \"14 peque\u00f1os cambios\".<\/p><p>Como v\u00ednculo carmelita con la Escuela Secundaria Mt. Carmel, tambi\u00e9n podemos proporcionar liderazgo y ejemplo a los miembros de la comunidad escolar.  Sobre todo, podemos a\u00f1adir una dimensi\u00f3n espiritual a nuestra actividad.  El cuidado de la tierra mejora nuestra relaci\u00f3n con Dios.  Las actividades no son s\u00f3lo acciones simb\u00f3licas, sino una formaci\u00f3n espiritual que causa una impresi\u00f3n duradera.\u00a0<\/p><p>La Escuela ya est\u00e1 participando en medidas positivas.  Como siempre, el liderazgo carmelita ayuda a sobrealimentar la actividad.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Planean una Auditor\u00eda del D\u00eda de la Tierra sobre los residuos de la cafeter\u00eda.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * El uso del pl\u00e1stico tambi\u00e9n es un objetivo prioritario.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Los estudiantes asistieron a la Cumbre Cat\u00f3lica sobre el Clima 2024, 2025.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Despensa de alimentos - Eduardo ya ayuda.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Tracy espera trabajar con la direcci\u00f3n de la escuela para facilitar el esfuerzo de la comunidad con el programa escolar.<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 * Se est\u00e1 estudiando la restauraci\u00f3n del tejado verde.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2b6658 elementor-widget elementor-widget-button\" data-id=\"e2b6658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a972a7f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a972a7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b30a7a6 e-flex e-con-boxed e-con e-parent\" data-id=\"b30a7a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f236e0b elementor-widget elementor-widget-menu-anchor\" data-id=\"f236e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"StSimon\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a85502 elementor-widget elementor-widget-text-editor\" data-id=\"2a85502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si\n<\/strong><strong>Priorato de San Sim\u00f3n Stock\n<\/strong><strong>Darien, IL\n<\/strong><strong>21 de abril de 2025<\/strong><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/h4>\n<strong><u>Acciones en el esp\u00edritu de Laudato Si' que ya hemos emprendido<\/u><\/strong><strong>: <\/strong><strong>\u00a0<\/strong>\n<ul>\n \t<li>Plantaci\u00f3n de numerosos \u00e1rboles en el campus (desde 2020)<\/li>\n \t<li>Uso de bombillas LED al sustituir todas las bombillas (desde 2020)<\/li>\n \t<li>Ser conscientes a la hora de apagar la luz cuando no se est\u00e1 en una habitaci\u00f3n (desde 2018)<\/li>\n<\/ul>\n<ul>\n \t<li>Generosas donaciones a las despensas de alimentos durante la temporada navide\u00f1a a la Parroquia de Nuestra Se\u00f1ora del Monte Carmelo, Darien y a la Parroquia de Nuestra Se\u00f1ora del Monte Carmelo, Joliet (desde 2022).<\/li>\n \t<li>Reciclaje de papeles en la Casa Winterberry (desde 2010)<\/li>\n \t<li>Comidas sin carne una vez a la semana en la mesa comunitaria (desde 2010)<strong>\n<\/strong><\/li>\n<\/ul>\n<strong>\u00a0<\/strong>\n\n<strong><u>Lo que deseamos lograr en 2025 y m\u00e1s all\u00e1 que est\u00e9n en el esp\u00edritu de Laudato Si': <\/u><\/strong><strong>\u00a0<\/strong>\n<ul>\n \t<li>Todo lo anterior para continuar<\/li>\n \t<li>A la hora de comprar futuros veh\u00edculos, investigue sobre coches el\u00e9ctricos o h\u00edbridos<\/li>\n \t<li>Investigar formas de reciclar latas y envases de vidrio en el campus de Dari\u00e9n (para el 1 de julio de 2025).<\/li>\n<\/ul>\n<ul>\n \t<li>Recoger la basura del campus (antes del 1 de julio de 2025)<\/li>\n<\/ul>\nRespetuosamente presentado en nombre de la comunidad, David McEvoy, O.Carm.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f143adc elementor-widget elementor-widget-button\" data-id=\"f143adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-25338b4 e-flex e-con-boxed e-con e-parent\" data-id=\"25338b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a79409c elementor-widget elementor-widget-menu-anchor\" data-id=\"a79409c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"TheresePhoenix\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d0be59 elementor-widget elementor-widget-text-editor\" data-id=\"2d0be59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><strong>Plan de acci\u00f3n Laudato Si<br \/><\/strong><strong>Priorato de Santa Teresa de Lisieux<br \/><\/strong><strong>Phoenix, AZ<br \/><\/strong><strong>Enviado por: Ron Oakham<br \/><\/strong><strong>Noviembre de 2025<\/strong><\/h4><p><u>Medidas ya adoptadas:<\/u><\/p><p>Reducir nuestro consumo de agua en la propiedad:<\/p><p>Reducir la superficie cubierta de c\u00e9sped que necesita riego continuo.<\/p><p>2023 Instalaci\u00f3n de un paisaje sin vegetaci\u00f3n en la parte delantera de las dos alas del edificio y a lo largo de la fachada que da a la carretera.<\/p><p>2024 Sustituci\u00f3n del c\u00e9sped plantado en la zona central del patio por c\u00e9sped artificial.<\/p><p>2025 Creaci\u00f3n de islas sin paisajes en la zona del jard\u00edn delantero.<\/p><p><u>Plan de acci\u00f3n para 2026 y a\u00f1os posteriores:<\/u><\/p><p>Investiga un poco sobre la instalaci\u00f3n de paneles solares.<\/p><p>para montar en las estructuras de sombra de la zona de aparcamiento<\/p><p>o en los tejados de los edificios residenciales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60d2011 elementor-widget elementor-widget-button\" data-id=\"60d2011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#return\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver al \u00edndice<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Uni\u00e9ndose a una comunidad mundial, la Provincia Carmelita del Pur\u00edsimo Coraz\u00f3n de Mar\u00eda se compromete a un proceso de seis a\u00f1os del Plan de Acci\u00f3n Laudato Si'. Este proceso incluir\u00e1 la inscripci\u00f3n en la Plataforma de Acci\u00f3n Laudato Si', la creaci\u00f3n de un Plan de Acci\u00f3n Laudato Si', y evaluaciones y actualizaciones anuales del Plan. A lo largo de estos seis a\u00f1os, se revisar\u00e1n las aportaciones del Consejo Provincial y de las Comisiones Provinciales. El Consejo Provincial y las Comisiones Provinciales supervisan todos los aspectos de las operaciones provinciales. Como escribi\u00f3 el Papa Francisco en Laudato Si': \"Se necesitan los talentos y la participaci\u00f3n de todos\" (LS14).<\/p>","protected":false},"author":14,"featured_media":6548,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_analytify_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"KJ Pino\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Order of Carmelites - Province of the Most Pure Heart of Mary\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites\" \/>\n\t\t<meta property=\"og:description\" content=\"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-27T21:44:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-23T19:22:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carmelites\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#blogposting\",\"name\":\"Laudato Si\\u2019 Action Plan | May 2025 - Order of Carmelites\",\"headline\":\"Laudato Si\\u2019 Action Plan | May 2025\",\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/author\\\/kjpino\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Carmelite-Flat-Shield-600.png\",\"width\":600,\"height\":600},\"datePublished\":\"2025-05-27T16:44:05-05:00\",\"dateModified\":\"2026-08-23T14:22:57-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmelites.net\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/carmelites.net\\\/es\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#listItem\",\"name\":\"Laudato Si\\u2019 Action Plan | May 2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#listItem\",\"position\":3,\"name\":\"Laudato Si\\u2019 Action Plan | May 2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/#organization\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"url\":\"https:\\\/\\\/carmelites.net\\\/es\\\/\",\"telephone\":\"+16309710050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo100.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#organizationLogo\",\"width\":345,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carmelites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/carmelites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarmelitesPCM\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/author\\\/kjpino\\\/#author\",\"url\":\"https:\\\/\\\/carmelites.net\\\/es\\\/author\\\/kjpino\\\/\",\"name\":\"KJ Pino\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ea6cc4ae84d0bfae6191ee86cb6bf7261952812e142feef209f4dfa9324b1617?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"KJ Pino\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#webpage\",\"url\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/\",\"name\":\"Laudato Si\\u2019 Action Plan | May 2025 - Order of Carmelites\",\"description\":\"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\\u2019 Action Plan process. This process will include enrollment in the Laudato Si\\u2019 Action Platform, creation of a Laudato Si\\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\\u2019: \\u201cEveryone\\u2019s talents and involvement are needed\\u201d (LS14).\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/author\\\/kjpino\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/author\\\/kjpino\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Carmelite-Flat-Shield-600.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#mainImage\",\"width\":600,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/uncategorized\\\/laudato-si-action-plan-may-2025\\\/#mainImage\"},\"datePublished\":\"2025-05-27T16:44:05-05:00\",\"dateModified\":\"2026-08-23T14:22:57-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/carmelites.net\\\/es\\\/\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites<\/title>\n\n","aioseo_head_json":{"title":"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites","description":"Uni\u00e9ndose a una comunidad mundial, la Provincia Carmelita del Pur\u00edsimo Coraz\u00f3n de Mar\u00eda se compromete a un proceso de seis a\u00f1os del Plan de Acci\u00f3n Laudato Si'. Este proceso incluir\u00e1 la inscripci\u00f3n en la Plataforma de Acci\u00f3n Laudato Si', la creaci\u00f3n de un Plan de Acci\u00f3n Laudato Si', y evaluaciones y actualizaciones anuales del Plan. A lo largo de estos seis a\u00f1os, se revisar\u00e1n las aportaciones del Consejo Provincial y de las Comisiones Provinciales. El Consejo Provincial y las Comisiones Provinciales supervisan todos los aspectos de las operaciones provinciales. Como escribi\u00f3 el Papa Francisco en Laudato Si': \"Se necesitan los talentos y la participaci\u00f3n de todos\" (LS14).","canonical_url":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#blogposting","name":"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites","headline":"Laudato Si\u2019 Action Plan | May 2025","author":{"@id":"https:\/\/carmelites.net\/es\/author\/kjpino\/#author"},"publisher":{"@id":"https:\/\/carmelites.net\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/03\/Carmelite-Flat-Shield-600.png","width":600,"height":600},"datePublished":"2025-05-27T16:44:05-05:00","dateModified":"2026-08-23T14:22:57-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#webpage"},"isPartOf":{"@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es#listItem","position":1,"name":"Home","item":"https:\/\/carmelites.net\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/carmelites.net\/es\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#listItem","name":"Laudato Si\u2019 Action Plan | May 2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#listItem","position":3,"name":"Laudato Si\u2019 Action Plan | May 2025","previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/es\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/carmelites.net\/es\/#organization","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","url":"https:\/\/carmelites.net\/es\/","telephone":"+16309710050","logo":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#organizationLogo","width":345,"height":100},"image":{"@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Carmelites\/","https:\/\/www.instagram.com\/carmelites\/","https:\/\/www.youtube.com\/@CarmelitesPCM"]},{"@type":"Person","@id":"https:\/\/carmelites.net\/es\/author\/kjpino\/#author","url":"https:\/\/carmelites.net\/es\/author\/kjpino\/","name":"KJ Pino","image":{"@type":"ImageObject","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ea6cc4ae84d0bfae6191ee86cb6bf7261952812e142feef209f4dfa9324b1617?s=96&d=mm&r=g","width":96,"height":96,"caption":"KJ Pino"}},{"@type":"WebPage","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#webpage","url":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/","name":"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites","description":"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/carmelites.net\/es\/#website"},"breadcrumb":{"@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#breadcrumblist"},"author":{"@id":"https:\/\/carmelites.net\/es\/author\/kjpino\/#author"},"creator":{"@id":"https:\/\/carmelites.net\/es\/author\/kjpino\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/03\/Carmelite-Flat-Shield-600.png","@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#mainImage","width":600,"height":600},"primaryImageOfPage":{"@id":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/#mainImage"},"datePublished":"2025-05-27T16:44:05-05:00","dateModified":"2026-08-23T14:22:57-05:00"},{"@type":"WebSite","@id":"https:\/\/carmelites.net\/es\/#website","url":"https:\/\/carmelites.net\/es\/","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","inLanguage":"es-ES","publisher":{"@id":"https:\/\/carmelites.net\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Order of Carmelites - Province of the Most Pure Heart of Mary","og:type":"article","og:title":"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites","og:description":"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).","og:url":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/","og:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:secure_url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","article:published_time":"2025-05-27T21:44:05+00:00","article:modified_time":"2026-08-23T19:22:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Carmelites\/","twitter:card":"summary_large_image","twitter:title":"Laudato Si\u2019 Action Plan | May 2025 - Order of Carmelites","twitter:description":"Joining a worldwide community, the Carmelite Province of the Most Pure Heart of Mary commits to a six-year Laudato Si\u2019 Action Plan process. This process will include enrollment in the Laudato Si\u2019 Action Platform, creation of a Laudato Si\u2019 Action Plan, and yearly assessments and updating of the Plan. Over these six years, input from the Provincial Council and Provincial Commissions will be reviewed. The Provincial Council and Commissions oversee all aspects of provincial operations. As Pope Francis wrote in Laudato Si\u2019: \u201cEveryone\u2019s talents and involvement are needed\u201d (LS14).","twitter:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png"},"aioseo_meta_data":{"post_id":"20255","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-08-23 19:23:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2026-01-16 18:08:51","updated":"2026-08-23 20:14:24","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/es\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLaudato Si\u2019 Action Plan | May 2025\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carmelites.net\/es"},{"label":"Uncategorized","link":"https:\/\/carmelites.net\/es\/category\/uncategorized\/"},{"label":"Laudato Si\u2019 Action Plan | May 2025","link":"https:\/\/carmelites.net\/es\/uncategorized\/laudato-si-action-plan-may-2025\/"}],"_links":{"self":[{"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/posts\/20255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/comments?post=20255"}],"version-history":[{"count":30,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/posts\/20255\/revisions"}],"predecessor-version":[{"id":27195,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/posts\/20255\/revisions\/27195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/media\/6548"}],"wp:attachment":[{"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/media?parent=20255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/categories?post=20255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carmelites.net\/es\/wp-json\/wp\/v2\/tags?post=20255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}