{"id":381,"count":1,"description":"","link":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/","name":"de pazzi","slug":"de-pazzi","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Order of Carmelites - Province of the Most Pure Heart of Mary\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"de pazzi - Order of Carmelites\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"345\" \/>\n\t\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carmelites\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"de pazzi - Order of Carmelites\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/tag\\\/de-pazzi\\\/#listItem\",\"name\":\"de pazzi\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/tag\\\/de-pazzi\\\/#listItem\",\"position\":2,\"name\":\"de pazzi\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/#collectionpage\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/\",\"name\":\"de pazzi - Order of Carmelites\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"telephone\":\"+16309710050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo100.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/#organizationLogo\",\"width\":345,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/381\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carmelites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/carmelites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarmelitesPCM\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>de pazzi - Order of Carmelites<\/title>\n\n","aioseo_head_json":{"title":"de pazzi - Order of Carmelites","description":"","canonical_url":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","position":1,"name":"Home","item":"https:\/\/carmelites.net\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/#listItem","name":"de pazzi"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/#listItem","position":2,"name":"de pazzi","previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/#collectionpage","url":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/","name":"de pazzi - Order of Carmelites","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/carmelites.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/carmelites.net\/de\/#organization","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","url":"https:\/\/carmelites.net\/de\/","telephone":"+16309710050","logo":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","@id":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/#organizationLogo","width":345,"height":100},"image":{"@id":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Carmelites\/","https:\/\/www.instagram.com\/carmelites\/","https:\/\/www.youtube.com\/@CarmelitesPCM"]},{"@type":"WebSite","@id":"https:\/\/carmelites.net\/de\/#website","url":"https:\/\/carmelites.net\/de\/","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","inLanguage":"de-DE","publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Order of Carmelites - Province of the Most Pure Heart of Mary","og:type":"article","og:title":"de pazzi - Order of Carmelites","og:url":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/","og:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:secure_url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:width":345,"og:image:height":100,"article:publisher":"https:\/\/www.facebook.com\/Carmelites\/","twitter:card":"summary_large_image","twitter:title":"de pazzi - Order of Carmelites","twitter:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png"},"aioseo_meta_data":{"term_id":"381","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-15 22:43:41","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"breadcrumb_settings":null,"created":"2026-05-15 22:41:41","updated":"2026-05-15 22:43:41"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tde pazzi\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carmelites.net\/de"},{"label":"de pazzi","link":"https:\/\/carmelites.net\/de\/tag\/de-pazzi\/"}],"_links":{"self":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts?tags=381"},{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tribe_events?tags=381"},{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tec_calendar_embed?tags=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}