{"id":5763,"date":"2024-03-02T18:11:09","date_gmt":"2024-03-03T00:11:09","guid":{"rendered":"https:\/\/carmelites.net\/?p=5763"},"modified":"2024-07-01T12:14:38","modified_gmt":"2024-07-01T17:14:38","slug":"conners-o-carm-quinn","status":"publish","type":"post","link":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/","title":{"rendered":"CONNERS, O.Carm., Quinn"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5763\" class=\"elementor elementor-5763\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a159e23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a159e23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52197be\" data-id=\"52197be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-847af1f elementor-widget elementor-widget-text-editor\" data-id=\"847af1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ministerium Info:<\/strong><\/h4><p><strong>RETIRED<\/strong><\/p><p>E-Mail: <a href=\"mailto:qconners@carmelites.net\" target=\"_blank\" rel=\"noopener\">qconners@carmelites.net<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-29f09283 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29f09283\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34cccd69\" data-id=\"34cccd69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-543efa32 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"543efa32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/carmelites.net\/de\/friars-of-pcm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur\u00fcck zu allen Br\u00fcdern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5066826c\" data-id=\"5066826c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ministry Info: RETIRED Email: qconners@carmelites.net Private Info: Cell: 202-285-8119 Whitefriars Hall (St. Therese Priory), Washington, DC POB: Chicago, ILDOB: Jun 10, 1944First Vows: Aug 22, 1965Solemn Vows: Feb 7, 1969Ordination: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_analytify_skip_tracking":false,"footnotes":""},"categories":[27],"tags":[30],"class_list":["post-5763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-friars","tag-c"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Order of Carmelites - Province of the Most Pure Heart of Mary\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CONNERS, O.Carm., Quinn - Order of Carmelites\" \/>\n\t\t<meta property=\"og:description\" content=\"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-03T00:11:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-01T17:14:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carmelites\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CONNERS, O.Carm., Quinn - Order of Carmelites\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#blogposting\",\"name\":\"CONNERS, O.Carm., Quinn - Order of Carmelites\",\"headline\":\"CONNERS, O.Carm., Quinn\",\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Conners_Quinn_600.jpg\",\"width\":1217,\"height\":1218},\"datePublished\":\"2024-03-02T18:11:09-06:00\",\"dateModified\":\"2024-07-01T12:14:38-05:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#webpage\"},\"articleSection\":\"Friars, C\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"name\":\"Friars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"position\":2,\"name\":\"Friars\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#listItem\",\"name\":\"CONNERS, O.Carm., Quinn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#listItem\",\"position\":3,\"name\":\"CONNERS, O.Carm., Quinn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"name\":\"Friars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"telephone\":\"+16309710050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo100.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#organizationLogo\",\"width\":345,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carmelites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/carmelites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarmelitesPCM\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8fa05500bcb02ce406479cff4229916c15cb0289e690ce56eb0734dec206058?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#webpage\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/\",\"name\":\"CONNERS, O.Carm., Quinn - Order of Carmelites\",\"description\":\"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Conners_Quinn_600.jpg\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#mainImage\",\"width\":1217,\"height\":1218},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/conners-o-carm-quinn\\\/#mainImage\"},\"datePublished\":\"2024-03-02T18:11:09-06:00\",\"dateModified\":\"2024-07-01T12:14:38-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>CONNERS, O.Carm., Quinn - Order of Carmelites<\/title>\n\n","aioseo_head_json":{"title":"CONNERS, O.Carm., Quinn \u2013 Karmeliterorden","description":"Informationen zum Dienst: IM RUHESTAND E-Mail: qconners@carmelites.net Zur\u00fcck zu allen Br\u00fcdern","canonical_url":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#blogposting","name":"CONNERS, O.Carm., Quinn - Order of Carmelites","headline":"CONNERS, O.Carm., Quinn","author":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/03\/Conners_Quinn_600.jpg","width":1217,"height":1218},"datePublished":"2024-03-02T18:11:09-06:00","dateModified":"2024-07-01T12:14:38-05:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#webpage"},"isPartOf":{"@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#webpage"},"articleSection":"Friars, C"},{"@type":"BreadcrumbList","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","position":1,"name":"Home","item":"https:\/\/carmelites.net\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","name":"Friars"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","position":2,"name":"Friars","item":"https:\/\/carmelites.net\/de\/category\/friars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#listItem","name":"CONNERS, O.Carm., Quinn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#listItem","position":3,"name":"CONNERS, O.Carm., Quinn","previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","name":"Friars"}}]},{"@type":"Organization","@id":"https:\/\/carmelites.net\/de\/#organization","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","url":"https:\/\/carmelites.net\/de\/","telephone":"+16309710050","logo":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#organizationLogo","width":345,"height":100},"image":{"@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Carmelites\/","https:\/\/www.instagram.com\/carmelites\/","https:\/\/www.youtube.com\/@CarmelitesPCM"]},{"@type":"Person","@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author","url":"https:\/\/carmelites.net\/de\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8fa05500bcb02ce406479cff4229916c15cb0289e690ce56eb0734dec206058?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#webpage","url":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/","name":"CONNERS, O.Carm., Quinn - Order of Carmelites","description":"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/carmelites.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#breadcrumblist"},"author":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"creator":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/03\/Conners_Quinn_600.jpg","@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#mainImage","width":1217,"height":1218},"primaryImageOfPage":{"@id":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/#mainImage"},"datePublished":"2024-03-02T18:11:09-06:00","dateModified":"2024-07-01T12:14:38-05:00"},{"@type":"WebSite","@id":"https:\/\/carmelites.net\/de\/#website","url":"https:\/\/carmelites.net\/de\/","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","inLanguage":"de-DE","publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Order of Carmelites - Province of the Most Pure Heart of Mary","og:type":"article","og:title":"CONNERS, O.Carm., Quinn - Order of Carmelites","og:description":"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars","og:url":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/","og:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:secure_url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","article:published_time":"2024-03-03T00:11:09+00:00","article:modified_time":"2024-07-01T17:14:38+00:00","article:publisher":"https:\/\/www.facebook.com\/Carmelites\/","twitter:card":"summary_large_image","twitter:title":"CONNERS, O.Carm., Quinn - Order of Carmelites","twitter:description":"Ministry Info:RETIREDEmail: qconners@carmelites.net Return to all Friars","twitter:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png"},"aioseo_meta_data":{"post_id":"5763","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-15 18:35:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2026-01-16 17:39:25","updated":"2026-07-15 18:35:15","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\/category\/friars\/\" title=\"Friars\">Friars<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tCONNERS, O.Carm., Quinn\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carmelites.net\/de"},{"label":"Friars","link":"https:\/\/carmelites.net\/de\/category\/friars\/"},{"label":"CONNERS, O.Carm., Quinn","link":"https:\/\/carmelites.net\/de\/friars\/conners-o-carm-quinn\/"}],"_links":{"self":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/comments?post=5763"}],"version-history":[{"count":49,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5763\/revisions"}],"predecessor-version":[{"id":13406,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5763\/revisions\/13406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/media\/5764"}],"wp:attachment":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/media?parent=5763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/categories?post=5763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags?post=5763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}