{"id":5522,"date":"2024-02-13T17:41:35","date_gmt":"2024-02-13T23:41:35","guid":{"rendered":"https:\/\/carmelites.net\/?p=5522"},"modified":"2024-07-02T19:44:44","modified_gmt":"2024-07-03T00:44:44","slug":"wilde-o-carm-adrian","status":"publish","type":"post","link":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/","title":{"rendered":"WILDE, O.Carm., Adrian"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"5522\" class=\"elementor elementor-5522\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a159e23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a159e23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52197be\" data-id=\"52197be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-847af1f elementor-widget elementor-widget-text-editor\" data-id=\"847af1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ministerium Info:<\/strong><\/h4><p><strong>RETIRED<\/strong><\/p><p>E-Mail: <a href=\"mailto:awilde@carmelites.net\" target=\"_blank\" rel=\"noopener\">awilde@carmelites.net<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9cead3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cead3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0eff900\" data-id=\"0eff900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-176b130 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"176b130\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/carmelites.net\/de\/friars-of-pcm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zur\u00fcck zu allen Br\u00fcdern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5085bd\" data-id=\"f5085bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ministry Info: RETIRED Email: awilde@carmelites.net Private Info: Cell: 941-313-4913 Prior for Carmelites in FloridaCarmel at Mission Valley, Nokomis, FL POB: Birmingham, United KingdomDOB: Feb 14, 1946 First Vows: Sep 8, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_analytify_skip_tracking":false,"footnotes":""},"categories":[27],"tags":[34],"class_list":["post-5522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-friars","tag-w"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Order of Carmelites - Province of the Most Pure Heart of Mary\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"WILDE, O.Carm., Adrian - Order of Carmelites\" \/>\n\t\t<meta property=\"og:description\" content=\"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-13T23:41:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-03T00:44:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carmelites\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"WILDE, O.Carm., Adrian - Order of Carmelites\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#blogposting\",\"name\":\"WILDE, O.Carm., Adrian - Order of Carmelites\",\"headline\":\"WILDE, O.Carm., Adrian\",\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wilde_Adrian.jpg\",\"width\":600,\"height\":600},\"datePublished\":\"2024-02-13T17:41:35-06:00\",\"dateModified\":\"2024-07-02T19:44:44-05:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#webpage\"},\"articleSection\":\"Friars, W\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"name\":\"Friars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"position\":2,\"name\":\"Friars\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#listItem\",\"name\":\"WILDE, O.Carm., Adrian\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#listItem\",\"position\":3,\"name\":\"WILDE, O.Carm., Adrian\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/category\\\/friars\\\/#listItem\",\"name\":\"Friars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"telephone\":\"+16309710050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo100.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#organizationLogo\",\"width\":345,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carmelites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/carmelites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarmelitesPCM\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8fa05500bcb02ce406479cff4229916c15cb0289e690ce56eb0734dec206058?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#webpage\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/\",\"name\":\"WILDE, O.Carm., Adrian - Order of Carmelites\",\"description\":\"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Wilde_Adrian.jpg\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#mainImage\",\"width\":600,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/friars\\\/wilde-o-carm-adrian\\\/#mainImage\"},\"datePublished\":\"2024-02-13T17:41:35-06:00\",\"dateModified\":\"2024-07-02T19:44:44-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>WILDE, O.Carm., Adrian - Order of Carmelites<\/title>\n\n","aioseo_head_json":{"title":"WILDE, O.Carm., Adrian - Order of Carmelites","description":"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars","canonical_url":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#blogposting","name":"WILDE, O.Carm., Adrian - Order of Carmelites","headline":"WILDE, O.Carm., Adrian","author":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/02\/Wilde_Adrian.jpg","width":600,"height":600},"datePublished":"2024-02-13T17:41:35-06:00","dateModified":"2024-07-02T19:44:44-05:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#webpage"},"isPartOf":{"@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#webpage"},"articleSection":"Friars, W"},{"@type":"BreadcrumbList","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","position":1,"name":"Home","item":"https:\/\/carmelites.net\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","name":"Friars"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","position":2,"name":"Friars","item":"https:\/\/carmelites.net\/de\/category\/friars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#listItem","name":"WILDE, O.Carm., Adrian"},"previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#listItem","position":3,"name":"WILDE, O.Carm., Adrian","previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/category\/friars\/#listItem","name":"Friars"}}]},{"@type":"Organization","@id":"https:\/\/carmelites.net\/de\/#organization","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","url":"https:\/\/carmelites.net\/de\/","telephone":"+16309710050","logo":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#organizationLogo","width":345,"height":100},"image":{"@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Carmelites\/","https:\/\/www.instagram.com\/carmelites\/","https:\/\/www.youtube.com\/@CarmelitesPCM"]},{"@type":"Person","@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author","url":"https:\/\/carmelites.net\/de\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8fa05500bcb02ce406479cff4229916c15cb0289e690ce56eb0734dec206058?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#webpage","url":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/","name":"WILDE, O.Carm., Adrian - Order of Carmelites","description":"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/carmelites.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#breadcrumblist"},"author":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"creator":{"@id":"https:\/\/carmelites.net\/de\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/02\/Wilde_Adrian.jpg","@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#mainImage","width":600,"height":600},"primaryImageOfPage":{"@id":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/#mainImage"},"datePublished":"2024-02-13T17:41:35-06:00","dateModified":"2024-07-02T19:44:44-05:00"},{"@type":"WebSite","@id":"https:\/\/carmelites.net\/de\/#website","url":"https:\/\/carmelites.net\/de\/","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","inLanguage":"de-DE","publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Order of Carmelites - Province of the Most Pure Heart of Mary","og:type":"article","og:title":"WILDE, O.Carm., Adrian - Order of Carmelites","og:description":"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars","og:url":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/","og:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:secure_url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","article:published_time":"2024-02-13T23:41:35+00:00","article:modified_time":"2024-07-03T00:44:44+00:00","article:publisher":"https:\/\/www.facebook.com\/Carmelites\/","twitter:card":"summary_large_image","twitter:title":"WILDE, O.Carm., Adrian - Order of Carmelites","twitter:description":"Ministry Info:RETIREDEmail: awilde@carmelites.net Return to all Friars","twitter:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png"},"aioseo_meta_data":{"post_id":"5522","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-15 18:40:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2026-01-16 17:48:02","updated":"2026-07-15 18:40:23","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\/category\/friars\/\" title=\"Friars\">Friars<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tWILDE, O.Carm., Adrian\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carmelites.net\/de"},{"label":"Friars","link":"https:\/\/carmelites.net\/de\/category\/friars\/"},{"label":"WILDE, O.Carm., Adrian","link":"https:\/\/carmelites.net\/de\/friars\/wilde-o-carm-adrian\/"}],"_links":{"self":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/comments?post=5522"}],"version-history":[{"count":40,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5522\/revisions"}],"predecessor-version":[{"id":13748,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/posts\/5522\/revisions\/13748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/media\/5523"}],"wp:attachment":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/media?parent=5522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/categories?post=5522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/tags?post=5522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}