{"id":18,"date":"2021-07-28T16:37:59","date_gmt":"2021-07-28T16:37:59","guid":{"rendered":"https:\/\/carmelites.net\/?page_id=18"},"modified":"2026-03-04T11:21:16","modified_gmt":"2026-03-04T17:21:16","slug":"ministries","status":"publish","type":"page","link":"https:\/\/carmelites.net\/de\/ministries\/","title":{"rendered":"DIENSTLEISTUNGEN"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"18\" class=\"elementor elementor-18\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e98380c e-flex e-con-boxed e-con e-parent\" data-id=\"e98380c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aeafa0e elementor-widget elementor-widget-heading\" data-id=\"aeafa0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DIENSTLEISTUNGEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6199053 elementor-widget elementor-widget-text-editor\" data-id=\"6199053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Die Karmelitenbr\u00fcder der Provinz vom Reinsten Herzen Mariens arbeiten in zwanzig Pfarreien, acht Gymnasien und drei Exerzitienh\u00e4usern in vier L\u00e4ndern Amerikas - den Vereinigten Staaten, Kanada, Per\u00fa, Mexic\u00f3, El Salvador und Honduras.<\/p><p>Verwenden Sie Strg\/Befehl F zum Suchen (funktioniert in jedem Desktop-Browser). Auf Smartphones verwenden Sie \"...\" und Suchen in Seite.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb5f96e elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"cb5f96e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.66,&quot;sizes&quot;:[]},&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-portfolio__filters\">\n\t\t\t<li class=\"elementor-portfolio__filter elementor-active\" tabindex=\"0\" data-filter=\"__all\">Alle<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"14\">a. Arizona<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"15\">b. Kalifornien<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"16\">c. Florida<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"10\">d. Illinois<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"20\">e. Kansas<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"19\">f. New Jersey<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"13\">h. Washington DC<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"18\">i. Kanada<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"21\">j. El Salvador<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"22\">k. Honduras<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"23\">l. Mexic\u00f3<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"24\">m. Per\u00fa<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"11\">n. Provinz<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"25\">o. Ressourcen<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"12\">p. Schulen<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"33\">q. Ministerien<\/li>\n\t\t\t\t\t<\/ul>\n\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-19 elementor-filter-25 elementor-filter-33 post-11749 post type-post status-publish format-standard has-post-thumbnail hentry category-new-jersey category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/new-jersey\/carmelite-missions-office-englewood-nj\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/CarmeliteMissions-300x200.png\" class=\"attachment-medium size-medium wp-image-11752\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/CarmeliteMissions-300x200.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/CarmeliteMissions-768x512.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/CarmeliteMissions.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelitisches Missionsb\u00fcro, Englewood, NJ\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-12 elementor-filter-33 post-10047 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/school\/colegio-nuestra-senora-del-carmen-barranco\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-salvador-barranco-300x200.jpg\" class=\"attachment-medium size-medium wp-image-144\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-salvador-barranco-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-salvador-barranco-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-salvador-barranco-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-salvador-barranco.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tColegio Nuestra Se\u00f1ora del Carmen, Barranco, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-25 elementor-filter-33 post-3018 post type-post status-publish format-standard has-post-thumbnail hentry category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/resources\/carmelite-ngo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/NGO900top-300x200.jpg\" class=\"attachment-medium size-medium wp-image-24768\" alt=\"Circular Carmelite NGO seal with an olive border listing Prophetic Mission, Prayer, Community around a central brown shield motif.\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/NGO900top-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/NGO900top-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/NGO900top-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/NGO900top.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmeliter-NGO\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-33 post-9890 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/peru\/villa-carmelitas-casa-de-retiro\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lurin-villa-carmelitas-300x200.jpg\" class=\"attachment-medium size-medium wp-image-152\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lurin-villa-carmelitas-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lurin-villa-carmelitas-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lurin-villa-carmelitas-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lurin-villa-carmelitas.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tVilla Carmelitas, Lur\u00edn, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-11 elementor-filter-33 post-2617 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-provincial category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/society-of-the-little-flower-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-102\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/SLF-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGesellschaft der kleinen Blume, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-11 elementor-filter-33 post-2638 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-provincial category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/provincial-offices\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/07\/Provincial900x600-300x200.png\" class=\"attachment-medium size-medium wp-image-15578\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/07\/Provincial900x600-300x200.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/07\/Provincial900x600-768x512.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/07\/Provincial900x600-18x12.png 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/07\/Provincial900x600.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tProvinzb\u00fcro der Karmeliten, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-20 elementor-filter-33 post-2920 post type-post status-publish format-standard has-post-thumbnail hentry category-kansas category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/kansas\/saint-boniface-parish-scipio-ks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/scipio-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-113\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/scipio-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/scipio-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/scipio-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/scipio-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Bonifatius, Scipio, KS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-25 elementor-filter-33 post-24683 post type-post status-publish format-standard has-post-thumbnail hentry category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/resources\/integral-ecology\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/01\/Integral-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-18345\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2025\/01\/Integral-1-300x300.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/01\/Integral-1-150x150.jpg 150w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/01\/Integral-1-12x12.jpg 12w, https:\/\/carmelites.net\/wp-content\/uploads\/2025\/01\/Integral-1.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIntegrale \u00d6kologie\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-21 elementor-filter-33 post-2941 post type-post status-publish format-standard has-post-thumbnail hentry category-el-salvador category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/el-salvador\/parroquia-nuestra-senora-de-lourdes-ciudad-delgado\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lourdes-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-162\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lourdes-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lourdes-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lourdes-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/lourdes-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia Nuestra Se\u00f1ora de Lourdes, Ciudad Delgado, El Salvador\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-33 post-2615 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/our-lady-of-mount-carmel-parish-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-100\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-darien-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei Unsere Liebe Frau vom Berg Karmel, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-13 elementor-filter-25 elementor-filter-33 post-3013 post type-post status-publish format-standard has-post-thumbnail hentry category-washington-dc category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/washington-dc\/carmelite-institute-of-north-america\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CINA-Institute-Logo-900x600-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-17134\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CINA-Institute-Logo-900x600-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CINA-Institute-Logo-900x600-1-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CINA-Institute-Logo-900x600-1-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CINA-Institute-Logo-900x600-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelitisches Institut von Nordamerika\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-15 elementor-filter-12 elementor-filter-33 post-2821 post type-post status-publish format-standard has-post-thumbnail hentry category-california category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/school\/crespi-carmelite-high-school-encino-ca\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/crespi-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-127\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/crespi-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/crespi-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/crespi-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/crespi-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCrespi Karmeliterschule, Encino, CA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-11 elementor-filter-33 post-2262 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-provincial category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/national-shrine-of-st-therese-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-300x200.jpg\" class=\"attachment-medium size-medium wp-image-105\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/shrine.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNationales Heiligtum der Heiligen Therese, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-12 elementor-filter-33 post-2657 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/mount-carmel-high-school-chicago-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mchs-2020-300x200.jpg\" class=\"attachment-medium size-medium wp-image-91\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mchs-2020-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mchs-2020-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mchs-2020-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mchs-2020.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMount Carmel High School, Chicago, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-33 post-11237 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/national-shrine-museum-of-st-therese-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/prayer-gazebo-in-the-300x169.jpg\" class=\"attachment-medium size-medium wp-image-11239\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/prayer-gazebo-in-the-300x169.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/prayer-gazebo-in-the.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNationales Heiligtumsmuseum der Heiligen Therese, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-33 post-2687 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/our-lady-of-mount-carmel-parish-joliet-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-98\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-joliet-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei Unsere Liebe Frau vom Berg Karmel, Joliet, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-23 elementor-filter-33 post-2951 post type-post status-publish format-standard has-post-thumbnail hentry category-mexico category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/mexico\/parroquia-de-la-transfiguracion-del-senor-torreon-coahuila\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/torrreon-transfig-01-300x200.jpg\" class=\"attachment-medium size-medium wp-image-156\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/torrreon-transfig-01-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/torrreon-transfig-01-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/torrreon-transfig-01-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/torrreon-transfig-01.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia La Transfiguraci\u00f3n del Se\u00f1or, Torre\u00f3n, Coahuila, M\u00e9xico\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-23 elementor-filter-33 post-2956 post type-post status-publish format-standard has-post-thumbnail hentry category-mexico category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/mexico\/casa-del-carmen-tlalpan-mexico-city\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mexico-city-chapel-300x200.jpg\" class=\"attachment-medium size-medium wp-image-158\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mexico-city-chapel-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mexico-city-chapel-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mexico-city-chapel-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/mexico-city-chapel.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCasa del Carmen, Tlalpan, M\u00e9xico-Stadt\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-20 elementor-filter-33 post-2904 post type-post status-publish format-standard has-post-thumbnail hentry category-kansas category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/kansas\/immaculate-conception-church-leavenworth-ks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/immac-conc-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-111\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/immac-conc-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/immac-conc-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/immac-conc-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/immac-conc-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKirche der Unbefleckten Empf\u00e4ngnis, Leavenworth, KS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-22 elementor-filter-33 post-2946 post type-post status-publish format-standard has-post-thumbnail hentry category-honduras category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/honduras\/parroquia-santa-lucia-martir-yamaranguila\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-300x200.jpg\" class=\"attachment-medium size-medium wp-image-1353\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-400x266.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2022\/07\/Carmelite-Parish-Honduras.jpg 752w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia Santa Luc\u00eda M\u00e1rtir, Yamaranguila, Intibuc\u00e1, Honduras\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-33 post-9753 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/peru\/parroquia-nuestra-senora-del-carmen-jose-galvez\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-josegalvez-300x200.jpg\" class=\"attachment-medium size-medium wp-image-148\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-josegalvez-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-josegalvez-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-josegalvez-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-josegalvez.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia Nuestra Se\u00f1ora del Carmen, Jos\u00e9 G\u00e1lvez, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-19 elementor-filter-33 post-2876 post type-post status-publish format-standard has-post-thumbnail hentry category-new-jersey category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/new-jersey\/st-therese-parish-cresskill-nj\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/cresskill-04-300x200.jpg\" class=\"attachment-medium size-medium wp-image-75\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/cresskill-04-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/cresskill-04-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/cresskill-04-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/cresskill-04.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Therese, Cresskill, NJ\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-13 elementor-filter-25 elementor-filter-33 post-15654 post type-post status-publish format-standard has-post-thumbnail hentry category-washington-dc category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/washington-dc\/carmelitana-collection\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/08\/student-cc-900-300x200.jpg\" class=\"attachment-medium size-medium wp-image-15659\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/08\/student-cc-900-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/08\/student-cc-900-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/08\/student-cc-900-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/08\/student-cc-900.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSammlung Carmelitana\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-20 elementor-filter-33 post-2893 post type-post status-publish format-standard has-post-thumbnail hentry category-kansas category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/kansas\/saint-joseph-church-leavenworth-ks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-joseph-300x200.jpg\" class=\"attachment-medium size-medium wp-image-109\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-joseph-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-joseph-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-joseph-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-joseph.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKirche St. Joseph, Leavenworth, KS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-16 elementor-filter-33 post-2844 post type-post status-publish format-standard has-post-thumbnail hentry category-florida category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/florida\/our-lady-of-mount-carmel-parish-osprey-fl\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-osprey-300x200.jpg\" class=\"attachment-medium size-medium wp-image-87\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-osprey-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-osprey-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-osprey-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-osprey.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei Unsere Liebe Frau vom Berg Karmel, Osprey, FL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-20 elementor-filter-33 post-2925 post type-post status-publish format-standard has-post-thumbnail hentry category-kansas category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/kansas\/elijahs-rest-retreat-ministry-scipio-ks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/elijahs-rest-300x200.jpg\" class=\"attachment-medium size-medium wp-image-118\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/elijahs-rest-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/elijahs-rest-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/elijahs-rest-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/elijahs-rest.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tElijah's Rest Retreat Ministry, Scipio, KS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-25 elementor-filter-33 post-11086 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/carmelite-gift-shop-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"139\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-13-at-8.06.50\u202fPM-300x139.png\" class=\"attachment-medium size-medium wp-image-11088\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-13-at-8.06.50\u202fPM-300x139.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-13-at-8.06.50\u202fPM-1024x474.png 1024w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-13-at-8.06.50\u202fPM-768x356.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-13-at-8.06.50\u202fPM.png 1144w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelitischer Geschenkeladen, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-20 elementor-filter-33 post-2915 post type-post status-publish format-standard has-post-thumbnail hentry category-kansas category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/kansas\/saint-therese-parish-richmond-ks\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/richmond-5-300x200.jpg\" class=\"attachment-medium size-medium wp-image-116\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/richmond-5-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/richmond-5-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/richmond-5-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/richmond-5.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Theresia, Richmond, KS\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-18 elementor-filter-33 post-2865 post type-post status-publish format-standard has-post-thumbnail hentry category-canada category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/canada\/our-lady-of-peace-niagara-falls\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olp-niagara-300x200.jpg\" class=\"attachment-medium size-medium wp-image-136\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olp-niagara-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olp-niagara-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olp-niagara-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olp-niagara.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tUnsere Liebe Frau des Friedens, Niagaraf\u00e4lle, ON, Kanada\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-15 elementor-filter-33 post-2826 post type-post status-publish format-standard has-post-thumbnail hentry category-california category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/california\/our-lady-of-mount-carmel-parish-fairfield-ca\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-fairfield-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-130\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-fairfield-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-fairfield-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-fairfield-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-fairfield-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei Unsere Liebe Frau vom Berge Karmel, Fairfield, CA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-25 elementor-filter-33 post-24665 post type-post status-publish format-standard has-post-thumbnail hentry category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/resources\/laudato-si\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2026\/05\/LaudatoSiLogo900x600-300x200.png\" class=\"attachment-medium size-medium wp-image-24676\" alt=\"Laudato Si&apos; Action Plan logo with shield crest and &apos;Order of Carmelites&apos; banner on a dark background\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2026\/05\/LaudatoSiLogo900x600-300x200.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2026\/05\/LaudatoSiLogo900x600-768x512.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2026\/05\/LaudatoSiLogo900x600-18x12.png 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2026\/05\/LaudatoSiLogo900x600.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLaudato Si'\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-12 elementor-filter-33 post-10025 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/school\/colegio-nuestra-senora-del-carmen-miraflores\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-carmelitas-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-142\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-carmelitas-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-carmelitas-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-carmelitas-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-carmelitas-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tColegio Nuestra Se\u00f1ora del Carmen, Miraflores, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-11 elementor-filter-33 post-2601 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-provincial category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/carmelite-spiritual-center-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-104\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carm-spir-cntr-1.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGeistliches Zentrum der Karmeliten, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-21 elementor-filter-33 post-2931 post type-post status-publish format-standard has-post-thumbnail hentry category-el-salvador category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/el-salvador\/casa-san-alberto-de-jerusalen-huizucar\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/san-alberto-300x200.jpg\" class=\"attachment-medium size-medium wp-image-161\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/san-alberto-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/san-alberto-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/san-alberto-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/san-alberto.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCasa San Alberto de Jerusal\u00e9n, Huiz\u00facar, El Salvador\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-33 post-9710 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/peru\/casa-san-elias-miraflores\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/casa-san-elias-300x200.jpg\" class=\"attachment-medium size-medium wp-image-154\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/casa-san-elias-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/casa-san-elias-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/casa-san-elias-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/casa-san-elias.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCasa San Eli\u00e1s, Miraflores, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-33 post-9820 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/peru\/parroquia-nuestra-senora-del-carmen-miraflores\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-miraflores-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-140\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-miraflores-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-miraflores-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-miraflores-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/olmc-miraflores-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia Nuestra Se\u00f1ora del Carmen, Miraflores, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-25 elementor-filter-33 post-24535 post type-post status-publish format-standard has-post-thumbnail hentry category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/resources\/carmelprays\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"184\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-23-at-20337-PM-300x184.png\" class=\"attachment-medium size-medium wp-image-24537\" alt=\"CarmelPrays.com logo with a stylized mountain, orange sun stars, blue waves, and white text.\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-23-at-20337-PM-300x184.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-23-at-20337-PM-18x12.png 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2026\/04\/Screenshot-2026-04-23-at-20337-PM.png 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelGebet.de\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-18 elementor-filter-11 elementor-filter-33 post-2857 post type-post status-publish format-standard has-post-thumbnail hentry category-canada category-provincial category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/provincial\/mount-carmel-spiritual-centre-niagara-falls\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/niagara-centre-front-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-134\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/niagara-centre-front-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/niagara-centre-front-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/niagara-centre-front-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/niagara-centre-front-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSpirituelles Zentrum Mount Carmel, Niagaraf\u00e4lle, ON, Kanada\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-12 elementor-filter-33 post-9791 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/school\/colegio-nuestro-salvador-jose-galvez\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-josegalvez-300x200.jpg\" class=\"attachment-medium size-medium wp-image-146\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-josegalvez-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-josegalvez-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-josegalvez-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/colegio-josegalvez.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tColegio Nuestro Salvador, Jos\u00e9 G\u00e1lvez, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-15 elementor-filter-33 post-2831 post type-post status-publish format-standard has-post-thumbnail hentry category-california category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/california\/st-teresa-of-avila-parish-san-francisco-ca\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-teresa-sf-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-132\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-teresa-sf-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-teresa-sf-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-teresa-sf-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-teresa-sf-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Teresa von Avila, San Francisco, CA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-13 elementor-filter-25 elementor-filter-33 post-3002 post type-post status-publish format-standard has-post-thumbnail hentry category-washington-dc category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/washington-dc\/school-of-theology-religious-studies-washington-dc\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CatholicU-300x200.jpg\" class=\"attachment-medium size-medium wp-image-20619\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CatholicU-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CatholicU-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CatholicU-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CatholicU.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFakult\u00e4t f\u00fcr Theologie und Religionswissenschaften, Washington, DC\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-21 elementor-filter-33 post-2936 post type-post status-publish format-standard has-post-thumbnail hentry category-el-salvador category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/el-salvador\/centro-xiberta-ciudad-delgado\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/Xiberta-01-300x200.jpg\" class=\"attachment-medium size-medium wp-image-160\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/Xiberta-01-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/Xiberta-01-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/Xiberta-01-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/Xiberta-01.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCentro Xiberta, Ciudad Delgado, El Salvador\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-14 elementor-filter-12 elementor-filter-33 post-2815 post type-post status-publish format-standard has-post-thumbnail hentry category-arizona category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/school\/salpointe-catholic-high-school-tucson-az\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/salpointe-main-300x200.jpg\" class=\"attachment-medium size-medium wp-image-120\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/salpointe-main-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/salpointe-main-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/salpointe-main-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/salpointe-main.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKatholische Oberschule Salpointe, Tucson, AZ\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-12 elementor-filter-33 post-2679 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/joliet-catholic-academy-joliet-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-300x200.jpg\" class=\"attachment-medium size-medium wp-image-95\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/JCA-2.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKatholische Akademie Joliet, Joliet, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-19 elementor-filter-33 post-2888 post type-post status-publish format-standard has-post-thumbnail hentry category-new-jersey category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/new-jersey\/our-lady-of-mount-carmel-parish-tenafly-nj\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/tenafly-02-300x200.jpg\" class=\"attachment-medium size-medium wp-image-81\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/tenafly-02-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/tenafly-02-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/tenafly-02-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/tenafly-02.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei Our Lady of Mount Carmel, Tenafly, NJ\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-25 elementor-filter-33 post-3008 post type-post status-publish format-standard has-post-thumbnail hentry category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/resources\/carmelite-media-publications\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CarmeliteMediaPub-300x200.jpg\" class=\"attachment-medium size-medium wp-image-24661\" alt=\"Carmelite Media Publications branding header with a heraldic shield emblem and the tagline &apos;A Ministry of Evangelization by the Carmelite Order&apos;\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CarmeliteMediaPub-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CarmeliteMediaPub-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CarmeliteMediaPub-18x12.jpg 18w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/CarmeliteMediaPub.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelitische Medien Ver\u00f6ffentlichungen\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-18 elementor-filter-33 post-2870 post type-post status-publish format-standard has-post-thumbnail hentry category-canada category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/canada\/st-patrick-parish-niagara-falls\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-patrick-1-300x200.jpg\" class=\"attachment-medium size-medium wp-image-138\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-patrick-1-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-patrick-1-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-patrick-1-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st-patrick-1.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Patrick, Niagara Falls, ON, Kanada\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-24 elementor-filter-33 post-10074 post type-post status-publish format-standard has-post-thumbnail hentry category-peru category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/peru\/parroquia-la-inmaculada-concepcion-pucusana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/pucusana-300x200.jpg\" class=\"attachment-medium size-medium wp-image-150\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/pucusana-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/pucusana-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/pucusana-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/pucusana.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tParroquia La Inmaculada Concepci\u00f3n, Pucusana, Per\u00fa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-13 elementor-filter-33 post-2790 post type-post status-publish format-standard has-post-thumbnail hentry category-washington-dc category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/washington-dc\/whitefriars-hall-house-of-studies\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/whitefriars-hall-dc-300x200.jpg\" class=\"attachment-medium size-medium wp-image-71\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/whitefriars-hall-dc-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/whitefriars-hall-dc-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/whitefriars-hall-dc-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/whitefriars-hall-dc.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tWhitefriars Hall, Washington, DC\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-12 elementor-filter-33 post-2782 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-school category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/carmel-catholic-high-school-mundelein-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-300x200.jpg\" class=\"attachment-medium size-medium wp-image-93\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-768x512.jpg 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-600x400.jpg 600w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2-800x533.jpg 800w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/carmel-catholic-2.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKatholische Oberschule Carmel, Mundelein, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-19 elementor-filter-33 post-2882 post type-post status-publish format-standard has-post-thumbnail hentry category-new-jersey category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/new-jersey\/st-cecilia-parish-englewood-nj\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st.cecilia-englewood-300x200.jpg\" class=\"attachment-medium size-medium wp-image-84\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st.cecilia-englewood-300x200.jpg 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st.cecilia-englewood-200x133.jpg 200w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st.cecilia-englewood-400x267.jpg 400w, https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/st.cecilia-englewood.jpg 432w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPfarrei St. Cecilia, Englewood, NJ\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-10 elementor-filter-25 elementor-filter-33 post-3028 post type-post status-publish format-standard has-post-thumbnail hentry category-illinois category-resources category-ministries\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-300x200.png\" class=\"attachment-medium size-medium wp-image-20128\" alt=\"\" srcset=\"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-300x200.png 300w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-1024x683.png 1024w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-768x512.png 768w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-1536x1024.png 1536w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-2048x1365.png 2048w, https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-18x12.png 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarmelitisches Laienb\u00fcro, Darien, IL\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MINISTRIES The Carmelite friars of the Most Pure Heart of Mary Province serve in twenty parishes, eight high schools, and three retreat houses in four countries of the Americas\u00a0\u2013 the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Order of Carmelites - Province of the Most Pure Heart of Mary\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lay Carmelite Office, Darien, IL - Order of Carmelites\" \/>\n\t\t<meta property=\"og:description\" content=\"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-08-03T16:22:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-03T15:56:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carmelites\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lay Carmelite Office, Darien, IL - Order of Carmelites\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#blogposting\",\"name\":\"Lay Carmelite Office, Darien, IL - Order of Carmelites\",\"headline\":\"Lay Carmelite Office, Darien, IL\",\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/spandita\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/scapular-brown-scaled.png\",\"width\":2560,\"height\":1707},\"datePublished\":\"2023-08-03T11:22:56-05:00\",\"dateModified\":\"2026-07-03T10:56:51-05:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#webpage\"},\"articleSection\":\"d. Illinois, o. Resources, q. Ministries\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carmelites.net\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/#listItem\",\"name\":\"MINISTRIES\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/#listItem\",\"position\":2,\"name\":\"MINISTRIES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"telephone\":\"+16309710050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo100.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#organizationLogo\",\"width\":345,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carmelites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/carmelites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarmelitesPCM\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/spandita\\\/#author\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/spandita\\\/\",\"name\":\"Spandita\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9c55831f077423cce08c8dbd39d3fdc4114a3732bad10950abc4bd487051e92?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Spandita\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#webpage\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/\",\"name\":\"Lay Carmelite Office, Darien, IL - Order of Carmelites\",\"description\":\"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/spandita\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/author\\\/spandita\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/carmelites.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/scapular-brown-scaled.png\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#mainImage\",\"width\":2560,\"height\":1707},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/ministries\\\/illinois\\\/lay-carmelite-office-darien-il\\\/#mainImage\"},\"datePublished\":\"2023-08-03T11:22:56-05:00\",\"dateModified\":\"2026-07-03T10:56:51-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/carmelites.net\\\/de\\\/\",\"name\":\"Order of Carmelites\",\"description\":\"Province of the Most Pure Heart of Mary\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/carmelites.net\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Lay Carmelite Office, Darien, IL - Order of Carmelites<\/title>\n\n","aioseo_head_json":{"title":"Lay Carmelite Office, Darien, IL - Order of Carmelites","description":"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net","canonical_url":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#blogposting","name":"Lay Carmelite Office, Darien, IL - Order of Carmelites","headline":"Lay Carmelite Office, Darien, IL","author":{"@id":"https:\/\/carmelites.net\/de\/author\/spandita\/#author"},"publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-scaled.png","width":2560,"height":1707},"datePublished":"2023-08-03T11:22:56-05:00","dateModified":"2026-07-03T10:56:51-05:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#webpage"},"isPartOf":{"@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#webpage"},"articleSection":"d. Illinois, o. Resources, q. Ministries"},{"@type":"BreadcrumbList","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","position":1,"name":"Home","item":"https:\/\/carmelites.net\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/ministries\/#listItem","name":"MINISTRIES"}},{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de\/ministries\/#listItem","position":2,"name":"MINISTRIES","previousItem":{"@type":"ListItem","@id":"https:\/\/carmelites.net\/de#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/carmelites.net\/de\/#organization","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","url":"https:\/\/carmelites.net\/de\/","telephone":"+16309710050","logo":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#organizationLogo","width":345,"height":100},"image":{"@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Carmelites\/","https:\/\/www.instagram.com\/carmelites\/","https:\/\/www.youtube.com\/@CarmelitesPCM"]},{"@type":"Person","@id":"https:\/\/carmelites.net\/de\/author\/spandita\/#author","url":"https:\/\/carmelites.net\/de\/author\/spandita\/","name":"Spandita","image":{"@type":"ImageObject","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e9c55831f077423cce08c8dbd39d3fdc4114a3732bad10950abc4bd487051e92?s=96&d=mm&r=g","width":96,"height":96,"caption":"Spandita"}},{"@type":"WebPage","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#webpage","url":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/","name":"Lay Carmelite Office, Darien, IL - Order of Carmelites","description":"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/carmelites.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#breadcrumblist"},"author":{"@id":"https:\/\/carmelites.net\/de\/author\/spandita\/#author"},"creator":{"@id":"https:\/\/carmelites.net\/de\/author\/spandita\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/carmelites.net\/wp-content\/uploads\/2023\/08\/scapular-brown-scaled.png","@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#mainImage","width":2560,"height":1707},"primaryImageOfPage":{"@id":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/#mainImage"},"datePublished":"2023-08-03T11:22:56-05:00","dateModified":"2026-07-03T10:56:51-05:00"},{"@type":"WebSite","@id":"https:\/\/carmelites.net\/de\/#website","url":"https:\/\/carmelites.net\/de\/","name":"Order of Carmelites","description":"Province of the Most Pure Heart of Mary","inLanguage":"de-DE","publisher":{"@id":"https:\/\/carmelites.net\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Order of Carmelites - Province of the Most Pure Heart of Mary","og:type":"article","og:title":"Lay Carmelite Office, Darien, IL - Order of Carmelites","og:description":"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net","og:url":"https:\/\/carmelites.net\/de\/ministries\/illinois\/lay-carmelite-office-darien-il\/","og:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","og:image:secure_url":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png","article:published_time":"2023-08-03T16:22:56+00:00","article:modified_time":"2026-07-03T15:56:51+00:00","article:publisher":"https:\/\/www.facebook.com\/Carmelites\/","twitter:card":"summary_large_image","twitter:title":"Lay Carmelite Office, Darien, IL - Order of Carmelites","twitter:description":"Lay Carmelite Office8501 Bailey RoadDarien, IL 60561-8417Min: 630-969-5050Fax: 630-969-7519laycarmelitespcm.orgEmail: laycarmelites@carmelites.net dbuschman@carmelites.net laycarmelites@carmelites.net nbuschman@carmelites.net","twitter:image":"https:\/\/carmelites.net\/wp-content\/uploads\/2021\/07\/logo100.png"},"aioseo_meta_data":{"post_id":"18","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-08-31 19:04:04","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2026-01-16 19:23:47","updated":"2026-08-31 19:04:04","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/carmelites.net\/de\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tMINISTRIES\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/carmelites.net\/de"},{"label":"MINISTRIES","link":"https:\/\/carmelites.net\/de\/ministries\/"}],"_links":{"self":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":103,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":23777,"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/pages\/18\/revisions\/23777"}],"wp:attachment":[{"href":"https:\/\/carmelites.net\/de\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}